{"id":3041,"date":"2015-04-22T10:36:52","date_gmt":"2015-04-22T10:36:52","guid":{"rendered":"http:\/\/localhost:82\/wordpress\/2015\/04\/22\/concessao-para-obras-no-marco-das-3-fronteiras-terminam-em-junho\/"},"modified":"2015-04-22T10:36:52","modified_gmt":"2015-04-22T10:36:52","slug":"concessao-para-obras-no-marco-das-3-fronteiras-terminam-em-junho","status":"publish","type":"post","link":"http:\/\/box5640.temp.domains\/~clickfoz\/concessao-para-obras-no-marco-das-3-fronteiras-terminam-em-junho\/","title":{"rendered":"Concess&atilde;o para obras no Marco das 3 Fronteiras terminam em junho"},"content":{"rendered":"<div>\nO prazo para apresenta&ccedil;&atilde;o das propostas para explora&ccedil;&atilde;o do Marco das Tr&ecirc;s Fronteiras e do Espa&ccedil;o das Am&eacute;ricas vai at&eacute; 02 de junho, quando ser&atilde;o abertos os envelopes. O edital de concess&atilde;o de uso do espa&ccedil;o foi relan&ccedil;ado pela Prefeitura de Foz do Igua&ccedil;u, depois de alguns ajustes.<\/p>\n<table cellspacing=\"0\" cellpadding=\"0\" border=\"0\" align=\"center\" width=\"200\" style=\"margin: 0 3px\">\n<tbody>\n<tr>\n<td style=\"text-align: right\"><span style=\"font-size: 11px\">Foto: Ilustra&ccedil;&atilde;o<\/span><\/td>\n<\/tr>\n<tr>\n<td bgcolor=\"#f4f4f2\"><img fetchpriority=\"high\" decoding=\"async\" height=\"393\" width=\"650\" src=\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/marco_parquetur%C3%ADstico.jpg\" alt=\"\" \/><\/td>\n<\/tr>\n<tr>\n<td bgcolor=\"#f4f4f2\" style=\"padding: 3px 1px;font-size: 11px;text-align: center\">Empresa poder&aacute; administrar o atrativo por 20 anos, renov&aacute;vel por mais 20<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: justify\">\nA empresa que apresentar a melhor proposta dever&aacute; implantar e depois operar o novo atrativo, por um prazo de 20 anos, renov&aacute;vel por mais 20. A previs&atilde;o &eacute; que o espa&ccedil;o receba entre 400 mil e 500 mil visitantes por ano.<\/p>\n<p>Os envelopes com as propostas ser&atilde;o recebidos e abertos no dia 2 de junho, &agrave;s 9h. A visita t&eacute;cnica ao Marco das Tr&ecirc;s Fronteiras poder&aacute; ser agendada previamente para o dia 27 ou 29 de maio. A retirada do edital deve ser feita na Secretaria Municipal de Turismo, mediante pagamento de taxa de R$ 100 e apresenta&ccedil;&atilde;o de uma autoriza&ccedil;&atilde;o, obtida pelo e-mail <strong><a href=\"'+String.fromCharCode(108,101,97,110,100,114,111,46,108,118,104,64,112,109,102,105,46,112,114,46,103,111,118,46,98,114)+'?'\">leandro.lvh@pmfi.pr.gov.br<\/a><\/strong>.<\/p>\n<p><strong>Altera&ccedil;&otilde;es &#8211;<\/strong> O edital, lan&ccedil;ado no ano passado, foi retirado por onze empresas, antes de o processo ser suspenso, por causa de v&aacute;rias d&uacute;vidas levantadas pelas participantes. Depois de sanadas as quest&otilde;es, o edital foi relan&ccedil;ado. &ldquo;As altera&ccedil;&otilde;es foram feitas no sentido de tornarmos a licita&ccedil;&atilde;o mais atraente&rdquo;, explicou o secret&aacute;rio municipal de Turismo, Paulo Tremarin.<\/p>\n<p>O atrativo fica pr&oacute;ximo do local onde ser&aacute; constru&iacute;da a segunda ponte sobre o Rio Paran&aacute;, ligando Foz do Igua&ccedil;u a Presidente Franco, no Paraguai. Com 760 metros de comprimento e 19 de largura, a futura ponte, que ser&aacute; do tipo estaiada, tirar&aacute; da Ponte da Amizade &ndash; entre Foz e Ciudad del Este &ndash; o tr&aacute;fego de ve&iacute;culos pesados.<\/p>\n<p><strong>Revitaliza&ccedil;&atilde;o &#8211; <\/strong>O edital de concess&atilde;o prev&ecirc; que ser&aacute; vencedora a empresa que combinar &ldquo;os crit&eacute;rios de maior oferta pela outorga da concess&atilde;o de uso com o de melhor t&eacute;cnica&rdquo;, ficando respons&aacute;vel pela &ldquo;implanta&ccedil;&atilde;o, opera&ccedil;&atilde;o, administra&ccedil;&atilde;o, manuten&ccedil;&atilde;o, conserva&ccedil;&atilde;o, vigil&acirc;ncia, moderniza&ccedil;&atilde;o e desenvolvimento tur&iacute;stico&rdquo; na &aacute;rea.<\/p>\n<p>O Marco das Tr&ecirc;s Fronteiras e o Espa&ccedil;o das Am&eacute;ricas, hoje pouco procurados pelos turistas, dever&atilde;o se transformar num dos maiores atrativos de Foz do Igua&ccedil;u. Ali, na conflu&ecirc;ncia dos rios Igua&ccedil;u e Paran&aacute;, h&aacute; o encontro de tr&ecirc;s pa&iacute;ses &ndash; Brasil, Paraguai e Argentina -, cada um com o respectivo marco para indicar sua fronteira.<\/p>\n<p><strong>Projeto &#8211;<\/strong> A empresa vencedora dever&aacute; implantar em toda a &aacute;rea um projeto desenvolvido pelo Fundo de Desenvolvimento e Promo&ccedil;&atilde;o Tur&iacute;stica do Igua&ccedil;u &ndash; Fundo Igua&ccedil;u, que tamb&eacute;m contribuiu com os estudos para a formata&ccedil;&atilde;o do edital de concess&atilde;o do espa&ccedil;o &agrave; iniciativa privada.<\/p>\n<p>Pelo projeto do Fundo Igua&ccedil;u, o Marco das Tr&ecirc;s Fronteiras ganhar&aacute; passarelas a&eacute;reas, que interligar&atilde;o torres com at&eacute; 60 metros de altura, de concreto e metal, no formato de &aacute;rvores. Em cada torre, al&eacute;m da simples observa&ccedil;&atilde;o da paisagem, poder&atilde;o ser desenvolvidas atividades como arborismo e escalada.<\/p>\n<p>O Espa&ccedil;o das Am&eacute;ricas, uma constru&ccedil;&atilde;o que hoje est&aacute; praticamente abandonada, funcionar&atilde;o um restaurante panor&acirc;mico, um centro cultural e de eventos. O projeto prev&ecirc; tamb&eacute;m a cria&ccedil;&atilde;o de um show de &aacute;guas dan&ccedil;antes e proje&ccedil;&atilde;o de imagens em cortina de &aacute;gua na conflu&ecirc;ncia dos rios Paran&aacute; e Igua&ccedil;u.<\/p>\n<p>Os visitantes contar&atilde;o ainda com playground, lojas de souvenires, mirantes e decks na &aacute;rea do Marco das Tr&ecirc;s Fronteiras, al&eacute;m de um biciclet&aacute;rio, de um p&iacute;er para passeios de barco no Rio Paran&aacute;, decks, mirantes, um memorial e um caf&eacute;, entre outros atrativos.<\/p>\n<p><strong>Parceria &#8211; <\/strong>&ldquo;Fizemos um trabalho em parceria, que envolveu a contrata&ccedil;&atilde;o de consultoria especializada, contratada pelo Fundo Igua&ccedil;u, e a equipe comandada pela procuradora municipal Letizia Jimenez Abbate Fiala, pelo Leandro Vandr&eacute; Heineck, da Secretaria Municipal de Turismo, e tamb&eacute;m pelo professor Jos&eacute; Borges Bonfim Filho. Esperamos, agora, que as empresas interessadas participem da licita&ccedil;&atilde;o e possamos revitalizar o Marco das Tr&ecirc;s Fronteiras e o Espa&ccedil;o das Am&eacute;ricas, pois acreditamos que, juntos, esse dois espa&ccedil;os possuem um grande potencial tur&iacute;stico&rdquo;, afirma o presidente do Fundo Igua&ccedil;u e superintendente de Comunica&ccedil;&atilde;o Social da Itaipu, Gilmar Piolla.<\/p>\n<p>Um dos aspectos interessantes do edital, segundo ele, &eacute; que os moradores de Foz do Igua&ccedil;u ter&atilde;o acesso livre ao espa&ccedil;o, mediante cadastramento pr&eacute;vio. &ldquo;O que ser&aacute; pago ser&atilde;o os passeios nos atrativos (torres), o estacionamento e o consumo na loja de souvenires, caf&eacute; e restaurante&rdquo;, informa.<\/p>\n<\/div>\n<div>&nbsp;<\/div>\n<div>&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>O prazo para apresenta&ccedil;&atilde;o das propostas para explora&ccedil;&atilde;o do Marco das Tr&ecirc;s Fronteiras e do Espa&ccedil;o das Am&eacute;ricas vai at&eacute; 02 de junho, quando ser&atilde;o abertos os envelopes. O edital de concess&atilde;o de uso do espa&ccedil;o foi relan&ccedil;ado pela Prefeitura de Foz do Igua&ccedil;u, depois de alguns ajustes. Foto: Ilustra&ccedil;&atilde;o Empresa poder&aacute; administrar o atrativo [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-3041","post","type-post","status-publish","format-standard","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Concess&atilde;o para obras no Marco das 3 Fronteiras terminam em junho - Clickfoz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/box5640.temp.domains\/~clickfoz\/concessao-para-obras-no-marco-das-3-fronteiras-terminam-em-junho\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Concess&atilde;o para obras no Marco das 3 Fronteiras terminam em junho - Clickfoz\" \/>\n<meta property=\"og:description\" content=\"O prazo para apresenta&ccedil;&atilde;o das propostas para explora&ccedil;&atilde;o do Marco das Tr&ecirc;s Fronteiras e do Espa&ccedil;o das Am&eacute;ricas vai at&eacute; 02 de junho, quando ser&atilde;o abertos os envelopes. O edital de concess&atilde;o de uso do espa&ccedil;o foi relan&ccedil;ado pela Prefeitura de Foz do Igua&ccedil;u, depois de alguns ajustes. Foto: Ilustra&ccedil;&atilde;o Empresa poder&aacute; administrar o atrativo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/box5640.temp.domains\/~clickfoz\/concessao-para-obras-no-marco-das-3-fronteiras-terminam-em-junho\/\" \/>\n<meta property=\"og:site_name\" content=\"Clickfoz\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/clickfoz\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/lauane.ferreirademelo\" \/>\n<meta property=\"article:published_time\" content=\"2015-04-22T10:36:52+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/marco_parquetur%C3%ADstico.jpg\" \/>\n<meta name=\"author\" content=\"Lauane de Melo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@clickfoz\" \/>\n<meta name=\"twitter:site\" content=\"@clickfoz\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lauane de Melo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/concessao-para-obras-no-marco-das-3-fronteiras-terminam-em-junho\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/concessao-para-obras-no-marco-das-3-fronteiras-terminam-em-junho\/\"},\"author\":{\"name\":\"Lauane de Melo\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/person\/8975ece75a84fdc225ca535af4957bbd\"},\"headline\":\"Concess&atilde;o para obras no Marco das 3 Fronteiras terminam em junho\",\"datePublished\":\"2015-04-22T10:36:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/concessao-para-obras-no-marco-das-3-fronteiras-terminam-em-junho\/\"},\"wordCount\":986,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\"},\"image\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/concessao-para-obras-no-marco-das-3-fronteiras-terminam-em-junho\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/marco_parquetur%C3%ADstico.jpg\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\/\/box5640.temp.domains\/~clickfoz\/concessao-para-obras-no-marco-das-3-fronteiras-terminam-em-junho\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/concessao-para-obras-no-marco-das-3-fronteiras-terminam-em-junho\/\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/concessao-para-obras-no-marco-das-3-fronteiras-terminam-em-junho\/\",\"name\":\"Concess&atilde;o para obras no Marco das 3 Fronteiras terminam em junho - Clickfoz\",\"isPartOf\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/concessao-para-obras-no-marco-das-3-fronteiras-terminam-em-junho\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/concessao-para-obras-no-marco-das-3-fronteiras-terminam-em-junho\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/marco_parquetur%C3%ADstico.jpg\",\"datePublished\":\"2015-04-22T10:36:52+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/concessao-para-obras-no-marco-das-3-fronteiras-terminam-em-junho\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/box5640.temp.domains\/~clickfoz\/concessao-para-obras-no-marco-das-3-fronteiras-terminam-em-junho\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/concessao-para-obras-no-marco-das-3-fronteiras-terminam-em-junho\/#primaryimage\",\"url\":\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/marco_parquetur%C3%ADstico.jpg\",\"contentUrl\":\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/marco_parquetur%C3%ADstico.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/concessao-para-obras-no-marco-das-3-fronteiras-terminam-em-junho\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/box5640.temp.domains\/~clickfoz\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Concess&atilde;o para obras no Marco das 3 Fronteiras terminam em junho\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#website\",\"url\":\"https:\/\/box5640.temp.domains\/~clickfoz\/\",\"name\":\"Click Foz do Igua\u00e7u\",\"description\":\"O portal de not\u00edcias de Foz do Igua\u00e7u\",\"publisher\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/box5640.temp.domains\/~clickfoz\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\",\"name\":\"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i\",\"url\":\"https:\/\/box5640.temp.domains\/~clickfoz\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png\",\"contentUrl\":\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png\",\"width\":190,\"height\":65,\"caption\":\"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i\"},\"image\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/clickfoz\",\"https:\/\/x.com\/clickfoz\",\"https:\/\/www.instagram.com\/clickfoz\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/person\/8975ece75a84fdc225ca535af4957bbd\",\"name\":\"Lauane de Melo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f2fd1c70b44916c2a755ede0f6ad25d15384a8c065befffe4307bac02f1ec8c8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f2fd1c70b44916c2a755ede0f6ad25d15384a8c065befffe4307bac02f1ec8c8?s=96&d=mm&r=g\",\"caption\":\"Lauane de Melo\"},\"sameAs\":[\"http:\/\/clickfozdoiguacu.com.br\",\"https:\/\/www.facebook.com\/lauane.ferreirademelo\"],\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/author\/lauane\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Concess&atilde;o para obras no Marco das 3 Fronteiras terminam em junho - Clickfoz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/box5640.temp.domains\/~clickfoz\/concessao-para-obras-no-marco-das-3-fronteiras-terminam-em-junho\/","og_locale":"pt_BR","og_type":"article","og_title":"Concess&atilde;o para obras no Marco das 3 Fronteiras terminam em junho - Clickfoz","og_description":"O prazo para apresenta&ccedil;&atilde;o das propostas para explora&ccedil;&atilde;o do Marco das Tr&ecirc;s Fronteiras e do Espa&ccedil;o das Am&eacute;ricas vai at&eacute; 02 de junho, quando ser&atilde;o abertos os envelopes. O edital de concess&atilde;o de uso do espa&ccedil;o foi relan&ccedil;ado pela Prefeitura de Foz do Igua&ccedil;u, depois de alguns ajustes. Foto: Ilustra&ccedil;&atilde;o Empresa poder&aacute; administrar o atrativo [&hellip;]","og_url":"http:\/\/box5640.temp.domains\/~clickfoz\/concessao-para-obras-no-marco-das-3-fronteiras-terminam-em-junho\/","og_site_name":"Clickfoz","article_publisher":"https:\/\/facebook.com\/clickfoz","article_author":"https:\/\/www.facebook.com\/lauane.ferreirademelo","article_published_time":"2015-04-22T10:36:52+00:00","og_image":[{"url":"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/marco_parquetur%C3%ADstico.jpg","type":"","width":"","height":""}],"author":"Lauane de Melo","twitter_card":"summary_large_image","twitter_creator":"@clickfoz","twitter_site":"@clickfoz","twitter_misc":{"Escrito por":"Lauane de Melo","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/concessao-para-obras-no-marco-das-3-fronteiras-terminam-em-junho\/#article","isPartOf":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/concessao-para-obras-no-marco-das-3-fronteiras-terminam-em-junho\/"},"author":{"name":"Lauane de Melo","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/person\/8975ece75a84fdc225ca535af4957bbd"},"headline":"Concess&atilde;o para obras no Marco das 3 Fronteiras terminam em junho","datePublished":"2015-04-22T10:36:52+00:00","mainEntityOfPage":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/concessao-para-obras-no-marco-das-3-fronteiras-terminam-em-junho\/"},"wordCount":986,"commentCount":0,"publisher":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization"},"image":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/concessao-para-obras-no-marco-das-3-fronteiras-terminam-em-junho\/#primaryimage"},"thumbnailUrl":"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/marco_parquetur%C3%ADstico.jpg","inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/box5640.temp.domains\/~clickfoz\/concessao-para-obras-no-marco-das-3-fronteiras-terminam-em-junho\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/concessao-para-obras-no-marco-das-3-fronteiras-terminam-em-junho\/","url":"http:\/\/box5640.temp.domains\/~clickfoz\/concessao-para-obras-no-marco-das-3-fronteiras-terminam-em-junho\/","name":"Concess&atilde;o para obras no Marco das 3 Fronteiras terminam em junho - Clickfoz","isPartOf":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#website"},"primaryImageOfPage":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/concessao-para-obras-no-marco-das-3-fronteiras-terminam-em-junho\/#primaryimage"},"image":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/concessao-para-obras-no-marco-das-3-fronteiras-terminam-em-junho\/#primaryimage"},"thumbnailUrl":"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/marco_parquetur%C3%ADstico.jpg","datePublished":"2015-04-22T10:36:52+00:00","breadcrumb":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/concessao-para-obras-no-marco-das-3-fronteiras-terminam-em-junho\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/box5640.temp.domains\/~clickfoz\/concessao-para-obras-no-marco-das-3-fronteiras-terminam-em-junho\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/concessao-para-obras-no-marco-das-3-fronteiras-terminam-em-junho\/#primaryimage","url":"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/marco_parquetur%C3%ADstico.jpg","contentUrl":"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/marco_parquetur%C3%ADstico.jpg"},{"@type":"BreadcrumbList","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/concessao-para-obras-no-marco-das-3-fronteiras-terminam-em-junho\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/box5640.temp.domains\/~clickfoz\/"},{"@type":"ListItem","position":2,"name":"Concess&atilde;o para obras no Marco das 3 Fronteiras terminam em junho"}]},{"@type":"WebSite","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#website","url":"https:\/\/box5640.temp.domains\/~clickfoz\/","name":"Click Foz do Igua\u00e7u","description":"O portal de not\u00edcias de Foz do Igua\u00e7u","publisher":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/box5640.temp.domains\/~clickfoz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization","name":"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i","url":"https:\/\/box5640.temp.domains\/~clickfoz\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/","url":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png","contentUrl":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png","width":190,"height":65,"caption":"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i"},"image":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/clickfoz","https:\/\/x.com\/clickfoz","https:\/\/www.instagram.com\/clickfoz"]},{"@type":"Person","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/person\/8975ece75a84fdc225ca535af4957bbd","name":"Lauane de Melo","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f2fd1c70b44916c2a755ede0f6ad25d15384a8c065befffe4307bac02f1ec8c8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f2fd1c70b44916c2a755ede0f6ad25d15384a8c065befffe4307bac02f1ec8c8?s=96&d=mm&r=g","caption":"Lauane de Melo"},"sameAs":["http:\/\/clickfozdoiguacu.com.br","https:\/\/www.facebook.com\/lauane.ferreirademelo"],"url":"http:\/\/box5640.temp.domains\/~clickfoz\/author\/lauane\/"}]}},"_links":{"self":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts\/3041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/comments?post=3041"}],"version-history":[{"count":0,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts\/3041\/revisions"}],"wp:attachment":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/media?parent=3041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/categories?post=3041"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/tags?post=3041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}