{"id":2929,"date":"2015-05-14T09:33:26","date_gmt":"2015-05-14T09:33:26","guid":{"rendered":"http:\/\/localhost:82\/wordpress\/2015\/05\/14\/tabela-do-brasileirao-serie-d-e-divulgada-pela-cbf\/"},"modified":"2015-05-14T09:33:26","modified_gmt":"2015-05-14T09:33:26","slug":"tabela-do-brasileirao-serie-d-e-divulgada-pela-cbf","status":"publish","type":"post","link":"http:\/\/box5640.temp.domains\/~clickfoz\/tabela-do-brasileirao-serie-d-e-divulgada-pela-cbf\/","title":{"rendered":"Tabela do Brasileir&atilde;o s&eacute;rie D &eacute; divulgada pela CBF"},"content":{"rendered":"<div>\nDepois de algumas especula&ccedil;&otilde;es sobre o grupo do Foz do Igua&ccedil;u Futebol Clube no Campeonato Brasileiro da S&eacute;rie D 2015, a <strong><a href=\"http:\/\/cdn.cbf.com.br\/content\/201505\/20150513191245_0.pdf\" target=\"_blank\">Confedera&ccedil;&atilde;o Brasileira de Futebol<\/a><\/strong>, CBF, divulgou nesta quarta-feira, 13, a tabela da competi&ccedil;&atilde;o nacional e p&ocirc;s fim ao mist&eacute;rio.<\/p>\n<table cellspacing=\"0\" cellpadding=\"0\" border=\"0\" align=\"center\" width=\"200\" style=\"margin: 0 3px\">\n<tbody>\n<tr>\n<td style=\"text-align: right\"><span style=\"font-size: 11px\">Foto: Arquivo<\/span><\/td>\n<\/tr>\n<tr>\n<td bgcolor=\"#f4f4f2\"><img fetchpriority=\"high\" decoding=\"async\" height=\"430\" width=\"650\" src=\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/Foz%20x%20Operario%20inicio.JPG\" alt=\"\" \/><\/td>\n<\/tr>\n<tr>\n<td bgcolor=\"#f4f4f2\" style=\"padding: 3px 1px;font-size: 11px;text-align: center\">O Foz Futebol conquistou a vaga para o Brasileir&atilde;o S&eacute;rie D, ap&oacute;s a bela campanha no Campeonato Paranaense 2015<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: justify\">\nDas equipes que hav&iacute;amos anunciado na &uacute;ltima ter&ccedil;a-feira, 12, como <u><strong><a href=\"http:\/\/www.clickfozdoiguacu.com.br\/pagina\/foz-futebol-ja-tem-possiveis-adversarios-no-brasileirao-serie-d\" target=\"_blank\">poss&iacute;veis advers&aacute;rios do Azul&atilde;o<\/a><\/strong><\/u>, apenas o Lajeadense (RS) se confirmou no mesmo grupo. Al&eacute;m destes dois times, completam a chave 8: Volta Redonda (RJ), S&atilde;o Caetano (SP) e Metropolitano (SC). <\/p>\n<p>O Brasileir&atilde;o come&ccedil;a no dia 12 de julho. Neste mesmo dia, o Foz Futebol estreia na competi&ccedil;&atilde;o nacional contra o Volta Redonda. &nbsp;A partida ser&aacute; disputada no Est&aacute;dio do ABC em Foz do Igua&ccedil;u. &ldquo;Vamos ver se agora, as coisas acontecem. Sim, pode acreditar. N&atilde;o &eacute; sonho n&atilde;o, estamos em competi&ccedil;&otilde;es nacionais&rdquo;, disse o presidente do clube igua&ccedil;uense, Arif Osman.<br \/>\n&nbsp;<\/p>\n<table cellspacing=\"0\" cellpadding=\"0\" border=\"0\" align=\"center\" width=\"200\" style=\"margin: 0px 3px\">\n<tbody>\n<tr>\n<td style=\"text-align: right\"><span style=\"font-size: 11px\">Foto: Facebook<\/span><\/td>\n<\/tr>\n<tr>\n<td bgcolor=\"#f4f4f2\"><img decoding=\"async\" height=\"439\" width=\"650\" src=\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/Arif%20Osman%20brasileirao.png\" alt=\"\" \/><\/td>\n<\/tr>\n<tr>\n<td bgcolor=\"#f4f4f2\" style=\"font-size: 11px;padding: 3px 1px;text-align: center\">Arif Osman, presidente do Foz Futebol, deu a not&iacute;cia em sua rede social nesta quarta-feira, 13<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: justify\">\nA primeira fase do campeonato segue at&eacute; dia 13 de setembro. Durante as 10 rodadas desta primeira etapa, o Foz folgar&aacute; duas e far&aacute; oito partidas, todas com turno e returno. Os dois melhores times avan&ccedil;am na competi&ccedil;&atilde;o. <\/p>\n<p>Na pr&oacute;xima fase, os 16 classificados (dois de cada grupo), se enfrentam em fase eliminat&oacute;ria at&eacute; a final em partidas de ida e volta. Os quatro que chegaram &agrave;s semifinais ter&atilde;o vaga garantida para a s&eacute;rie C de 2016. A grande decis&atilde;o acontece dia 15 de novembro. <\/p>\n<p><strong>Confira os jogos do Foz Futebol na primeira fase do Brasileir&atilde;o S&eacute;rie D:<\/strong><\/p>\n<p>1&ordf; rodada 12\/07 &#8211; Foz Futebol x Volta Redonda<br \/>\n2&ordf; rodada 19\/07 &#8211; Folga do Foz Futebol<br \/>\n3&ordf; rodada 26\/07 &#8211; S&atilde;o Caetano x Foz Futebol<br \/>\n4&ordf; rodada 02\/08 &#8211; Lajeadense x Foz Futebol<br \/>\n5&ordf; rodada 09\/08 &#8211; Foz Futebol x Metropolitano<br \/>\n6&ordf; rodada 16\/08 &#8211; Foz Futebol x Lajeadense<br \/>\n7&ordf; rodada 23\/08 &#8211; Metropolitano x Foz Futebol<br \/>\n8&ordf; rodada 30\/08 &#8211; Foz Futebol x S&atilde;o Caetano<br \/>\n9&ordf; rodada 06\/09 &#8211; Folga do Foz Futebol<br \/>\n10&ordf; rodada 13\/09 &#8211; Volta Redonda e Foz Futebol<\/p>\n<\/div>\n<div>&nbsp;<\/div>\n<div>&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Depois de algumas especula&ccedil;&otilde;es sobre o grupo do Foz do Igua&ccedil;u Futebol Clube no Campeonato Brasileiro da S&eacute;rie D 2015, a Confedera&ccedil;&atilde;o Brasileira de Futebol, CBF, divulgou nesta quarta-feira, 13, a tabela da competi&ccedil;&atilde;o nacional e p&ocirc;s fim ao mist&eacute;rio. Foto: Arquivo O Foz Futebol conquistou a vaga para o Brasileir&atilde;o S&eacute;rie D, ap&oacute;s a [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-2929","post","type-post","status-publish","format-standard","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tabela do Brasileir&atilde;o s&eacute;rie D &eacute; divulgada pela CBF - Clickfoz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/box5640.temp.domains\/~clickfoz\/tabela-do-brasileirao-serie-d-e-divulgada-pela-cbf\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tabela do Brasileir&atilde;o s&eacute;rie D &eacute; divulgada pela CBF - Clickfoz\" \/>\n<meta property=\"og:description\" content=\"Depois de algumas especula&ccedil;&otilde;es sobre o grupo do Foz do Igua&ccedil;u Futebol Clube no Campeonato Brasileiro da S&eacute;rie D 2015, a Confedera&ccedil;&atilde;o Brasileira de Futebol, CBF, divulgou nesta quarta-feira, 13, a tabela da competi&ccedil;&atilde;o nacional e p&ocirc;s fim ao mist&eacute;rio. Foto: Arquivo O Foz Futebol conquistou a vaga para o Brasileir&atilde;o S&eacute;rie D, ap&oacute;s a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/box5640.temp.domains\/~clickfoz\/tabela-do-brasileirao-serie-d-e-divulgada-pela-cbf\/\" \/>\n<meta property=\"og:site_name\" content=\"Clickfoz\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/clickfoz\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/lauane.ferreirademelo\" \/>\n<meta property=\"article:published_time\" content=\"2015-05-14T09:33:26+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/Foz%20x%20Operario%20inicio.JPG\" \/>\n<meta name=\"author\" content=\"Lauane de Melo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@clickfoz\" \/>\n<meta name=\"twitter:site\" content=\"@clickfoz\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lauane de Melo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/tabela-do-brasileirao-serie-d-e-divulgada-pela-cbf\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/tabela-do-brasileirao-serie-d-e-divulgada-pela-cbf\/\"},\"author\":{\"name\":\"Lauane de Melo\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/person\/8975ece75a84fdc225ca535af4957bbd\"},\"headline\":\"Tabela do Brasileir&atilde;o s&eacute;rie D &eacute; divulgada pela CBF\",\"datePublished\":\"2015-05-14T09:33:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/tabela-do-brasileirao-serie-d-e-divulgada-pela-cbf\/\"},\"wordCount\":447,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\"},\"image\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/tabela-do-brasileirao-serie-d-e-divulgada-pela-cbf\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/Foz%20x%20Operario%20inicio.JPG\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\/\/box5640.temp.domains\/~clickfoz\/tabela-do-brasileirao-serie-d-e-divulgada-pela-cbf\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/tabela-do-brasileirao-serie-d-e-divulgada-pela-cbf\/\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/tabela-do-brasileirao-serie-d-e-divulgada-pela-cbf\/\",\"name\":\"Tabela do Brasileir&atilde;o s&eacute;rie D &eacute; divulgada pela CBF - Clickfoz\",\"isPartOf\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/tabela-do-brasileirao-serie-d-e-divulgada-pela-cbf\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/tabela-do-brasileirao-serie-d-e-divulgada-pela-cbf\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/Foz%20x%20Operario%20inicio.JPG\",\"datePublished\":\"2015-05-14T09:33:26+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/tabela-do-brasileirao-serie-d-e-divulgada-pela-cbf\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/box5640.temp.domains\/~clickfoz\/tabela-do-brasileirao-serie-d-e-divulgada-pela-cbf\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/tabela-do-brasileirao-serie-d-e-divulgada-pela-cbf\/#primaryimage\",\"url\":\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/Foz%20x%20Operario%20inicio.JPG\",\"contentUrl\":\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/Foz%20x%20Operario%20inicio.JPG\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/tabela-do-brasileirao-serie-d-e-divulgada-pela-cbf\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/box5640.temp.domains\/~clickfoz\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tabela do Brasileir&atilde;o s&eacute;rie D &eacute; divulgada pela CBF\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#website\",\"url\":\"https:\/\/box5640.temp.domains\/~clickfoz\/\",\"name\":\"Click Foz do Igua\u00e7u\",\"description\":\"O portal de not\u00edcias de Foz do Igua\u00e7u\",\"publisher\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/box5640.temp.domains\/~clickfoz\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\",\"name\":\"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i\",\"url\":\"https:\/\/box5640.temp.domains\/~clickfoz\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png\",\"contentUrl\":\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png\",\"width\":190,\"height\":65,\"caption\":\"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i\"},\"image\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/clickfoz\",\"https:\/\/x.com\/clickfoz\",\"https:\/\/www.instagram.com\/clickfoz\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/person\/8975ece75a84fdc225ca535af4957bbd\",\"name\":\"Lauane de Melo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f2fd1c70b44916c2a755ede0f6ad25d15384a8c065befffe4307bac02f1ec8c8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f2fd1c70b44916c2a755ede0f6ad25d15384a8c065befffe4307bac02f1ec8c8?s=96&d=mm&r=g\",\"caption\":\"Lauane de Melo\"},\"sameAs\":[\"http:\/\/clickfozdoiguacu.com.br\",\"https:\/\/www.facebook.com\/lauane.ferreirademelo\"],\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/author\/lauane\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tabela do Brasileir&atilde;o s&eacute;rie D &eacute; divulgada pela CBF - Clickfoz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/box5640.temp.domains\/~clickfoz\/tabela-do-brasileirao-serie-d-e-divulgada-pela-cbf\/","og_locale":"pt_BR","og_type":"article","og_title":"Tabela do Brasileir&atilde;o s&eacute;rie D &eacute; divulgada pela CBF - Clickfoz","og_description":"Depois de algumas especula&ccedil;&otilde;es sobre o grupo do Foz do Igua&ccedil;u Futebol Clube no Campeonato Brasileiro da S&eacute;rie D 2015, a Confedera&ccedil;&atilde;o Brasileira de Futebol, CBF, divulgou nesta quarta-feira, 13, a tabela da competi&ccedil;&atilde;o nacional e p&ocirc;s fim ao mist&eacute;rio. Foto: Arquivo O Foz Futebol conquistou a vaga para o Brasileir&atilde;o S&eacute;rie D, ap&oacute;s a [&hellip;]","og_url":"http:\/\/box5640.temp.domains\/~clickfoz\/tabela-do-brasileirao-serie-d-e-divulgada-pela-cbf\/","og_site_name":"Clickfoz","article_publisher":"https:\/\/facebook.com\/clickfoz","article_author":"https:\/\/www.facebook.com\/lauane.ferreirademelo","article_published_time":"2015-05-14T09:33:26+00:00","og_image":[{"url":"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/Foz%20x%20Operario%20inicio.JPG","type":"","width":"","height":""}],"author":"Lauane de Melo","twitter_card":"summary_large_image","twitter_creator":"@clickfoz","twitter_site":"@clickfoz","twitter_misc":{"Escrito por":"Lauane de Melo","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/tabela-do-brasileirao-serie-d-e-divulgada-pela-cbf\/#article","isPartOf":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/tabela-do-brasileirao-serie-d-e-divulgada-pela-cbf\/"},"author":{"name":"Lauane de Melo","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/person\/8975ece75a84fdc225ca535af4957bbd"},"headline":"Tabela do Brasileir&atilde;o s&eacute;rie D &eacute; divulgada pela CBF","datePublished":"2015-05-14T09:33:26+00:00","mainEntityOfPage":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/tabela-do-brasileirao-serie-d-e-divulgada-pela-cbf\/"},"wordCount":447,"commentCount":0,"publisher":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization"},"image":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/tabela-do-brasileirao-serie-d-e-divulgada-pela-cbf\/#primaryimage"},"thumbnailUrl":"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/Foz%20x%20Operario%20inicio.JPG","inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/box5640.temp.domains\/~clickfoz\/tabela-do-brasileirao-serie-d-e-divulgada-pela-cbf\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/tabela-do-brasileirao-serie-d-e-divulgada-pela-cbf\/","url":"http:\/\/box5640.temp.domains\/~clickfoz\/tabela-do-brasileirao-serie-d-e-divulgada-pela-cbf\/","name":"Tabela do Brasileir&atilde;o s&eacute;rie D &eacute; divulgada pela CBF - Clickfoz","isPartOf":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#website"},"primaryImageOfPage":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/tabela-do-brasileirao-serie-d-e-divulgada-pela-cbf\/#primaryimage"},"image":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/tabela-do-brasileirao-serie-d-e-divulgada-pela-cbf\/#primaryimage"},"thumbnailUrl":"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/Foz%20x%20Operario%20inicio.JPG","datePublished":"2015-05-14T09:33:26+00:00","breadcrumb":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/tabela-do-brasileirao-serie-d-e-divulgada-pela-cbf\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/box5640.temp.domains\/~clickfoz\/tabela-do-brasileirao-serie-d-e-divulgada-pela-cbf\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/tabela-do-brasileirao-serie-d-e-divulgada-pela-cbf\/#primaryimage","url":"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/Foz%20x%20Operario%20inicio.JPG","contentUrl":"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/Foz%20x%20Operario%20inicio.JPG"},{"@type":"BreadcrumbList","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/tabela-do-brasileirao-serie-d-e-divulgada-pela-cbf\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/box5640.temp.domains\/~clickfoz\/"},{"@type":"ListItem","position":2,"name":"Tabela do Brasileir&atilde;o s&eacute;rie D &eacute; divulgada pela CBF"}]},{"@type":"WebSite","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#website","url":"https:\/\/box5640.temp.domains\/~clickfoz\/","name":"Click Foz do Igua\u00e7u","description":"O portal de not\u00edcias de Foz do Igua\u00e7u","publisher":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/box5640.temp.domains\/~clickfoz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization","name":"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i","url":"https:\/\/box5640.temp.domains\/~clickfoz\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/","url":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png","contentUrl":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png","width":190,"height":65,"caption":"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i"},"image":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/clickfoz","https:\/\/x.com\/clickfoz","https:\/\/www.instagram.com\/clickfoz"]},{"@type":"Person","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/person\/8975ece75a84fdc225ca535af4957bbd","name":"Lauane de Melo","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f2fd1c70b44916c2a755ede0f6ad25d15384a8c065befffe4307bac02f1ec8c8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f2fd1c70b44916c2a755ede0f6ad25d15384a8c065befffe4307bac02f1ec8c8?s=96&d=mm&r=g","caption":"Lauane de Melo"},"sameAs":["http:\/\/clickfozdoiguacu.com.br","https:\/\/www.facebook.com\/lauane.ferreirademelo"],"url":"http:\/\/box5640.temp.domains\/~clickfoz\/author\/lauane\/"}]}},"_links":{"self":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts\/2929","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/comments?post=2929"}],"version-history":[{"count":0,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts\/2929\/revisions"}],"wp:attachment":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/media?parent=2929"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/categories?post=2929"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/tags?post=2929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}