{"id":2839,"date":"2015-05-28T16:39:04","date_gmt":"2015-05-28T16:39:04","guid":{"rendered":"http:\/\/localhost:82\/wordpress\/2015\/05\/28\/codefoz-entrega-projeto-de-revitalizacao-da-av-das-cataratas\/"},"modified":"2015-05-28T16:39:04","modified_gmt":"2015-05-28T16:39:04","slug":"codefoz-entrega-projeto-de-revitalizacao-da-av-das-cataratas","status":"publish","type":"post","link":"http:\/\/box5640.temp.domains\/~clickfoz\/codefoz-entrega-projeto-de-revitalizacao-da-av-das-cataratas\/","title":{"rendered":"Codefoz entrega projeto de revitaliza&ccedil;&atilde;o da Av. das Cataratas"},"content":{"rendered":"<div>\nO projeto para revitaliza&ccedil;&atilde;o da Avenida das Cataratas, no trecho de quatro quil&ocirc;metros entre a Avenida Jorge Schimmelpfeng e o trevo de acesso &agrave; Argentina, j&aacute; est&aacute; conclu&iacute;do. Na noite desta quarta-feira, 27, o documento foi entregue pelo secret&aacute;rio do Conselho de Desenvolvimento Econ&ocirc;mico e Social de Foz do Igua&ccedil;u (Codefoz) e superintendente de Comunica&ccedil;&atilde;o Social da Itaipu, Gilmar Piolla, ao prefeito Reni Pereira, durante reuni&atilde;o ordin&aacute;ria do plen&aacute;rio do Codefoz, na Funda&ccedil;&atilde;o Cultural.<\/p>\n<table cellspacing=\"0\" cellpadding=\"0\" border=\"0\" align=\"center\" width=\"200\" style=\"margin: 0 3px\">\n<tbody>\n<tr>\n<td style=\"text-align: right\"><span style=\"font-size: 11px\">Foto: Itaipu<\/span><\/td>\n<\/tr>\n<tr>\n<td bgcolor=\"#f4f4f2\"><img fetchpriority=\"high\" decoding=\"async\" height=\"433\" width=\"650\" src=\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/revitaliza%C3%A7%C3%A3o%20da%20avenida%20das%20cataratas1.jpg\" alt=\"\" \/><\/td>\n<\/tr>\n<tr>\n<td bgcolor=\"#f4f4f2\" style=\"padding: 3px 1px;font-size: 11px;text-align: center\">Prefeito Reni Pereira recebe o projeto do Codefoz nesta quarta-feira, 27<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: justify\">\nDesenvolvido em parceria entre a Itaipu Binacional e o Iguassu Convention &amp; Visitors Bureau, o projeto de revitaliza&ccedil;&atilde;o prev&ecirc; o alargamento e duplica&ccedil;&atilde;o das pistas, a constru&ccedil;&atilde;o de rotat&oacute;rias e de retornos em n&iacute;vel, a implanta&ccedil;&atilde;o de faixas elevadas para pedestres, de cal&ccedil;adas e ciclovia, al&eacute;m de paisagismo, ilumina&ccedil;&atilde;o e sinaliza&ccedil;&atilde;o. &ldquo;Queremos garantir maior seguran&ccedil;a aos usu&aacute;rios e contribuir para uma imagem positiva aos turistas que vierem conhecer nossos atrativos&rdquo;, disse Piolla, que &eacute; tamb&eacute;m presidente do Fundo Igua&ccedil;u.<\/p>\n<p>O prefeito Reni Pereira lembrou que o ministro das Cidades, Gilberto Kassab, j&aacute; reconheceu a necessidade de melhorias na Avenida das Cataratas e que, &ldquo;com uma argumenta&ccedil;&atilde;o t&eacute;cnica e com esse projeto bem feito, (a obra) s&oacute; n&atilde;o sai se n&atilde;o tiver dinheiro&rdquo;. Mas, segundo o prefeito, &ldquo;a crise n&atilde;o &eacute; permanente&rdquo;, e Foz do Igua&ccedil;u estar&aacute; habilitada a receber os recursos necess&aacute;rios na primeira oportunidade.<\/p>\n<p><strong>O projeto &#8211; <\/strong>Reni Pereira recebeu de Piolla o projeto executivo, o relat&oacute;rio do projeto e o or&ccedil;amento da obra, que prev&ecirc; recursos da ordem de R$ 17,5 milh&otilde;es, para execu&ccedil;&atilde;o de toda a revitaliza&ccedil;&atilde;o. O objetivo &eacute; transformar a avenida &ldquo;em cart&atilde;o postal da cidade, integrada com o projeto de duplica&ccedil;&atilde;o da Rodovia das Cataratas&rdquo;, como afirmou Piolla na apresenta&ccedil;&atilde;o.&nbsp;<br \/>\n&nbsp;<\/p>\n<table cellspacing=\"0\" cellpadding=\"0\" border=\"0\" align=\"center\" width=\"200\" style=\"margin: 0 3px\">\n<tbody>\n<tr>\n<td style=\"text-align: right\"><span style=\"font-size: 11px\">Foto: Itaipu<\/span><\/td>\n<\/tr>\n<tr>\n<td bgcolor=\"#f4f4f2\"><img decoding=\"async\" height=\"433\" width=\"650\" src=\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/revitaliza%C3%A7%C3%A3o%20da%20avenida%20das%20cataratas.jpg\" alt=\"\" \/><\/td>\n<\/tr>\n<tr>\n<td bgcolor=\"#f4f4f2\" style=\"padding: 3px 1px;font-size: 11px;text-align: center\">Avenida das Cataratas ganhar&aacute; um corredor de Ip&ecirc;s<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: justify\">\nPrincipal liga&ccedil;&atilde;o para o acesso &agrave; Argentina, ao Aeroporto Internacional e ao Parque Nacional do Igua&ccedil;u, a Avenida das Cataratas ter&aacute; um paisagismo diferenciado, com o plantio de ip&ecirc;s de v&aacute;rias cores e de outras esp&eacute;cies de vegeta&ccedil;&atilde;o nativa no canteiro central. Em toda a extens&atilde;o da avenida, haver&aacute; uma ciclovia e cal&ccedil;ada para pedestres, com no m&iacute;nimo tr&ecirc;s metros de largura.<\/p>\n<p>No trecho entre a Churrascaria Rafain e o trevo de acesso &agrave; Argentina, o projeto prev&ecirc; a implanta&ccedil;&atilde;o de tr&ecirc;s pistas. A pista lateral em frente ao restaurante ser&aacute; mantida. Ser&atilde;o constru&iacute;das duas rotat&oacute;rias, uma na futura extens&atilde;o da Avenida Harry Shinckle, que ligar&aacute; a Avenida &agrave; Rodovi&aacute;ria e &agrave; BR-277 (o projeto dessa liga&ccedil;&atilde;o j&aacute; foi licitado, segundo o prefeito) e outra em frente ao Hotel Mabu e Shopping Catua&iacute; Palladium (em constru&ccedil;&atilde;o). Haver&aacute; passagens em n&iacute;vel para pedestres em frente ao Hotel Dom Pedro I e em frente ao shopping. <\/p>\n<p>Em abril, quando o ministro Gilberto Kassab esteve em Cascavel, representantes de Foz do Igua&ccedil;u entregaram um documento pedindo apoio para os projetos da Avenida das Cataratas e &nbsp;para o viaduto entre a Avenida Costa e Silva e a BR-277. O ministro reconheceu a necessidade das obras e recomendou que os projetos fossem doados pelo Fundo Igua&ccedil;u &agrave; Prefeitura, que, por sua vez, faria o encaminhamento ao minist&eacute;rio. <\/p>\n<p>Gilmar Piolla informou que os projetos do viaduto da Avenida Costa e Silva e da rotat&oacute;ria do CTG Charrua est&atilde;o sendo desenvolvidos e devem ficar prontos num prazo entre quatro a seis meses. Essas obras, bem como a duplica&ccedil;&atilde;o da BR-469 (Rodovia das Cataratas) e o novo sistema de pistas do Aeroporto Internacional, s&atilde;o consideradas &ldquo;emblem&aacute;ticas&rdquo; e fazem parte do Plano de Desenvolvimento Econ&ocirc;mico (PDE) do Codefoz. <\/p>\n<p>Com custo estimado de R$ 12 milh&otilde;es, o projeto para o viaduto da Avenida Costa e Silva consiste na readequa&ccedil;&atilde;o da interse&ccedil;&atilde;o com a Rodovia BR-277, numa extens&atilde;o aproximada de 700 metros. A proposta &eacute; construir quatro obras de arte especiais, em curva, constitu&iacute;das em acesso por &ldquo;terras armadas&rdquo;, juntamente com a implanta&ccedil;&atilde;o de rotat&oacute;ria alongada sob as obras &nbsp;de arte projetadas e a intera&ccedil;&atilde;o com as vias marginais existentes, que tamb&eacute;m ser&atilde;o readequadas.<\/p>\n<\/div>\n<div>&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>O projeto para revitaliza&ccedil;&atilde;o da Avenida das Cataratas, no trecho de quatro quil&ocirc;metros entre a Avenida Jorge Schimmelpfeng e o trevo de acesso &agrave; Argentina, j&aacute; est&aacute; conclu&iacute;do. Na noite desta quarta-feira, 27, o documento foi entregue pelo secret&aacute;rio do Conselho de Desenvolvimento Econ&ocirc;mico e Social de Foz do Igua&ccedil;u (Codefoz) e superintendente de Comunica&ccedil;&atilde;o [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-2839","post","type-post","status-publish","format-standard","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Codefoz entrega projeto de revitaliza&ccedil;&atilde;o da Av. das Cataratas - Clickfoz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/box5640.temp.domains\/~clickfoz\/codefoz-entrega-projeto-de-revitalizacao-da-av-das-cataratas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Codefoz entrega projeto de revitaliza&ccedil;&atilde;o da Av. das Cataratas - Clickfoz\" \/>\n<meta property=\"og:description\" content=\"O projeto para revitaliza&ccedil;&atilde;o da Avenida das Cataratas, no trecho de quatro quil&ocirc;metros entre a Avenida Jorge Schimmelpfeng e o trevo de acesso &agrave; Argentina, j&aacute; est&aacute; conclu&iacute;do. Na noite desta quarta-feira, 27, o documento foi entregue pelo secret&aacute;rio do Conselho de Desenvolvimento Econ&ocirc;mico e Social de Foz do Igua&ccedil;u (Codefoz) e superintendente de Comunica&ccedil;&atilde;o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/box5640.temp.domains\/~clickfoz\/codefoz-entrega-projeto-de-revitalizacao-da-av-das-cataratas\/\" \/>\n<meta property=\"og:site_name\" content=\"Clickfoz\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/clickfoz\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/lauane.ferreirademelo\" \/>\n<meta property=\"article:published_time\" content=\"2015-05-28T16:39:04+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/revitaliza%C3%A7%C3%A3o%20da%20avenida%20das%20cataratas1.jpg\" \/>\n<meta name=\"author\" content=\"Lauane de Melo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@clickfoz\" \/>\n<meta name=\"twitter:site\" content=\"@clickfoz\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lauane de Melo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/codefoz-entrega-projeto-de-revitalizacao-da-av-das-cataratas\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/codefoz-entrega-projeto-de-revitalizacao-da-av-das-cataratas\/\"},\"author\":{\"name\":\"Lauane de Melo\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/person\/8975ece75a84fdc225ca535af4957bbd\"},\"headline\":\"Codefoz entrega projeto de revitaliza&ccedil;&atilde;o da Av. das Cataratas\",\"datePublished\":\"2015-05-28T16:39:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/codefoz-entrega-projeto-de-revitalizacao-da-av-das-cataratas\/\"},\"wordCount\":890,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\"},\"image\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/codefoz-entrega-projeto-de-revitalizacao-da-av-das-cataratas\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/revitaliza%C3%A7%C3%A3o%20da%20avenida%20das%20cataratas1.jpg\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\/\/box5640.temp.domains\/~clickfoz\/codefoz-entrega-projeto-de-revitalizacao-da-av-das-cataratas\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/codefoz-entrega-projeto-de-revitalizacao-da-av-das-cataratas\/\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/codefoz-entrega-projeto-de-revitalizacao-da-av-das-cataratas\/\",\"name\":\"Codefoz entrega projeto de revitaliza&ccedil;&atilde;o da Av. das Cataratas - Clickfoz\",\"isPartOf\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/codefoz-entrega-projeto-de-revitalizacao-da-av-das-cataratas\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/codefoz-entrega-projeto-de-revitalizacao-da-av-das-cataratas\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/revitaliza%C3%A7%C3%A3o%20da%20avenida%20das%20cataratas1.jpg\",\"datePublished\":\"2015-05-28T16:39:04+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/codefoz-entrega-projeto-de-revitalizacao-da-av-das-cataratas\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/box5640.temp.domains\/~clickfoz\/codefoz-entrega-projeto-de-revitalizacao-da-av-das-cataratas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/codefoz-entrega-projeto-de-revitalizacao-da-av-das-cataratas\/#primaryimage\",\"url\":\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/revitaliza%C3%A7%C3%A3o%20da%20avenida%20das%20cataratas1.jpg\",\"contentUrl\":\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/revitaliza%C3%A7%C3%A3o%20da%20avenida%20das%20cataratas1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/codefoz-entrega-projeto-de-revitalizacao-da-av-das-cataratas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/box5640.temp.domains\/~clickfoz\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Codefoz entrega projeto de revitaliza&ccedil;&atilde;o da Av. das Cataratas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#website\",\"url\":\"https:\/\/box5640.temp.domains\/~clickfoz\/\",\"name\":\"Click Foz do Igua\u00e7u\",\"description\":\"O portal de not\u00edcias de Foz do Igua\u00e7u\",\"publisher\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/box5640.temp.domains\/~clickfoz\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\",\"name\":\"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i\",\"url\":\"https:\/\/box5640.temp.domains\/~clickfoz\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png\",\"contentUrl\":\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png\",\"width\":190,\"height\":65,\"caption\":\"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i\"},\"image\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/clickfoz\",\"https:\/\/x.com\/clickfoz\",\"https:\/\/www.instagram.com\/clickfoz\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/person\/8975ece75a84fdc225ca535af4957bbd\",\"name\":\"Lauane de Melo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f2fd1c70b44916c2a755ede0f6ad25d15384a8c065befffe4307bac02f1ec8c8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f2fd1c70b44916c2a755ede0f6ad25d15384a8c065befffe4307bac02f1ec8c8?s=96&d=mm&r=g\",\"caption\":\"Lauane de Melo\"},\"sameAs\":[\"http:\/\/clickfozdoiguacu.com.br\",\"https:\/\/www.facebook.com\/lauane.ferreirademelo\"],\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/author\/lauane\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Codefoz entrega projeto de revitaliza&ccedil;&atilde;o da Av. das Cataratas - Clickfoz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/box5640.temp.domains\/~clickfoz\/codefoz-entrega-projeto-de-revitalizacao-da-av-das-cataratas\/","og_locale":"pt_BR","og_type":"article","og_title":"Codefoz entrega projeto de revitaliza&ccedil;&atilde;o da Av. das Cataratas - Clickfoz","og_description":"O projeto para revitaliza&ccedil;&atilde;o da Avenida das Cataratas, no trecho de quatro quil&ocirc;metros entre a Avenida Jorge Schimmelpfeng e o trevo de acesso &agrave; Argentina, j&aacute; est&aacute; conclu&iacute;do. Na noite desta quarta-feira, 27, o documento foi entregue pelo secret&aacute;rio do Conselho de Desenvolvimento Econ&ocirc;mico e Social de Foz do Igua&ccedil;u (Codefoz) e superintendente de Comunica&ccedil;&atilde;o [&hellip;]","og_url":"http:\/\/box5640.temp.domains\/~clickfoz\/codefoz-entrega-projeto-de-revitalizacao-da-av-das-cataratas\/","og_site_name":"Clickfoz","article_publisher":"https:\/\/facebook.com\/clickfoz","article_author":"https:\/\/www.facebook.com\/lauane.ferreirademelo","article_published_time":"2015-05-28T16:39:04+00:00","og_image":[{"url":"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/revitaliza%C3%A7%C3%A3o%20da%20avenida%20das%20cataratas1.jpg","type":"","width":"","height":""}],"author":"Lauane de Melo","twitter_card":"summary_large_image","twitter_creator":"@clickfoz","twitter_site":"@clickfoz","twitter_misc":{"Escrito por":"Lauane de Melo","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/codefoz-entrega-projeto-de-revitalizacao-da-av-das-cataratas\/#article","isPartOf":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/codefoz-entrega-projeto-de-revitalizacao-da-av-das-cataratas\/"},"author":{"name":"Lauane de Melo","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/person\/8975ece75a84fdc225ca535af4957bbd"},"headline":"Codefoz entrega projeto de revitaliza&ccedil;&atilde;o da Av. das Cataratas","datePublished":"2015-05-28T16:39:04+00:00","mainEntityOfPage":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/codefoz-entrega-projeto-de-revitalizacao-da-av-das-cataratas\/"},"wordCount":890,"commentCount":0,"publisher":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization"},"image":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/codefoz-entrega-projeto-de-revitalizacao-da-av-das-cataratas\/#primaryimage"},"thumbnailUrl":"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/revitaliza%C3%A7%C3%A3o%20da%20avenida%20das%20cataratas1.jpg","inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/box5640.temp.domains\/~clickfoz\/codefoz-entrega-projeto-de-revitalizacao-da-av-das-cataratas\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/codefoz-entrega-projeto-de-revitalizacao-da-av-das-cataratas\/","url":"http:\/\/box5640.temp.domains\/~clickfoz\/codefoz-entrega-projeto-de-revitalizacao-da-av-das-cataratas\/","name":"Codefoz entrega projeto de revitaliza&ccedil;&atilde;o da Av. das Cataratas - Clickfoz","isPartOf":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#website"},"primaryImageOfPage":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/codefoz-entrega-projeto-de-revitalizacao-da-av-das-cataratas\/#primaryimage"},"image":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/codefoz-entrega-projeto-de-revitalizacao-da-av-das-cataratas\/#primaryimage"},"thumbnailUrl":"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/revitaliza%C3%A7%C3%A3o%20da%20avenida%20das%20cataratas1.jpg","datePublished":"2015-05-28T16:39:04+00:00","breadcrumb":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/codefoz-entrega-projeto-de-revitalizacao-da-av-das-cataratas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/box5640.temp.domains\/~clickfoz\/codefoz-entrega-projeto-de-revitalizacao-da-av-das-cataratas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/codefoz-entrega-projeto-de-revitalizacao-da-av-das-cataratas\/#primaryimage","url":"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/revitaliza%C3%A7%C3%A3o%20da%20avenida%20das%20cataratas1.jpg","contentUrl":"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/revitaliza%C3%A7%C3%A3o%20da%20avenida%20das%20cataratas1.jpg"},{"@type":"BreadcrumbList","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/codefoz-entrega-projeto-de-revitalizacao-da-av-das-cataratas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/box5640.temp.domains\/~clickfoz\/"},{"@type":"ListItem","position":2,"name":"Codefoz entrega projeto de revitaliza&ccedil;&atilde;o da Av. das Cataratas"}]},{"@type":"WebSite","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#website","url":"https:\/\/box5640.temp.domains\/~clickfoz\/","name":"Click Foz do Igua\u00e7u","description":"O portal de not\u00edcias de Foz do Igua\u00e7u","publisher":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/box5640.temp.domains\/~clickfoz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization","name":"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i","url":"https:\/\/box5640.temp.domains\/~clickfoz\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/","url":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png","contentUrl":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png","width":190,"height":65,"caption":"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i"},"image":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/clickfoz","https:\/\/x.com\/clickfoz","https:\/\/www.instagram.com\/clickfoz"]},{"@type":"Person","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/person\/8975ece75a84fdc225ca535af4957bbd","name":"Lauane de Melo","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f2fd1c70b44916c2a755ede0f6ad25d15384a8c065befffe4307bac02f1ec8c8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f2fd1c70b44916c2a755ede0f6ad25d15384a8c065befffe4307bac02f1ec8c8?s=96&d=mm&r=g","caption":"Lauane de Melo"},"sameAs":["http:\/\/clickfozdoiguacu.com.br","https:\/\/www.facebook.com\/lauane.ferreirademelo"],"url":"http:\/\/box5640.temp.domains\/~clickfoz\/author\/lauane\/"}]}},"_links":{"self":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts\/2839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/comments?post=2839"}],"version-history":[{"count":0,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts\/2839\/revisions"}],"wp:attachment":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/media?parent=2839"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/categories?post=2839"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/tags?post=2839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}