{"id":2629,"date":"2015-07-14T10:22:22","date_gmt":"2015-07-14T10:22:22","guid":{"rendered":"http:\/\/localhost:82\/wordpress\/2015\/07\/14\/copel-abre-70-vagas-para-concurso-publico\/"},"modified":"2015-07-14T10:22:22","modified_gmt":"2015-07-14T10:22:22","slug":"copel-abre-70-vagas-para-concurso-publico","status":"publish","type":"post","link":"http:\/\/box5640.temp.domains\/~clickfoz\/copel-abre-70-vagas-para-concurso-publico\/","title":{"rendered":"Copel abre 70 vagas para concurso p&uacute;blico"},"content":{"rendered":"<div>\nA Copel publicou na tarde desta segunda-feira, 13, edital de concurso p&uacute;blico para a sele&ccedil;&atilde;o de pelo menos 70 novos empregados. Os sal&aacute;rios variam de R$ 1.447,60 para n&iacute;vel m&eacute;dio at&eacute; R$ 6.064,54 para n&iacute;vel superior.&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" src=\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/COPEL_Logo_Laranja.jpg\" width=\"650\" height=\"230\" alt=\"\" \/><\/div>\n<div>As provas ser&atilde;o realizadas pela Universidade Federal do Paran&aacute; no dia 27 de setembro. As inscri&ccedil;&otilde;es devem ser efetuadas exclusivamente pela internet entre 21 de julho e 21 de agosto, no endere&ccedil;o <strong><a href=\"http:\/\/www.nc.ufpr.br\/concursos_externos\/copel2015\" target=\"_blank\">www.nc.ufpr.br\/concursos_externos\/copel2015<\/a><\/strong>.&nbsp;<\/p>\n<p>Entre os maiores benef&iacute;cios oferecidos pela Copel, destacam-se o 13&ordm; sal&aacute;rio do vale alimenta&ccedil;&atilde;o, adiantamento de f&eacute;rias parcelado em at&eacute; 10 vezes sem juros, plano de assist&ecirc;ncia m&eacute;dica e previd&ecirc;ncia privada. <\/p>\n<p>Para n&iacute;vel superior as vagas s&atilde;o para: Administrador, Advogado, Analista Comercial, Analista de Sistemas, Analista Socioambiental, Analista de Web Designer, Bi&oacute;logo, Contador, Economista, Engenheiro Ambiental, Engenheiro Civil, Engenheiro da Computa&ccedil;&atilde;o, Engenheiro Eletricista, Engenheiro Eletr&ocirc;nico, Engenheiro Florestal, Engenheiro Mec&acirc;nico, Ge&oacute;logo, M&eacute;dico do Trabalho, Redator e Soci&oacute;logo.<\/p>\n<p>J&aacute; para t&eacute;cnico em n&iacute;vel m&eacute;dio as vagas s&atilde;o para: T&eacute;cnico de Agrimensura, T&eacute;cnico de Seguran&ccedil;a do Trabalho, T&eacute;cnico em Meio Ambiente, T&eacute;cnico Florestal, T&eacute;cnico Industrial de Eletromec&acirc;nica, T&eacute;cnico Industrial de Eletr&ocirc;nica, T&eacute;cnico Industrial de Eletrot&eacute;cnica, T&eacute;cnico Industrial de Mec&acirc;nica, T&eacute;cnico Industrial de Qu&iacute;mica e T&eacute;cnico de Hidrologia. <\/p>\n<p>H&aacute; vagas tamb&eacute;m para n&iacute;vel m&eacute;dio: Leiturista, T&eacute;cnico Administrativo, Teleatendente, Eletricista Aprendiz, Oficial de Opera&ccedil;&atilde;o e Manuten&ccedil;&atilde;o Eletromec&acirc;nica de Usina, Inspe&ccedil;&atilde;o de Manuten&ccedil;&atilde;o de Ve&iacute;culos e T&eacute;cnico Cont&aacute;bil.&nbsp;<\/p>\n<div>&nbsp;<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Copel publicou na tarde desta segunda-feira, 13, edital de concurso p&uacute;blico para a sele&ccedil;&atilde;o de pelo menos 70 novos empregados. Os sal&aacute;rios variam de R$ 1.447,60 para n&iacute;vel m&eacute;dio at&eacute; R$ 6.064,54 para n&iacute;vel superior.&nbsp; As provas ser&atilde;o realizadas pela Universidade Federal do Paran&aacute; no dia 27 de setembro. As inscri&ccedil;&otilde;es devem ser efetuadas [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-2629","post","type-post","status-publish","format-standard","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Copel abre 70 vagas para concurso p&uacute;blico - Clickfoz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/box5640.temp.domains\/~clickfoz\/copel-abre-70-vagas-para-concurso-publico\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Copel abre 70 vagas para concurso p&uacute;blico - Clickfoz\" \/>\n<meta property=\"og:description\" content=\"A Copel publicou na tarde desta segunda-feira, 13, edital de concurso p&uacute;blico para a sele&ccedil;&atilde;o de pelo menos 70 novos empregados. Os sal&aacute;rios variam de R$ 1.447,60 para n&iacute;vel m&eacute;dio at&eacute; R$ 6.064,54 para n&iacute;vel superior.&nbsp; As provas ser&atilde;o realizadas pela Universidade Federal do Paran&aacute; no dia 27 de setembro. As inscri&ccedil;&otilde;es devem ser efetuadas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/box5640.temp.domains\/~clickfoz\/copel-abre-70-vagas-para-concurso-publico\/\" \/>\n<meta property=\"og:site_name\" content=\"Clickfoz\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/clickfoz\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/lauane.ferreirademelo\" \/>\n<meta property=\"article:published_time\" content=\"2015-07-14T10:22:22+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/COPEL_Logo_Laranja.jpg\" \/>\n<meta name=\"author\" content=\"Lauane de Melo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@clickfoz\" \/>\n<meta name=\"twitter:site\" content=\"@clickfoz\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lauane de Melo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/copel-abre-70-vagas-para-concurso-publico\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/copel-abre-70-vagas-para-concurso-publico\/\"},\"author\":{\"name\":\"Lauane de Melo\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/person\/8975ece75a84fdc225ca535af4957bbd\"},\"headline\":\"Copel abre 70 vagas para concurso p&uacute;blico\",\"datePublished\":\"2015-07-14T10:22:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/copel-abre-70-vagas-para-concurso-publico\/\"},\"wordCount\":358,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\"},\"image\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/copel-abre-70-vagas-para-concurso-publico\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/COPEL_Logo_Laranja.jpg\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\/\/box5640.temp.domains\/~clickfoz\/copel-abre-70-vagas-para-concurso-publico\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/copel-abre-70-vagas-para-concurso-publico\/\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/copel-abre-70-vagas-para-concurso-publico\/\",\"name\":\"Copel abre 70 vagas para concurso p&uacute;blico - Clickfoz\",\"isPartOf\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/copel-abre-70-vagas-para-concurso-publico\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/copel-abre-70-vagas-para-concurso-publico\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/COPEL_Logo_Laranja.jpg\",\"datePublished\":\"2015-07-14T10:22:22+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/copel-abre-70-vagas-para-concurso-publico\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/box5640.temp.domains\/~clickfoz\/copel-abre-70-vagas-para-concurso-publico\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/copel-abre-70-vagas-para-concurso-publico\/#primaryimage\",\"url\":\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/COPEL_Logo_Laranja.jpg\",\"contentUrl\":\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/COPEL_Logo_Laranja.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/copel-abre-70-vagas-para-concurso-publico\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/box5640.temp.domains\/~clickfoz\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Copel abre 70 vagas para concurso p&uacute;blico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#website\",\"url\":\"https:\/\/box5640.temp.domains\/~clickfoz\/\",\"name\":\"Click Foz do Igua\u00e7u\",\"description\":\"O portal de not\u00edcias de Foz do Igua\u00e7u\",\"publisher\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/box5640.temp.domains\/~clickfoz\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\",\"name\":\"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i\",\"url\":\"https:\/\/box5640.temp.domains\/~clickfoz\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png\",\"contentUrl\":\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png\",\"width\":190,\"height\":65,\"caption\":\"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i\"},\"image\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/clickfoz\",\"https:\/\/x.com\/clickfoz\",\"https:\/\/www.instagram.com\/clickfoz\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/person\/8975ece75a84fdc225ca535af4957bbd\",\"name\":\"Lauane de Melo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f2fd1c70b44916c2a755ede0f6ad25d15384a8c065befffe4307bac02f1ec8c8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f2fd1c70b44916c2a755ede0f6ad25d15384a8c065befffe4307bac02f1ec8c8?s=96&d=mm&r=g\",\"caption\":\"Lauane de Melo\"},\"sameAs\":[\"http:\/\/clickfozdoiguacu.com.br\",\"https:\/\/www.facebook.com\/lauane.ferreirademelo\"],\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/author\/lauane\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Copel abre 70 vagas para concurso p&uacute;blico - Clickfoz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/box5640.temp.domains\/~clickfoz\/copel-abre-70-vagas-para-concurso-publico\/","og_locale":"pt_BR","og_type":"article","og_title":"Copel abre 70 vagas para concurso p&uacute;blico - Clickfoz","og_description":"A Copel publicou na tarde desta segunda-feira, 13, edital de concurso p&uacute;blico para a sele&ccedil;&atilde;o de pelo menos 70 novos empregados. Os sal&aacute;rios variam de R$ 1.447,60 para n&iacute;vel m&eacute;dio at&eacute; R$ 6.064,54 para n&iacute;vel superior.&nbsp; As provas ser&atilde;o realizadas pela Universidade Federal do Paran&aacute; no dia 27 de setembro. As inscri&ccedil;&otilde;es devem ser efetuadas [&hellip;]","og_url":"http:\/\/box5640.temp.domains\/~clickfoz\/copel-abre-70-vagas-para-concurso-publico\/","og_site_name":"Clickfoz","article_publisher":"https:\/\/facebook.com\/clickfoz","article_author":"https:\/\/www.facebook.com\/lauane.ferreirademelo","article_published_time":"2015-07-14T10:22:22+00:00","og_image":[{"url":"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/COPEL_Logo_Laranja.jpg","type":"","width":"","height":""}],"author":"Lauane de Melo","twitter_card":"summary_large_image","twitter_creator":"@clickfoz","twitter_site":"@clickfoz","twitter_misc":{"Escrito por":"Lauane de Melo","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/copel-abre-70-vagas-para-concurso-publico\/#article","isPartOf":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/copel-abre-70-vagas-para-concurso-publico\/"},"author":{"name":"Lauane de Melo","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/person\/8975ece75a84fdc225ca535af4957bbd"},"headline":"Copel abre 70 vagas para concurso p&uacute;blico","datePublished":"2015-07-14T10:22:22+00:00","mainEntityOfPage":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/copel-abre-70-vagas-para-concurso-publico\/"},"wordCount":358,"commentCount":0,"publisher":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization"},"image":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/copel-abre-70-vagas-para-concurso-publico\/#primaryimage"},"thumbnailUrl":"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/COPEL_Logo_Laranja.jpg","inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/box5640.temp.domains\/~clickfoz\/copel-abre-70-vagas-para-concurso-publico\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/copel-abre-70-vagas-para-concurso-publico\/","url":"http:\/\/box5640.temp.domains\/~clickfoz\/copel-abre-70-vagas-para-concurso-publico\/","name":"Copel abre 70 vagas para concurso p&uacute;blico - Clickfoz","isPartOf":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#website"},"primaryImageOfPage":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/copel-abre-70-vagas-para-concurso-publico\/#primaryimage"},"image":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/copel-abre-70-vagas-para-concurso-publico\/#primaryimage"},"thumbnailUrl":"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/COPEL_Logo_Laranja.jpg","datePublished":"2015-07-14T10:22:22+00:00","breadcrumb":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/copel-abre-70-vagas-para-concurso-publico\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/box5640.temp.domains\/~clickfoz\/copel-abre-70-vagas-para-concurso-publico\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/copel-abre-70-vagas-para-concurso-publico\/#primaryimage","url":"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/COPEL_Logo_Laranja.jpg","contentUrl":"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/COPEL_Logo_Laranja.jpg"},{"@type":"BreadcrumbList","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/copel-abre-70-vagas-para-concurso-publico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/box5640.temp.domains\/~clickfoz\/"},{"@type":"ListItem","position":2,"name":"Copel abre 70 vagas para concurso p&uacute;blico"}]},{"@type":"WebSite","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#website","url":"https:\/\/box5640.temp.domains\/~clickfoz\/","name":"Click Foz do Igua\u00e7u","description":"O portal de not\u00edcias de Foz do Igua\u00e7u","publisher":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/box5640.temp.domains\/~clickfoz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization","name":"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i","url":"https:\/\/box5640.temp.domains\/~clickfoz\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/","url":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png","contentUrl":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png","width":190,"height":65,"caption":"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i"},"image":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/clickfoz","https:\/\/x.com\/clickfoz","https:\/\/www.instagram.com\/clickfoz"]},{"@type":"Person","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/person\/8975ece75a84fdc225ca535af4957bbd","name":"Lauane de Melo","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f2fd1c70b44916c2a755ede0f6ad25d15384a8c065befffe4307bac02f1ec8c8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f2fd1c70b44916c2a755ede0f6ad25d15384a8c065befffe4307bac02f1ec8c8?s=96&d=mm&r=g","caption":"Lauane de Melo"},"sameAs":["http:\/\/clickfozdoiguacu.com.br","https:\/\/www.facebook.com\/lauane.ferreirademelo"],"url":"http:\/\/box5640.temp.domains\/~clickfoz\/author\/lauane\/"}]}},"_links":{"self":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts\/2629","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/comments?post=2629"}],"version-history":[{"count":0,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts\/2629\/revisions"}],"wp:attachment":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/media?parent=2629"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/categories?post=2629"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/tags?post=2629"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}