{"id":2605,"date":"2015-07-18T11:08:19","date_gmt":"2015-07-18T11:08:19","guid":{"rendered":"http:\/\/localhost:82\/wordpress\/2015\/07\/18\/futsal-de-foz-pede-ajuda-para-os-atingidos-pelo-tornado-no-sudoeste\/"},"modified":"2015-07-18T11:08:19","modified_gmt":"2015-07-18T11:08:19","slug":"futsal-de-foz-pede-ajuda-para-os-atingidos-pelo-tornado-no-sudoeste","status":"publish","type":"post","link":"http:\/\/box5640.temp.domains\/~clickfoz\/futsal-de-foz-pede-ajuda-para-os-atingidos-pelo-tornado-no-sudoeste\/","title":{"rendered":"Futsal de Foz pede ajuda para os atingidos pelo tornado no Sudoeste"},"content":{"rendered":"<p>\nJogadores e comiss&atilde;o t&eacute;cnica do Casa Nissei\/Foz Cataratas iniciaram esta semana uma campanha para arrecadar roupas, cal&ccedil;ados e cobertores para ajudar as fam&iacute;lias atingidas pelo vendaval e chuva de granizo ocorrido nos &uacute;ltimos dias na regi&atilde;o sudoeste do Paran&aacute;. Pelo menos 76 casas e 227 pessoas foram afetadas pelo vendaval da noite de segunda-feira, 13, em Francisco Beltr&atilde;o. <\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" src=\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/Sudoeste%20Tornado.jpg\" width=\"650\" height=\"323\" alt=\"\" \/><\/p>\n<p>A iniciativa que partiu dos atletas e comiss&atilde;o t&eacute;cnica durante os treinamentos da equipe, est&aacute; ganhando as ruas. Sensibilizados com os acontecimentos, torcedores e empres&aacute;rios se engajaram nesta campanha que visa ajudar as fam&iacute;lias v&iacute;timas dessa cat&aacute;strofe.<\/p>\n<p>Todas as doa&ccedil;&otilde;es arrecadadas nesta campanha, ser&atilde;o entregues pelos jogadores igua&ccedil;uenses na pr&oacute;xima quarta-feira, 22, dia em que a equipe do Casa Nissei\/Foz Cataratas enfrenta o Marreco na cidade de Francisco Beltr&atilde;o.<\/p>\n<p>Os interessados em colaborar podem levar suas doa&ccedil;&otilde;es ao Gin&aacute;sio de Esportes Costa Cavalcante at&eacute; a ter&ccedil;a-feira, 21, &agrave;s 19 horas.<\/p>\n<p>A comiss&atilde;o t&eacute;cnica, jogadores e alguns colaboradores da equipe da fronteira tamb&eacute;m &nbsp;arrecadaram uma quantia em dinheiro. Os valores ser&atilde;o depositados em uma conta disponibilizada pela A&ccedil;&atilde;o Social de Francisco Beltr&atilde;o. Quem quiser ajudar basta depositar qualquer valor &ndash; Caixa Econ&ocirc;mica Federal &ndash; Ag&ecirc;ncia &ndash; 0601 &ndash; Opera&ccedil;&atilde;o &ndash; 006 &ndash; Conta 428-2.&nbsp;<\/p>\n<div>&nbsp;<\/div>\n<div>&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Jogadores e comiss&atilde;o t&eacute;cnica do Casa Nissei\/Foz Cataratas iniciaram esta semana uma campanha para arrecadar roupas, cal&ccedil;ados e cobertores para ajudar as fam&iacute;lias atingidas pelo vendaval e chuva de granizo ocorrido nos &uacute;ltimos dias na regi&atilde;o sudoeste do Paran&aacute;. Pelo menos 76 casas e 227 pessoas foram afetadas pelo vendaval da noite de segunda-feira, 13, [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-2605","post","type-post","status-publish","format-standard","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Futsal de Foz pede ajuda para os atingidos pelo tornado no Sudoeste - Clickfoz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/box5640.temp.domains\/~clickfoz\/futsal-de-foz-pede-ajuda-para-os-atingidos-pelo-tornado-no-sudoeste\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Futsal de Foz pede ajuda para os atingidos pelo tornado no Sudoeste - Clickfoz\" \/>\n<meta property=\"og:description\" content=\"Jogadores e comiss&atilde;o t&eacute;cnica do Casa Nissei\/Foz Cataratas iniciaram esta semana uma campanha para arrecadar roupas, cal&ccedil;ados e cobertores para ajudar as fam&iacute;lias atingidas pelo vendaval e chuva de granizo ocorrido nos &uacute;ltimos dias na regi&atilde;o sudoeste do Paran&aacute;. Pelo menos 76 casas e 227 pessoas foram afetadas pelo vendaval da noite de segunda-feira, 13, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/box5640.temp.domains\/~clickfoz\/futsal-de-foz-pede-ajuda-para-os-atingidos-pelo-tornado-no-sudoeste\/\" \/>\n<meta property=\"og:site_name\" content=\"Clickfoz\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/clickfoz\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/lauane.ferreirademelo\" \/>\n<meta property=\"article:published_time\" content=\"2015-07-18T11:08:19+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/Sudoeste%20Tornado.jpg\" \/>\n<meta name=\"author\" content=\"Lauane de Melo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@clickfoz\" \/>\n<meta name=\"twitter:site\" content=\"@clickfoz\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lauane de Melo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/futsal-de-foz-pede-ajuda-para-os-atingidos-pelo-tornado-no-sudoeste\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/futsal-de-foz-pede-ajuda-para-os-atingidos-pelo-tornado-no-sudoeste\/\"},\"author\":{\"name\":\"Lauane de Melo\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/person\/8975ece75a84fdc225ca535af4957bbd\"},\"headline\":\"Futsal de Foz pede ajuda para os atingidos pelo tornado no Sudoeste\",\"datePublished\":\"2015-07-18T11:08:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/futsal-de-foz-pede-ajuda-para-os-atingidos-pelo-tornado-no-sudoeste\/\"},\"wordCount\":278,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\"},\"image\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/futsal-de-foz-pede-ajuda-para-os-atingidos-pelo-tornado-no-sudoeste\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/Sudoeste%20Tornado.jpg\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\/\/box5640.temp.domains\/~clickfoz\/futsal-de-foz-pede-ajuda-para-os-atingidos-pelo-tornado-no-sudoeste\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/futsal-de-foz-pede-ajuda-para-os-atingidos-pelo-tornado-no-sudoeste\/\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/futsal-de-foz-pede-ajuda-para-os-atingidos-pelo-tornado-no-sudoeste\/\",\"name\":\"Futsal de Foz pede ajuda para os atingidos pelo tornado no Sudoeste - Clickfoz\",\"isPartOf\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/futsal-de-foz-pede-ajuda-para-os-atingidos-pelo-tornado-no-sudoeste\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/futsal-de-foz-pede-ajuda-para-os-atingidos-pelo-tornado-no-sudoeste\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/Sudoeste%20Tornado.jpg\",\"datePublished\":\"2015-07-18T11:08:19+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/futsal-de-foz-pede-ajuda-para-os-atingidos-pelo-tornado-no-sudoeste\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/box5640.temp.domains\/~clickfoz\/futsal-de-foz-pede-ajuda-para-os-atingidos-pelo-tornado-no-sudoeste\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/futsal-de-foz-pede-ajuda-para-os-atingidos-pelo-tornado-no-sudoeste\/#primaryimage\",\"url\":\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/Sudoeste%20Tornado.jpg\",\"contentUrl\":\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/Sudoeste%20Tornado.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/futsal-de-foz-pede-ajuda-para-os-atingidos-pelo-tornado-no-sudoeste\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/box5640.temp.domains\/~clickfoz\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Futsal de Foz pede ajuda para os atingidos pelo tornado no Sudoeste\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#website\",\"url\":\"https:\/\/box5640.temp.domains\/~clickfoz\/\",\"name\":\"Click Foz do Igua\u00e7u\",\"description\":\"O portal de not\u00edcias de Foz do Igua\u00e7u\",\"publisher\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/box5640.temp.domains\/~clickfoz\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\",\"name\":\"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i\",\"url\":\"https:\/\/box5640.temp.domains\/~clickfoz\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png\",\"contentUrl\":\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png\",\"width\":190,\"height\":65,\"caption\":\"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i\"},\"image\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/clickfoz\",\"https:\/\/x.com\/clickfoz\",\"https:\/\/www.instagram.com\/clickfoz\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/person\/8975ece75a84fdc225ca535af4957bbd\",\"name\":\"Lauane de Melo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f2fd1c70b44916c2a755ede0f6ad25d15384a8c065befffe4307bac02f1ec8c8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f2fd1c70b44916c2a755ede0f6ad25d15384a8c065befffe4307bac02f1ec8c8?s=96&d=mm&r=g\",\"caption\":\"Lauane de Melo\"},\"sameAs\":[\"http:\/\/clickfozdoiguacu.com.br\",\"https:\/\/www.facebook.com\/lauane.ferreirademelo\"],\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/author\/lauane\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Futsal de Foz pede ajuda para os atingidos pelo tornado no Sudoeste - Clickfoz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/box5640.temp.domains\/~clickfoz\/futsal-de-foz-pede-ajuda-para-os-atingidos-pelo-tornado-no-sudoeste\/","og_locale":"pt_BR","og_type":"article","og_title":"Futsal de Foz pede ajuda para os atingidos pelo tornado no Sudoeste - Clickfoz","og_description":"Jogadores e comiss&atilde;o t&eacute;cnica do Casa Nissei\/Foz Cataratas iniciaram esta semana uma campanha para arrecadar roupas, cal&ccedil;ados e cobertores para ajudar as fam&iacute;lias atingidas pelo vendaval e chuva de granizo ocorrido nos &uacute;ltimos dias na regi&atilde;o sudoeste do Paran&aacute;. Pelo menos 76 casas e 227 pessoas foram afetadas pelo vendaval da noite de segunda-feira, 13, [&hellip;]","og_url":"http:\/\/box5640.temp.domains\/~clickfoz\/futsal-de-foz-pede-ajuda-para-os-atingidos-pelo-tornado-no-sudoeste\/","og_site_name":"Clickfoz","article_publisher":"https:\/\/facebook.com\/clickfoz","article_author":"https:\/\/www.facebook.com\/lauane.ferreirademelo","article_published_time":"2015-07-18T11:08:19+00:00","og_image":[{"url":"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/Sudoeste%20Tornado.jpg","type":"","width":"","height":""}],"author":"Lauane de Melo","twitter_card":"summary_large_image","twitter_creator":"@clickfoz","twitter_site":"@clickfoz","twitter_misc":{"Escrito por":"Lauane de Melo","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/futsal-de-foz-pede-ajuda-para-os-atingidos-pelo-tornado-no-sudoeste\/#article","isPartOf":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/futsal-de-foz-pede-ajuda-para-os-atingidos-pelo-tornado-no-sudoeste\/"},"author":{"name":"Lauane de Melo","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/person\/8975ece75a84fdc225ca535af4957bbd"},"headline":"Futsal de Foz pede ajuda para os atingidos pelo tornado no Sudoeste","datePublished":"2015-07-18T11:08:19+00:00","mainEntityOfPage":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/futsal-de-foz-pede-ajuda-para-os-atingidos-pelo-tornado-no-sudoeste\/"},"wordCount":278,"commentCount":0,"publisher":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization"},"image":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/futsal-de-foz-pede-ajuda-para-os-atingidos-pelo-tornado-no-sudoeste\/#primaryimage"},"thumbnailUrl":"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/Sudoeste%20Tornado.jpg","inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/box5640.temp.domains\/~clickfoz\/futsal-de-foz-pede-ajuda-para-os-atingidos-pelo-tornado-no-sudoeste\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/futsal-de-foz-pede-ajuda-para-os-atingidos-pelo-tornado-no-sudoeste\/","url":"http:\/\/box5640.temp.domains\/~clickfoz\/futsal-de-foz-pede-ajuda-para-os-atingidos-pelo-tornado-no-sudoeste\/","name":"Futsal de Foz pede ajuda para os atingidos pelo tornado no Sudoeste - Clickfoz","isPartOf":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#website"},"primaryImageOfPage":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/futsal-de-foz-pede-ajuda-para-os-atingidos-pelo-tornado-no-sudoeste\/#primaryimage"},"image":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/futsal-de-foz-pede-ajuda-para-os-atingidos-pelo-tornado-no-sudoeste\/#primaryimage"},"thumbnailUrl":"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/Sudoeste%20Tornado.jpg","datePublished":"2015-07-18T11:08:19+00:00","breadcrumb":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/futsal-de-foz-pede-ajuda-para-os-atingidos-pelo-tornado-no-sudoeste\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/box5640.temp.domains\/~clickfoz\/futsal-de-foz-pede-ajuda-para-os-atingidos-pelo-tornado-no-sudoeste\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/futsal-de-foz-pede-ajuda-para-os-atingidos-pelo-tornado-no-sudoeste\/#primaryimage","url":"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/Sudoeste%20Tornado.jpg","contentUrl":"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/Sudoeste%20Tornado.jpg"},{"@type":"BreadcrumbList","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/futsal-de-foz-pede-ajuda-para-os-atingidos-pelo-tornado-no-sudoeste\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/box5640.temp.domains\/~clickfoz\/"},{"@type":"ListItem","position":2,"name":"Futsal de Foz pede ajuda para os atingidos pelo tornado no Sudoeste"}]},{"@type":"WebSite","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#website","url":"https:\/\/box5640.temp.domains\/~clickfoz\/","name":"Click Foz do Igua\u00e7u","description":"O portal de not\u00edcias de Foz do Igua\u00e7u","publisher":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/box5640.temp.domains\/~clickfoz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization","name":"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i","url":"https:\/\/box5640.temp.domains\/~clickfoz\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/","url":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png","contentUrl":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png","width":190,"height":65,"caption":"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i"},"image":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/clickfoz","https:\/\/x.com\/clickfoz","https:\/\/www.instagram.com\/clickfoz"]},{"@type":"Person","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/person\/8975ece75a84fdc225ca535af4957bbd","name":"Lauane de Melo","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f2fd1c70b44916c2a755ede0f6ad25d15384a8c065befffe4307bac02f1ec8c8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f2fd1c70b44916c2a755ede0f6ad25d15384a8c065befffe4307bac02f1ec8c8?s=96&d=mm&r=g","caption":"Lauane de Melo"},"sameAs":["http:\/\/clickfozdoiguacu.com.br","https:\/\/www.facebook.com\/lauane.ferreirademelo"],"url":"http:\/\/box5640.temp.domains\/~clickfoz\/author\/lauane\/"}]}},"_links":{"self":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts\/2605","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/comments?post=2605"}],"version-history":[{"count":0,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts\/2605\/revisions"}],"wp:attachment":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/media?parent=2605"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/categories?post=2605"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/tags?post=2605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}