{"id":14491,"date":"2010-06-12T10:23:51","date_gmt":"2010-06-12T10:23:51","guid":{"rendered":"http:\/\/localhost:82\/wordpress\/2010\/06\/12\/namoro-entre-o-mesmo-sexo-5775\/"},"modified":"2010-06-12T10:23:51","modified_gmt":"2010-06-12T10:23:51","slug":"namoro-entre-o-mesmo-sexo-5775","status":"publish","type":"post","link":"http:\/\/box5640.temp.domains\/~clickfoz\/namoro-entre-o-mesmo-sexo-5775\/","title":{"rendered":"Namoro entre o mesmo sexo"},"content":{"rendered":"<table cellspacing=\"0\" cellpadding=\"0\" border=\"0\" align=\"left\" width=\"200\" style=\"margin: 0 3px\">\n<tbody>\n<tr>\n<td style=\"text-align: right\">&nbsp;<\/td>\n<\/tr>\n<tr>\n<td bgcolor=\"#f4f4f2\"><img fetchpriority=\"high\" decoding=\"async\" height=\"200\" width=\"300\" alt=\"\" src=\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/orgulho%20gay.png\" \/><\/td>\n<\/tr>\n<tr>\n<td bgcolor=\"#f4f4f2\" style=\"padding-top: 3px;padding-right: 1px;padding-bottom: 3px;padding-left: 1px;font-size: 11px;text-align: center\">&quot;Quem n&atilde;o te aceita como voc&ecirc; &eacute; n&atilde;o merece sua considera&ccedil;&atilde;o&quot;, revela a personagem<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div style=\"text-align: justify\">Falar de namoro e n&atilde;o citar a rela&ccedil;&atilde;o homossexual no momento hist&oacute;rico que estamos vivendo &eacute; desprezar boa parte da sociedade. Por isso no Especial Dia do Namoro o portal Clickfoz preparou uma mat&eacute;ria sobre o namoro entre pessoas do mesmo sexo, desmistificando o conceito de que o homossexual n&atilde;o consegue se prender em um relacionamento duradouro.&nbsp;<\/div>\n<div style=\"text-align: justify\">&nbsp;<\/div>\n<div style=\"text-align: justify\">Argumentado biologicamente, psicologicamente e socialmente o gay sempre foi retratado muitas vezes como inexistente, um dos exemplos &eacute; a falta de legisla&ccedil;&atilde;o espec&iacute;fica para contra a viol&ecirc;ncia moral, e pedido para permanecer &agrave; margem, por gritos silenciosos da n&atilde;o aceita&ccedil;&atilde;o.<\/div>\n<div style=\"text-align: justify\">&nbsp;<\/div>\n<div style=\"text-align: justify\">Mesmo com a revolu&ccedil;&atilde;o sexual, a rela&ccedil;&atilde;o homo afetiva existe na maioria das vezes sem a consci&ecirc;ncia dos pais e da rede de relacionamentos, mas n&atilde;o est&aacute; nem um pouco longe de se parecer com uma rela&ccedil;&atilde;o heterossexual. O amor, relacionamento, afeto, carinho e aten&ccedil;&atilde;o s&atilde;o os mesmos.<\/div>\n<div style=\"text-align: justify\">&nbsp;<\/div>\n<div style=\"text-align: justify\">Os nomes do casal feminino foram trocados, n&atilde;o por pedido dos entrevistados, mas para preservar a identidade e conservar que os personagens n&atilde;o sejam vitimas de qualquer mal trato.<\/div>\n<div style=\"text-align: justify\">&nbsp;<\/div>\n<div style=\"text-align: justify\"><strong>Ela com ela<\/strong> &#8211; Talita, 21 anos, com diploma de curso superior, residente em Foz do Igua&ccedil;u est&aacute; prestes h&aacute; completar cinco meses com Michele. Hoje o namoro das duas tem a autoridade dos pais presente, mas nem sempre foi assim, t&atilde;o aberto na fam&iacute;lia.<\/div>\n<div style=\"text-align: justify\">&nbsp;<\/div>\n<div style=\"text-align: justify\">&ldquo;Tive um sentimento diferente por mulheres desde muito cedo, com uns 13, 14 anos, mas s&oacute; fui manifest&aacute;-lo mais tarde, quando senti o mundo &lsquo;se abrindo&rsquo; para mim, percebi que n&atilde;o era passageiro, e finalmente conheci outras garotas como eu. Minhas amizades eram superficiais na &eacute;poca, mas os amigos foram bem compreensivos, e isso me surpreendeu bastante, e acabou fazendo com que a amizade ficasse mais forte, mais concreta, porque eu pude finalmente me sentir aceita sendo quem eu sou&rdquo;, revela Talita.<\/div>\n<div style=\"text-align: justify\">&nbsp;<\/div>\n<div style=\"text-align: justify\">Por&eacute;m o mais complicado ainda estava por vir, revelar &agrave; fam&iacute;lia. &ldquo;Mas depois que voc&ecirc; &eacute; aceito pela fam&iacute;lia acaba perdendo o medo das pessoas, porque quem n&atilde;o te aceita como voc&ecirc; &eacute;, n&atilde;o merece sua considera&ccedil;&atilde;o&rdquo;, diz.<\/div>\n<div style=\"text-align: justify\">&nbsp;<\/div>\n<div style=\"text-align: justify\">Vamos direto ao ponto que esse texto se refere, o namoro. Talita e Michele j&aacute; viviam em um c&iacute;rculo de amizades em comum, se viam em festas e em bares. Mas a hist&oacute;ria deu start no anivers&aacute;rio de Talita, foi quando Michele achou que elas poderiam ser um pouco mais amigas, ent&atilde;o conversa vai, papo vem, at&eacute; que rolou um clima e aconteceu o primeiro beijo. Por&eacute;m logo n&atilde;o se encontraram mais, ent&atilde;o aproximadamente dois meses depois elas se viram acidentalmente em um bar, ficaram e foi a&iacute; que Michele percebeu que poderia rolar algo a mais entre as duas.<\/div>\n<div style=\"text-align: justify\">&nbsp;<\/div>\n<div style=\"text-align: justify\">&ldquo;Algumas pessoas da fam&iacute;lia sabem, mas &eacute; algo meio que n&atilde;o muito falado. Minha irm&atilde; &eacute; mais nova, tem 15 anos, mas sempre me apoiou, e eu contei a ela bem antes dos meus pais, que quando descobriram, ficaram muito decepcionados. No come&ccedil;o foi bastante dif&iacute;cil, sofremos bastante aqui em casa, eles para me entender e eu para entend&ecirc;-los. Mas com o tempo &#8211; que nem foi tanto assim &#8211; eles perceberam que n&atilde;o tinha como me mudar, e que eu era feliz desse jeito, e passaram a me aceitar e querer minha felicidade.<\/div>\n<div style=\"text-align: justify\">O meu pai &eacute; um pouquinho mais cabe&ccedil;a dura, mas ele me respeita e respeita a minha namorada, ela vem aqui em casa e a presen&ccedil;a dela j&aacute; &eacute; uma coisa normal, quando ela n&atilde;o os vem at&eacute; estranham e perguntam&rdquo;, Talita revela.<\/div>\n<div style=\"text-align: justify\">&nbsp;<\/div>\n<div style=\"text-align: justify\"><strong>Ele com ele<\/strong> &#8211; Ralf, 23 anos, namora o Ricardo &agrave; dist&acirc;ncia h&aacute; 3 anos, por&eacute;m se conhecem atrav&eacute;s da internet h&aacute; cerca de 7 anos. A hist&oacute;ria dos dois &eacute; cosmopolita, s&atilde;o idas e vindas entre Alemanha, R&uacute;ssia, Inglaterra e Irlanda, basicamente.&nbsp;<\/div>\n<div style=\"text-align: justify\">&nbsp;<\/div>\n<table cellspacing=\"0\" cellpadding=\"0\" border=\"0\" align=\"right\" width=\"200\" style=\"margin: 0 3px\">\n<tbody>\n<tr>\n<td style=\"text-align: right\">Foto: Arquivo pessoal<\/td>\n<\/tr>\n<tr>\n<td bgcolor=\"#f4f4f2\"><img decoding=\"async\" height=\"225\" width=\"300\" alt=\"\" src=\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/Ralf%20e%20Rico.jpg\" \/><\/td>\n<\/tr>\n<tr>\n<td bgcolor=\"#f4f4f2\" style=\"padding-top: 3px;padding-right: 1px;padding-bottom: 3px;padding-left: 1px;font-size: 11px;text-align: center\">Ralf e Rico em algum lugar da Europa<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div style=\"text-align: justify\">Tudo come&ccedil;ou quando Ralf decidiu fazer um interc&acirc;mbio para a Alemanha e entrou em contato com alguns estudantes brasileiros que estavam na por l&aacute; para trocar experi&ecirc;ncias. Foi onde ele teve o primeiro contato com o Ricardo e come&ccedil;aram a trocar mensagens atrav&eacute;s da internet. At&eacute; ent&atilde;o ningu&eacute;m sabia de ningu&eacute;m, eram s&oacute; amigos. Em 2004 o Ricardo voltou para o Brasil e o Ralf foi para a R&uacute;ssia, e os dois mantendo sempre contato. Em 2005 Ralf voltou da R&uacute;ssia, mas embarcou de novo para a Europa, dessa vez para a Inglaterra, e a internet sempre foi uma ferramenta de aproxima&ccedil;&atilde;o e comunica&ccedil;&atilde;o dos dois, mas somente depois de um ano em Londres foi que aconteceu a primeira grande aproxima&ccedil;&atilde;o, Ralf voltou para o Brasil e foi em um elevador de um hotel de Foz do Igua&ccedil;u que aconteceu o primeiro beijo, em uma viagem de estudos que Ricardo estava realizado na cidade. A partir da&iacute; eles iniciaram algo com mais sentimento, mesmo com um pouco de medo em se namorar a dist&acirc;ncia os dois investiram, Ralf em Foz do Igua&ccedil;u e o Ricardo em Curitiba. &ldquo;Mas percebemos que realmente nos gost&aacute;vamos e existia um sentimento de amor muito forte. Resolvemos ent&atilde;o iniciar um namoro a dist&acirc;ncia. Foram in&uacute;meras idas e vindas, todos os meses era Curitiba-Foz-Foz-Curitiba, que eu perdi a conta&rdquo;.&nbsp;<\/div>\n<div style=\"text-align: justify\">&nbsp;<\/div>\n<div style=\"text-align: justify\">O namoro &agrave; dist&acirc;ncia dos dois n&atilde;o foi prejudicial para nenhum lado, a confian&ccedil;a que eles t&ecirc;m um no outro &eacute; grande e sem crises de ci&uacute;me conseguem com a ajuda da internet sempre estar em contato. &ldquo;Acho que gostamos tanto de namorar a dist&acirc;ncia que ele foi estudar agora na Europa&rdquo;, revela. E os planos s&atilde;o grandes, os dois querem antes de completados cinco anos de namoro estar morando juntos. &ldquo;Alguma parte vai ter que ceder para que isso acontecer&rdquo;, diz.<\/div>\n<div style=\"text-align: justify\">&nbsp;<\/div>\n<div style=\"text-align: justify\">&ldquo;O namoro &agrave; dist&acirc;ncia envolve um aprendizado cont&iacute;nuo, exige muita confian&ccedil;a e principalmente paci&ecirc;ncia, &eacute; uma longa estrada que pode ter um final ou at&eacute; mesmo um recome&ccedil;o de outra etapa do namoro, partindo do princ&iacute;pio que as pessoas um dias t&ecirc;m o objetivo de ficar juntas, ou seja, morando juntas&rdquo;, explica.<\/div>\n<div style=\"text-align: justify\">&nbsp;<\/div>\n<div style=\"text-align: justify\">Ralf ainda revela que nunca escondeu nada de ningu&eacute;m, nem no ambiente fam&iacute;liar, acad&ecirc;mico ou profissional. Ele sempre foi aberto e acha que isso proporciona um respeito maior por parte das pessoas. &ldquo;Elas percebem que por voc&ecirc; ser gay, voc&ecirc; n&atilde;o &eacute; melhor ou maior que ningu&eacute;m, e sim um ser humano normal, que ri e chora como qualquer outra pessoa&rdquo; finaliza Ralf.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &quot;Quem n&atilde;o te aceita como voc&ecirc; &eacute; n&atilde;o merece sua considera&ccedil;&atilde;o&quot;, revela a personagem Falar de namoro e n&atilde;o citar a rela&ccedil;&atilde;o homossexual no momento hist&oacute;rico que estamos vivendo &eacute; desprezar boa parte da sociedade. Por isso no Especial Dia do Namoro o portal Clickfoz preparou uma mat&eacute;ria sobre o namoro entre pessoas do [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-14491","post","type-post","status-publish","format-standard","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Namoro entre o mesmo sexo - Clickfoz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/box5640.temp.domains\/~clickfoz\/namoro-entre-o-mesmo-sexo-5775\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Namoro entre o mesmo sexo - Clickfoz\" \/>\n<meta property=\"og:description\" content=\"&nbsp; &quot;Quem n&atilde;o te aceita como voc&ecirc; &eacute; n&atilde;o merece sua considera&ccedil;&atilde;o&quot;, revela a personagem Falar de namoro e n&atilde;o citar a rela&ccedil;&atilde;o homossexual no momento hist&oacute;rico que estamos vivendo &eacute; desprezar boa parte da sociedade. Por isso no Especial Dia do Namoro o portal Clickfoz preparou uma mat&eacute;ria sobre o namoro entre pessoas do [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/box5640.temp.domains\/~clickfoz\/namoro-entre-o-mesmo-sexo-5775\/\" \/>\n<meta property=\"og:site_name\" content=\"Clickfoz\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/clickfoz\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/garon.piceli\" \/>\n<meta property=\"article:published_time\" content=\"2010-06-12T10:23:51+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/orgulho%20gay.png\" \/>\n<meta name=\"author\" content=\"Garon Piceli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@garonpiceli\" \/>\n<meta name=\"twitter:site\" content=\"@clickfoz\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Garon Piceli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/namoro-entre-o-mesmo-sexo-5775\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/namoro-entre-o-mesmo-sexo-5775\/\"},\"author\":{\"name\":\"Garon Piceli\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/person\/1c68351359e4744c29866b9bc7a0bfff\"},\"headline\":\"Namoro entre o mesmo sexo\",\"datePublished\":\"2010-06-12T10:23:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/namoro-entre-o-mesmo-sexo-5775\/\"},\"wordCount\":1320,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\"},\"image\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/namoro-entre-o-mesmo-sexo-5775\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/orgulho%20gay.png\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\/\/box5640.temp.domains\/~clickfoz\/namoro-entre-o-mesmo-sexo-5775\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/namoro-entre-o-mesmo-sexo-5775\/\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/namoro-entre-o-mesmo-sexo-5775\/\",\"name\":\"Namoro entre o mesmo sexo - Clickfoz\",\"isPartOf\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/namoro-entre-o-mesmo-sexo-5775\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/namoro-entre-o-mesmo-sexo-5775\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/orgulho%20gay.png\",\"datePublished\":\"2010-06-12T10:23:51+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/namoro-entre-o-mesmo-sexo-5775\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/box5640.temp.domains\/~clickfoz\/namoro-entre-o-mesmo-sexo-5775\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/namoro-entre-o-mesmo-sexo-5775\/#primaryimage\",\"url\":\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/orgulho%20gay.png\",\"contentUrl\":\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/orgulho%20gay.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/namoro-entre-o-mesmo-sexo-5775\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/box5640.temp.domains\/~clickfoz\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Namoro entre o mesmo sexo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#website\",\"url\":\"https:\/\/box5640.temp.domains\/~clickfoz\/\",\"name\":\"Click Foz do Igua\u00e7u\",\"description\":\"O portal de not\u00edcias de Foz do Igua\u00e7u\",\"publisher\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/box5640.temp.domains\/~clickfoz\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\",\"name\":\"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i\",\"url\":\"https:\/\/box5640.temp.domains\/~clickfoz\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png\",\"contentUrl\":\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png\",\"width\":190,\"height\":65,\"caption\":\"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i\"},\"image\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/clickfoz\",\"https:\/\/x.com\/clickfoz\",\"https:\/\/www.instagram.com\/clickfoz\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/person\/1c68351359e4744c29866b9bc7a0bfff\",\"name\":\"Garon Piceli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4185832e3322de80868dff0f56e6c20788e54c0fab66a0314b34288fcc3a3fad?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4185832e3322de80868dff0f56e6c20788e54c0fab66a0314b34288fcc3a3fad?s=96&d=mm&r=g\",\"caption\":\"Garon Piceli\"},\"sameAs\":[\"https:\/\/www.facebook.com\/garon.piceli\",\"https:\/\/x.com\/garonpiceli\"],\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/author\/garon\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Namoro entre o mesmo sexo - Clickfoz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/box5640.temp.domains\/~clickfoz\/namoro-entre-o-mesmo-sexo-5775\/","og_locale":"pt_BR","og_type":"article","og_title":"Namoro entre o mesmo sexo - Clickfoz","og_description":"&nbsp; &quot;Quem n&atilde;o te aceita como voc&ecirc; &eacute; n&atilde;o merece sua considera&ccedil;&atilde;o&quot;, revela a personagem Falar de namoro e n&atilde;o citar a rela&ccedil;&atilde;o homossexual no momento hist&oacute;rico que estamos vivendo &eacute; desprezar boa parte da sociedade. Por isso no Especial Dia do Namoro o portal Clickfoz preparou uma mat&eacute;ria sobre o namoro entre pessoas do [&hellip;]","og_url":"http:\/\/box5640.temp.domains\/~clickfoz\/namoro-entre-o-mesmo-sexo-5775\/","og_site_name":"Clickfoz","article_publisher":"https:\/\/facebook.com\/clickfoz","article_author":"https:\/\/www.facebook.com\/garon.piceli","article_published_time":"2010-06-12T10:23:51+00:00","og_image":[{"url":"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/orgulho%20gay.png","type":"","width":"","height":""}],"author":"Garon Piceli","twitter_card":"summary_large_image","twitter_creator":"@garonpiceli","twitter_site":"@clickfoz","twitter_misc":{"Escrito por":"Garon Piceli","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/namoro-entre-o-mesmo-sexo-5775\/#article","isPartOf":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/namoro-entre-o-mesmo-sexo-5775\/"},"author":{"name":"Garon Piceli","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/person\/1c68351359e4744c29866b9bc7a0bfff"},"headline":"Namoro entre o mesmo sexo","datePublished":"2010-06-12T10:23:51+00:00","mainEntityOfPage":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/namoro-entre-o-mesmo-sexo-5775\/"},"wordCount":1320,"commentCount":0,"publisher":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization"},"image":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/namoro-entre-o-mesmo-sexo-5775\/#primaryimage"},"thumbnailUrl":"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/orgulho%20gay.png","inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/box5640.temp.domains\/~clickfoz\/namoro-entre-o-mesmo-sexo-5775\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/namoro-entre-o-mesmo-sexo-5775\/","url":"http:\/\/box5640.temp.domains\/~clickfoz\/namoro-entre-o-mesmo-sexo-5775\/","name":"Namoro entre o mesmo sexo - Clickfoz","isPartOf":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#website"},"primaryImageOfPage":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/namoro-entre-o-mesmo-sexo-5775\/#primaryimage"},"image":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/namoro-entre-o-mesmo-sexo-5775\/#primaryimage"},"thumbnailUrl":"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/orgulho%20gay.png","datePublished":"2010-06-12T10:23:51+00:00","breadcrumb":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/namoro-entre-o-mesmo-sexo-5775\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/box5640.temp.domains\/~clickfoz\/namoro-entre-o-mesmo-sexo-5775\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/namoro-entre-o-mesmo-sexo-5775\/#primaryimage","url":"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/orgulho%20gay.png","contentUrl":"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/orgulho%20gay.png"},{"@type":"BreadcrumbList","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/namoro-entre-o-mesmo-sexo-5775\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/box5640.temp.domains\/~clickfoz\/"},{"@type":"ListItem","position":2,"name":"Namoro entre o mesmo sexo"}]},{"@type":"WebSite","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#website","url":"https:\/\/box5640.temp.domains\/~clickfoz\/","name":"Click Foz do Igua\u00e7u","description":"O portal de not\u00edcias de Foz do Igua\u00e7u","publisher":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/box5640.temp.domains\/~clickfoz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization","name":"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i","url":"https:\/\/box5640.temp.domains\/~clickfoz\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/","url":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png","contentUrl":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png","width":190,"height":65,"caption":"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i"},"image":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/clickfoz","https:\/\/x.com\/clickfoz","https:\/\/www.instagram.com\/clickfoz"]},{"@type":"Person","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/person\/1c68351359e4744c29866b9bc7a0bfff","name":"Garon Piceli","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/4185832e3322de80868dff0f56e6c20788e54c0fab66a0314b34288fcc3a3fad?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4185832e3322de80868dff0f56e6c20788e54c0fab66a0314b34288fcc3a3fad?s=96&d=mm&r=g","caption":"Garon Piceli"},"sameAs":["https:\/\/www.facebook.com\/garon.piceli","https:\/\/x.com\/garonpiceli"],"url":"http:\/\/box5640.temp.domains\/~clickfoz\/author\/garon\/"}]}},"_links":{"self":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts\/14491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/comments?post=14491"}],"version-history":[{"count":0,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts\/14491\/revisions"}],"wp:attachment":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/media?parent=14491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/categories?post=14491"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/tags?post=14491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}