{"id":14429,"date":"2010-06-17T11:16:52","date_gmt":"2010-06-17T11:16:52","guid":{"rendered":"http:\/\/localhost:82\/wordpress\/2010\/06\/17\/foz-futsal-goleia-o-marreco-por-8-a-1-e-se-mantem-entre-os-12-primeiros-do-paranaense-5837\/"},"modified":"2010-06-17T11:16:52","modified_gmt":"2010-06-17T11:16:52","slug":"foz-futsal-goleia-o-marreco-por-8-a-1-e-se-mantem-entre-os-12-primeiros-do-paranaense-5837","status":"publish","type":"post","link":"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-goleia-o-marreco-por-8-a-1-e-se-mantem-entre-os-12-primeiros-do-paranaense-5837\/","title":{"rendered":"Foz Futsal goleia o Marreco por 8 a 1 e se mant&eacute;m entre os 12 primeiros do Paranaense"},"content":{"rendered":"<p style=\"text-align: justify\">Com tr&ecirc;s gols de Marcelinho, um de Renatinho Paulista, um de Ma&ccedil;arico, um de Giba e um de Carl&atilde;o, o Foz Futsal goleou o Marreco Futsal, equipe que ocupa a terceira coloca&ccedil;&atilde;o no campeonato e lutava pela lideran&ccedil;a da Chave Ouro do Paranaense.<\/p>\n<p style=\"text-align: justify\">&ldquo;Encaramos o jogo com muita seriedade e por isso constru&iacute;mos o placar el&aacute;stico&quot;, disse o artilheiro Marcelinho ao rep&oacute;rter Sidnei Buzanelo, da R&aacute;dio Cultura AM.<\/p>\n<p style=\"text-align: justify\">Com a vit&oacute;ria, o Foz Futsal se mant&eacute;m na 12&ordf; coloca&ccedil;&atilde;o do Estadual e d&aacute; um passo importante na campanha rumo &agrave; classifica&ccedil;&atilde;o para a pr&oacute;xima fase.<br \/>\n&ldquo;Ainda temos mais duas partidas importantes em casa, mas acreditamos que demos um importante passo para a nossa classifica&ccedil;&atilde;o&rdquo;, destacou Ed Carlos, t&eacute;cnico do Foz Futsal.<\/p>\n<p style=\"text-align: justify\">A torcida igua&ccedil;uense tamb&eacute;m vem marcando boa presen&ccedil;a nas partidas do tricampe&atilde;o paranaense tanto no estadual, quanto na Liga Nacional.<\/p>\n<p style=\"text-align: justify\">&ldquo;O Foz est&aacute; com tudo agora, for&ccedil;a m&aacute;xima. D&aacute; gosto de ver a tamanha mudan&ccedil;a&rdquo;, comentou o torcedor William Torres, na comunidade do Foz Futsal no site de relacionamentos, Orkut.&nbsp; <\/p>\n<p style=\"text-align: justify\">O pr&oacute;ximo desafio da equipe igua&ccedil;uense ser&aacute; contra o Cascavel, na ter&ccedil;a-feira (22), &agrave;s 20h30, no Gin&aacute;sio Costa Cavalcanti, em Foz do Igua&ccedil;u. <\/p>\n<p style=\"text-align: justify\">Os ingressos para a partida custam R$ 5,00 e podem ser adquiridos de forma antecipada nas Lojas Manica, Estacionamento Bismillah, Masterfarma &#8211; Evolu&ccedil;&atilde;o, Mundo do Futebol e Cataratas Materiais de Constru&ccedil;&atilde;o. A bilheteria do Gin&aacute;sio Costa Cavalcanti estar&aacute; aberta a partir das 19h00.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com tr&ecirc;s gols de Marcelinho, um de Renatinho Paulista, um de Ma&ccedil;arico, um de Giba e um de Carl&atilde;o, o Foz Futsal goleou o Marreco Futsal, equipe que ocupa a terceira coloca&ccedil;&atilde;o no campeonato e lutava pela lideran&ccedil;a da Chave Ouro do Paranaense. &ldquo;Encaramos o jogo com muita seriedade e por isso constru&iacute;mos o placar [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-14429","post","type-post","status-publish","format-standard","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Foz Futsal goleia o Marreco por 8 a 1 e se mant&eacute;m entre os 12 primeiros do Paranaense - Clickfoz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-goleia-o-marreco-por-8-a-1-e-se-mantem-entre-os-12-primeiros-do-paranaense-5837\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Foz Futsal goleia o Marreco por 8 a 1 e se mant&eacute;m entre os 12 primeiros do Paranaense - Clickfoz\" \/>\n<meta property=\"og:description\" content=\"Com tr&ecirc;s gols de Marcelinho, um de Renatinho Paulista, um de Ma&ccedil;arico, um de Giba e um de Carl&atilde;o, o Foz Futsal goleou o Marreco Futsal, equipe que ocupa a terceira coloca&ccedil;&atilde;o no campeonato e lutava pela lideran&ccedil;a da Chave Ouro do Paranaense. &ldquo;Encaramos o jogo com muita seriedade e por isso constru&iacute;mos o placar [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-goleia-o-marreco-por-8-a-1-e-se-mantem-entre-os-12-primeiros-do-paranaense-5837\/\" \/>\n<meta property=\"og:site_name\" content=\"Clickfoz\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/clickfoz\" \/>\n<meta property=\"article:published_time\" content=\"2010-06-17T11:16:52+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2023\/11\/logo-clickfoz.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@clickfoz\" \/>\n<meta name=\"twitter:site\" content=\"@clickfoz\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-goleia-o-marreco-por-8-a-1-e-se-mantem-entre-os-12-primeiros-do-paranaense-5837\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-goleia-o-marreco-por-8-a-1-e-se-mantem-entre-os-12-primeiros-do-paranaense-5837\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Foz Futsal goleia o Marreco por 8 a 1 e se mant&eacute;m entre os 12 primeiros do Paranaense\",\"datePublished\":\"2010-06-17T11:16:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-goleia-o-marreco-por-8-a-1-e-se-mantem-entre-os-12-primeiros-do-paranaense-5837\/\"},\"wordCount\":333,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-goleia-o-marreco-por-8-a-1-e-se-mantem-entre-os-12-primeiros-do-paranaense-5837\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-goleia-o-marreco-por-8-a-1-e-se-mantem-entre-os-12-primeiros-do-paranaense-5837\/\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-goleia-o-marreco-por-8-a-1-e-se-mantem-entre-os-12-primeiros-do-paranaense-5837\/\",\"name\":\"Foz Futsal goleia o Marreco por 8 a 1 e se mant&eacute;m entre os 12 primeiros do Paranaense - Clickfoz\",\"isPartOf\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#website\"},\"datePublished\":\"2010-06-17T11:16:52+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-goleia-o-marreco-por-8-a-1-e-se-mantem-entre-os-12-primeiros-do-paranaense-5837\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-goleia-o-marreco-por-8-a-1-e-se-mantem-entre-os-12-primeiros-do-paranaense-5837\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-goleia-o-marreco-por-8-a-1-e-se-mantem-entre-os-12-primeiros-do-paranaense-5837\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/box5640.temp.domains\/~clickfoz\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Foz Futsal goleia o Marreco por 8 a 1 e se mant&eacute;m entre os 12 primeiros do Paranaense\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#website\",\"url\":\"https:\/\/box5640.temp.domains\/~clickfoz\/\",\"name\":\"Click Foz do Igua\u00e7u\",\"description\":\"O portal de not\u00edcias de Foz do Igua\u00e7u\",\"publisher\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/box5640.temp.domains\/~clickfoz\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\",\"name\":\"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i\",\"url\":\"https:\/\/box5640.temp.domains\/~clickfoz\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png\",\"contentUrl\":\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png\",\"width\":190,\"height\":65,\"caption\":\"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i\"},\"image\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/clickfoz\",\"https:\/\/x.com\/clickfoz\",\"https:\/\/www.instagram.com\/clickfoz\"]},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Foz Futsal goleia o Marreco por 8 a 1 e se mant&eacute;m entre os 12 primeiros do Paranaense - Clickfoz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-goleia-o-marreco-por-8-a-1-e-se-mantem-entre-os-12-primeiros-do-paranaense-5837\/","og_locale":"pt_BR","og_type":"article","og_title":"Foz Futsal goleia o Marreco por 8 a 1 e se mant&eacute;m entre os 12 primeiros do Paranaense - Clickfoz","og_description":"Com tr&ecirc;s gols de Marcelinho, um de Renatinho Paulista, um de Ma&ccedil;arico, um de Giba e um de Carl&atilde;o, o Foz Futsal goleou o Marreco Futsal, equipe que ocupa a terceira coloca&ccedil;&atilde;o no campeonato e lutava pela lideran&ccedil;a da Chave Ouro do Paranaense. &ldquo;Encaramos o jogo com muita seriedade e por isso constru&iacute;mos o placar [&hellip;]","og_url":"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-goleia-o-marreco-por-8-a-1-e-se-mantem-entre-os-12-primeiros-do-paranaense-5837\/","og_site_name":"Clickfoz","article_publisher":"https:\/\/facebook.com\/clickfoz","article_published_time":"2010-06-17T11:16:52+00:00","og_image":[{"width":1200,"height":675,"url":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2023\/11\/logo-clickfoz.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_creator":"@clickfoz","twitter_site":"@clickfoz","twitter_misc":{"Escrito por":"","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-goleia-o-marreco-por-8-a-1-e-se-mantem-entre-os-12-primeiros-do-paranaense-5837\/#article","isPartOf":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-goleia-o-marreco-por-8-a-1-e-se-mantem-entre-os-12-primeiros-do-paranaense-5837\/"},"author":{"name":"","@id":""},"headline":"Foz Futsal goleia o Marreco por 8 a 1 e se mant&eacute;m entre os 12 primeiros do Paranaense","datePublished":"2010-06-17T11:16:52+00:00","mainEntityOfPage":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-goleia-o-marreco-por-8-a-1-e-se-mantem-entre-os-12-primeiros-do-paranaense-5837\/"},"wordCount":333,"commentCount":0,"publisher":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization"},"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-goleia-o-marreco-por-8-a-1-e-se-mantem-entre-os-12-primeiros-do-paranaense-5837\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-goleia-o-marreco-por-8-a-1-e-se-mantem-entre-os-12-primeiros-do-paranaense-5837\/","url":"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-goleia-o-marreco-por-8-a-1-e-se-mantem-entre-os-12-primeiros-do-paranaense-5837\/","name":"Foz Futsal goleia o Marreco por 8 a 1 e se mant&eacute;m entre os 12 primeiros do Paranaense - Clickfoz","isPartOf":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#website"},"datePublished":"2010-06-17T11:16:52+00:00","breadcrumb":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-goleia-o-marreco-por-8-a-1-e-se-mantem-entre-os-12-primeiros-do-paranaense-5837\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-goleia-o-marreco-por-8-a-1-e-se-mantem-entre-os-12-primeiros-do-paranaense-5837\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-goleia-o-marreco-por-8-a-1-e-se-mantem-entre-os-12-primeiros-do-paranaense-5837\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/box5640.temp.domains\/~clickfoz\/"},{"@type":"ListItem","position":2,"name":"Foz Futsal goleia o Marreco por 8 a 1 e se mant&eacute;m entre os 12 primeiros do Paranaense"}]},{"@type":"WebSite","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#website","url":"https:\/\/box5640.temp.domains\/~clickfoz\/","name":"Click Foz do Igua\u00e7u","description":"O portal de not\u00edcias de Foz do Igua\u00e7u","publisher":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/box5640.temp.domains\/~clickfoz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization","name":"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i","url":"https:\/\/box5640.temp.domains\/~clickfoz\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/","url":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png","contentUrl":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png","width":190,"height":65,"caption":"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i"},"image":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/clickfoz","https:\/\/x.com\/clickfoz","https:\/\/www.instagram.com\/clickfoz"]},{"@type":"Person","@id":"","url":"http:\/\/box5640.temp.domains\/~clickfoz\/author\/"}]}},"_links":{"self":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts\/14429","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/comments?post=14429"}],"version-history":[{"count":0,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts\/14429\/revisions"}],"wp:attachment":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/media?parent=14429"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/categories?post=14429"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/tags?post=14429"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}