{"id":14426,"date":"2010-06-17T13:29:41","date_gmt":"2010-06-17T13:29:41","guid":{"rendered":"http:\/\/localhost:82\/wordpress\/2010\/06\/17\/oeste-e-sudoeste-do-parana-recebem-mais-r-267-milhoes-para-obras-de-saneamento-basico-5840-3\/"},"modified":"2010-06-17T13:29:41","modified_gmt":"2010-06-17T13:29:41","slug":"oeste-e-sudoeste-do-parana-recebem-mais-r-267-milhoes-para-obras-de-saneamento-basico-5840-3","status":"publish","type":"post","link":"http:\/\/box5640.temp.domains\/~clickfoz\/oeste-e-sudoeste-do-parana-recebem-mais-r-267-milhoes-para-obras-de-saneamento-basico-5840-3\/","title":{"rendered":"Oeste e Sudoeste do Paran&aacute; recebem mais R$ 26,7 milh&otilde;es para obras de saneamento b&aacute;sico"},"content":{"rendered":"<p style=\"text-align: justify\">Na sexta-feira (18) o governador do Paran&aacute;, Orlando Pessuti, e o presidente da Sanepar, St&ecirc;nio Jacob, assinam sete ordens de servi&ccedil;os e entregam 10 obras de saneamento b&aacute;sico para 13 munic&iacute;pios das regi&otilde;es Oeste e Sudoeste do Estado. A cerim&ocirc;nia ser&aacute; realizada nas depend&ecirc;ncias da Funda&ccedil;&atilde;o Assis Gurgacz (FAG), em Cascavel, durante a Escola de Governo, a partir das 9h.<\/p>\n<p>Do total dos recursos, R$ 23,3 milh&otilde;es est&atilde;o destinados &agrave; amplia&ccedil;&atilde;o dos sistemas de esgoto sanit&aacute;rio de Cascavel, Ampere, Palmas, Toledo, Foz do Igua&ccedil;u, Francisco Beltr&atilde;o, Santa Terezinha de Itaipu, Santo Antonio do Sudoeste e S&atilde;o Miguel do Igua&ccedil;u. Os demais s&atilde;o investimentos para amplia&ccedil;&atilde;o dos sistemas de abastecimento de &aacute;gua de Cascavel, Francisco Beltr&atilde;o, Guarania&ccedil;u, Cruzeiro do Igua&ccedil;u e Lindoeste. <\/p>\n<p>As ordens de servi&ccedil;os que ser&atilde;o assinadas v&atilde;o beneficiar mais de 513 mil moradores das &aacute;reas urbanas e gerar cerca de 1.540 novos postos de trabalho nos munic&iacute;pios contemplados. J&aacute;, os investimentos conclu&iacute;dos estenderam os servi&ccedil;os de &aacute;gua e esgoto para 868 mil pessoas nas duas regi&otilde;es.<\/p>\n<p>Minha Casa, Minha Vida &ndash; Um dos destaques &eacute; a assinatura do conv&ecirc;nio entre o Governo do Estado, a Sanepar e a Prefeitura de Cascavel, que tem por finalidade o atendimento do Programa Minha Casa, Minha Vida. A parceria vai atender as casas que ser&atilde;o constru&iacute;das no Parque dos Ip&ecirc;s, Jardim da Amizade, Jardim Veneza, Jardim Esmeralda e Jardim Cidade Verde.<\/p>\n<p>\n<strong>Servi&ccedil;o:<\/strong> <br \/>\nEntrega de obras e assinatura de ordens de servi&ccedil;os para amplia&ccedil;&atilde;o de sistemas de abastecimento e de esgotamento sanit&aacute;rio<br \/>\n<strong>Data:<\/strong> 18 de junho de 2010.<br \/>\n<strong>Hor&aacute;rio:<\/strong> 9 horas<br \/>\n<strong>Local: <\/strong>Audit&oacute;rio da FAG &ndash; Avenida das Torres, 500&nbsp; &#8211; Cascavel<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na sexta-feira (18) o governador do Paran&aacute;, Orlando Pessuti, e o presidente da Sanepar, St&ecirc;nio Jacob, assinam sete ordens de servi&ccedil;os e entregam 10 obras de saneamento b&aacute;sico para 13 munic&iacute;pios das regi&otilde;es Oeste e Sudoeste do Estado. A cerim&ocirc;nia ser&aacute; realizada nas depend&ecirc;ncias da Funda&ccedil;&atilde;o Assis Gurgacz (FAG), em Cascavel, durante a Escola de [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-14426","post","type-post","status-publish","format-standard","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Oeste e Sudoeste do Paran&aacute; recebem mais R$ 26,7 milh&otilde;es para obras de saneamento b&aacute;sico - Clickfoz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/box5640.temp.domains\/~clickfoz\/oeste-e-sudoeste-do-parana-recebem-mais-r-267-milhoes-para-obras-de-saneamento-basico-5840-3\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oeste e Sudoeste do Paran&aacute; recebem mais R$ 26,7 milh&otilde;es para obras de saneamento b&aacute;sico - Clickfoz\" \/>\n<meta property=\"og:description\" content=\"Na sexta-feira (18) o governador do Paran&aacute;, Orlando Pessuti, e o presidente da Sanepar, St&ecirc;nio Jacob, assinam sete ordens de servi&ccedil;os e entregam 10 obras de saneamento b&aacute;sico para 13 munic&iacute;pios das regi&otilde;es Oeste e Sudoeste do Estado. A cerim&ocirc;nia ser&aacute; realizada nas depend&ecirc;ncias da Funda&ccedil;&atilde;o Assis Gurgacz (FAG), em Cascavel, durante a Escola de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/box5640.temp.domains\/~clickfoz\/oeste-e-sudoeste-do-parana-recebem-mais-r-267-milhoes-para-obras-de-saneamento-basico-5840-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Clickfoz\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/clickfoz\" \/>\n<meta property=\"article:published_time\" content=\"2010-06-17T13:29:41+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2023\/11\/logo-clickfoz.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@clickfoz\" \/>\n<meta name=\"twitter:site\" content=\"@clickfoz\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/oeste-e-sudoeste-do-parana-recebem-mais-r-267-milhoes-para-obras-de-saneamento-basico-5840-3\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/oeste-e-sudoeste-do-parana-recebem-mais-r-267-milhoes-para-obras-de-saneamento-basico-5840-3\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Oeste e Sudoeste do Paran&aacute; recebem mais R$ 26,7 milh&otilde;es para obras de saneamento b&aacute;sico\",\"datePublished\":\"2010-06-17T13:29:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/oeste-e-sudoeste-do-parana-recebem-mais-r-267-milhoes-para-obras-de-saneamento-basico-5840-3\/\"},\"wordCount\":364,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\/\/box5640.temp.domains\/~clickfoz\/oeste-e-sudoeste-do-parana-recebem-mais-r-267-milhoes-para-obras-de-saneamento-basico-5840-3\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/oeste-e-sudoeste-do-parana-recebem-mais-r-267-milhoes-para-obras-de-saneamento-basico-5840-3\/\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/oeste-e-sudoeste-do-parana-recebem-mais-r-267-milhoes-para-obras-de-saneamento-basico-5840-3\/\",\"name\":\"Oeste e Sudoeste do Paran&aacute; recebem mais R$ 26,7 milh&otilde;es para obras de saneamento b&aacute;sico - Clickfoz\",\"isPartOf\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#website\"},\"datePublished\":\"2010-06-17T13:29:41+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/oeste-e-sudoeste-do-parana-recebem-mais-r-267-milhoes-para-obras-de-saneamento-basico-5840-3\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/box5640.temp.domains\/~clickfoz\/oeste-e-sudoeste-do-parana-recebem-mais-r-267-milhoes-para-obras-de-saneamento-basico-5840-3\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/oeste-e-sudoeste-do-parana-recebem-mais-r-267-milhoes-para-obras-de-saneamento-basico-5840-3\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/box5640.temp.domains\/~clickfoz\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Oeste e Sudoeste do Paran&aacute; recebem mais R$ 26,7 milh&otilde;es para obras de saneamento b&aacute;sico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#website\",\"url\":\"https:\/\/box5640.temp.domains\/~clickfoz\/\",\"name\":\"Click Foz do Igua\u00e7u\",\"description\":\"O portal de not\u00edcias de Foz do Igua\u00e7u\",\"publisher\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/box5640.temp.domains\/~clickfoz\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\",\"name\":\"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i\",\"url\":\"https:\/\/box5640.temp.domains\/~clickfoz\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png\",\"contentUrl\":\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png\",\"width\":190,\"height\":65,\"caption\":\"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i\"},\"image\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/clickfoz\",\"https:\/\/x.com\/clickfoz\",\"https:\/\/www.instagram.com\/clickfoz\"]},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Oeste e Sudoeste do Paran&aacute; recebem mais R$ 26,7 milh&otilde;es para obras de saneamento b&aacute;sico - Clickfoz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/box5640.temp.domains\/~clickfoz\/oeste-e-sudoeste-do-parana-recebem-mais-r-267-milhoes-para-obras-de-saneamento-basico-5840-3\/","og_locale":"pt_BR","og_type":"article","og_title":"Oeste e Sudoeste do Paran&aacute; recebem mais R$ 26,7 milh&otilde;es para obras de saneamento b&aacute;sico - Clickfoz","og_description":"Na sexta-feira (18) o governador do Paran&aacute;, Orlando Pessuti, e o presidente da Sanepar, St&ecirc;nio Jacob, assinam sete ordens de servi&ccedil;os e entregam 10 obras de saneamento b&aacute;sico para 13 munic&iacute;pios das regi&otilde;es Oeste e Sudoeste do Estado. A cerim&ocirc;nia ser&aacute; realizada nas depend&ecirc;ncias da Funda&ccedil;&atilde;o Assis Gurgacz (FAG), em Cascavel, durante a Escola de [&hellip;]","og_url":"http:\/\/box5640.temp.domains\/~clickfoz\/oeste-e-sudoeste-do-parana-recebem-mais-r-267-milhoes-para-obras-de-saneamento-basico-5840-3\/","og_site_name":"Clickfoz","article_publisher":"https:\/\/facebook.com\/clickfoz","article_published_time":"2010-06-17T13:29:41+00:00","og_image":[{"width":1200,"height":675,"url":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2023\/11\/logo-clickfoz.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_creator":"@clickfoz","twitter_site":"@clickfoz","twitter_misc":{"Escrito por":"","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/oeste-e-sudoeste-do-parana-recebem-mais-r-267-milhoes-para-obras-de-saneamento-basico-5840-3\/#article","isPartOf":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/oeste-e-sudoeste-do-parana-recebem-mais-r-267-milhoes-para-obras-de-saneamento-basico-5840-3\/"},"author":{"name":"","@id":""},"headline":"Oeste e Sudoeste do Paran&aacute; recebem mais R$ 26,7 milh&otilde;es para obras de saneamento b&aacute;sico","datePublished":"2010-06-17T13:29:41+00:00","mainEntityOfPage":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/oeste-e-sudoeste-do-parana-recebem-mais-r-267-milhoes-para-obras-de-saneamento-basico-5840-3\/"},"wordCount":364,"commentCount":0,"publisher":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization"},"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/box5640.temp.domains\/~clickfoz\/oeste-e-sudoeste-do-parana-recebem-mais-r-267-milhoes-para-obras-de-saneamento-basico-5840-3\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/oeste-e-sudoeste-do-parana-recebem-mais-r-267-milhoes-para-obras-de-saneamento-basico-5840-3\/","url":"http:\/\/box5640.temp.domains\/~clickfoz\/oeste-e-sudoeste-do-parana-recebem-mais-r-267-milhoes-para-obras-de-saneamento-basico-5840-3\/","name":"Oeste e Sudoeste do Paran&aacute; recebem mais R$ 26,7 milh&otilde;es para obras de saneamento b&aacute;sico - Clickfoz","isPartOf":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#website"},"datePublished":"2010-06-17T13:29:41+00:00","breadcrumb":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/oeste-e-sudoeste-do-parana-recebem-mais-r-267-milhoes-para-obras-de-saneamento-basico-5840-3\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/box5640.temp.domains\/~clickfoz\/oeste-e-sudoeste-do-parana-recebem-mais-r-267-milhoes-para-obras-de-saneamento-basico-5840-3\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/oeste-e-sudoeste-do-parana-recebem-mais-r-267-milhoes-para-obras-de-saneamento-basico-5840-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/box5640.temp.domains\/~clickfoz\/"},{"@type":"ListItem","position":2,"name":"Oeste e Sudoeste do Paran&aacute; recebem mais R$ 26,7 milh&otilde;es para obras de saneamento b&aacute;sico"}]},{"@type":"WebSite","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#website","url":"https:\/\/box5640.temp.domains\/~clickfoz\/","name":"Click Foz do Igua\u00e7u","description":"O portal de not\u00edcias de Foz do Igua\u00e7u","publisher":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/box5640.temp.domains\/~clickfoz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization","name":"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i","url":"https:\/\/box5640.temp.domains\/~clickfoz\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/","url":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png","contentUrl":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png","width":190,"height":65,"caption":"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i"},"image":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/clickfoz","https:\/\/x.com\/clickfoz","https:\/\/www.instagram.com\/clickfoz"]},{"@type":"Person","@id":"","url":"http:\/\/box5640.temp.domains\/~clickfoz\/author\/"}]}},"_links":{"self":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts\/14426","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/comments?post=14426"}],"version-history":[{"count":0,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts\/14426\/revisions"}],"wp:attachment":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/media?parent=14426"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/categories?post=14426"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/tags?post=14426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}