{"id":14402,"date":"2010-06-17T17:56:54","date_gmt":"2010-06-17T17:56:54","guid":{"rendered":"http:\/\/localhost:82\/wordpress\/2010\/06\/17\/ceramica-de-curitiba-e-a-primeira-do-parana-a-receber-selo-nacional-de-qualidade-5848-3\/"},"modified":"2010-06-17T17:56:54","modified_gmt":"2010-06-17T17:56:54","slug":"ceramica-de-curitiba-e-a-primeira-do-parana-a-receber-selo-nacional-de-qualidade-5848-3","status":"publish","type":"post","link":"http:\/\/box5640.temp.domains\/~clickfoz\/ceramica-de-curitiba-e-a-primeira-do-parana-a-receber-selo-nacional-de-qualidade-5848-3\/","title":{"rendered":"Cer&acirc;mica de Curitiba &eacute; a primeira do Paran&aacute; a receber selo nacional de qualidade"},"content":{"rendered":"<p style=\"text-align: justify\">A Cer&acirc;mica S&atilde;o Pedro, de Curitiba, &eacute; a primeira empresa do ramo no Paran&aacute; a receber o selo do Programa Setorial da Qualidade (PSQ), emitido pela Associa&ccedil;&atilde;o Nacional da Ind&uacute;stria Cer&acirc;mica (ANICER). A empresa obteve a certifica&ccedil;&atilde;o para os blocos cer&acirc;micos estruturais, que produz em sua f&aacute;brica do bairro Caximba, na capital. O PSQ faz parte do Programa Brasileiro da Qualidade e Produtividade na Habita&ccedil;&atilde;o (PBQP-H), do Minist&eacute;rio das Cidades, que atesta a qualidade de produtos da constru&ccedil;&atilde;o civil. <br \/>\n&nbsp;<br \/>\nPara conseguir a certifica&ccedil;&atilde;o, a Cer&acirc;mica S&atilde;o Pedro teve de adequar seus produtos para que estivessem de acordo com as exig&ecirc;ncias da Associa&ccedil;&atilde;o Brasileira de Normas T&eacute;cnicas (ABNT), que determina caracter&iacute;sticas espec&iacute;ficas para o material. <br \/>\n&nbsp;<br \/>\n<strong>Hist&oacute;ria <\/strong>&#8211; Fundada h&aacute; 47 anos e com 22 funcion&aacute;rios, a Cer&acirc;mica S&atilde;o Pedro teve a qualidade de seu produto atestada em todas as etapas exigidas para a certifica&ccedil;&atilde;o. &ldquo;As amostras analisadas estavam dentro das conformidades exigidas nos ensaios, que verificam as dimens&otilde;es, a resist&ecirc;ncia, absor&ccedil;&atilde;o de &aacute;gua, esquadro e compress&atilde;o&rdquo;, afirma o consultor t&eacute;cnico do Senai, Adilson Carlos Costa, que foi o respons&aacute;vel pela consultoria. &nbsp;<br \/>\n&nbsp;<br \/>\nO assessor t&eacute;cnico da qualidade da Anicer, Antonio Carlos Pimenta, diz que o selo PSQ &eacute; uma forma de demonstra&ccedil;&atilde;o p&uacute;blica da empresa de que est&aacute; atuando em sintonia com o programa de qualidade na habita&ccedil;&atilde;o.&nbsp; Ele explica que para manter o selo, a empresa ter&aacute; novas amostras de produtos coletadas a cada tr&ecirc;s meses para reavalia&ccedil;&atilde;o. &ldquo;&Eacute; um processo permanente de verifica&ccedil;&atilde;o da qualidade&rdquo;, diz Pimenta.<br \/>\n&nbsp;<br \/>\nO selo PSQ ser&aacute; entregue para a Cer&acirc;mica S&atilde;o Pedro durante o 39&ordm; Encontro Nacional da Ind&uacute;stria de Cer&acirc;mica Vermelha, que acontece em agosto, em Florian&oacute;polis, Santa Catarina. O assessor da Anicer explica que a certifica&ccedil;&atilde;o poder&aacute; ser utilizada tanto nos produtos, quanto nos materiais de divulga&ccedil;&atilde;o da empresa.<br \/>\n&nbsp;<br \/>\n<strong>Adequa&ccedil;&otilde;es <\/strong>&#8211; Para conquistar o selo, a Cer&acirc;mica S&atilde;o Pedro passou por diversas mudan&ccedil;as que aperfei&ccedil;oaram a produ&ccedil;&atilde;o. Um exemplo foi na quest&atilde;o de tempo de descanso da argila: antes ela era extra&iacute;da da jazida e ia direto para a produ&ccedil;&atilde;o. Agora, depois das dicas do Senai, a argila descansa por dois anos ao ar livre, ficando exposta ao sol e &agrave; chuva. Tudo isso para que o produto final tenha mais resist&ecirc;ncia.<br \/>\n&nbsp;<br \/>\nNo transporte tamb&eacute;m houve mudan&ccedil;as. A empresa implantou o m&eacute;todo de <br \/>\n&nbsp;paletiza&ccedil;&atilde;o dos produtos, com a utiliza&ccedil;&atilde;o de pallets de madeira ou pl&aacute;stico que s&atilde;o colocados embaixo dos produtos para que estes sejam levantados por uma empilhadeira. Antes o processo era manual. A cer&acirc;mica tamb&eacute;m adquiriu equipamentos mais potentes para moer argila e um novo forno t&uacute;nel<br \/>\n&nbsp;<br \/>\nO Senai auxiliou na implanta&ccedil;&atilde;o de um laborat&oacute;rio para apoiar a produ&ccedil;&atilde;o, instalado dentro da empresa. No laborat&oacute;rio, a cer&acirc;mica pode fazer ensaios de rotina na argila para verificar se o produto est&aacute; saindo de acordo com as normas. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Cer&acirc;mica S&atilde;o Pedro, de Curitiba, &eacute; a primeira empresa do ramo no Paran&aacute; a receber o selo do Programa Setorial da Qualidade (PSQ), emitido pela Associa&ccedil;&atilde;o Nacional da Ind&uacute;stria Cer&acirc;mica (ANICER). A empresa obteve a certifica&ccedil;&atilde;o para os blocos cer&acirc;micos estruturais, que produz em sua f&aacute;brica do bairro Caximba, na capital. O PSQ faz [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-14402","post","type-post","status-publish","format-standard","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cer&acirc;mica de Curitiba &eacute; a primeira do Paran&aacute; a receber selo nacional de qualidade - Clickfoz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/box5640.temp.domains\/~clickfoz\/ceramica-de-curitiba-e-a-primeira-do-parana-a-receber-selo-nacional-de-qualidade-5848-3\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cer&acirc;mica de Curitiba &eacute; a primeira do Paran&aacute; a receber selo nacional de qualidade - Clickfoz\" \/>\n<meta property=\"og:description\" content=\"A Cer&acirc;mica S&atilde;o Pedro, de Curitiba, &eacute; a primeira empresa do ramo no Paran&aacute; a receber o selo do Programa Setorial da Qualidade (PSQ), emitido pela Associa&ccedil;&atilde;o Nacional da Ind&uacute;stria Cer&acirc;mica (ANICER). A empresa obteve a certifica&ccedil;&atilde;o para os blocos cer&acirc;micos estruturais, que produz em sua f&aacute;brica do bairro Caximba, na capital. O PSQ faz [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/box5640.temp.domains\/~clickfoz\/ceramica-de-curitiba-e-a-primeira-do-parana-a-receber-selo-nacional-de-qualidade-5848-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Clickfoz\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/clickfoz\" \/>\n<meta property=\"article:published_time\" content=\"2010-06-17T17:56:54+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2023\/11\/logo-clickfoz.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@clickfoz\" \/>\n<meta name=\"twitter:site\" content=\"@clickfoz\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/ceramica-de-curitiba-e-a-primeira-do-parana-a-receber-selo-nacional-de-qualidade-5848-3\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/ceramica-de-curitiba-e-a-primeira-do-parana-a-receber-selo-nacional-de-qualidade-5848-3\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Cer&acirc;mica de Curitiba &eacute; a primeira do Paran&aacute; a receber selo nacional de qualidade\",\"datePublished\":\"2010-06-17T17:56:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/ceramica-de-curitiba-e-a-primeira-do-parana-a-receber-selo-nacional-de-qualidade-5848-3\/\"},\"wordCount\":661,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\/\/box5640.temp.domains\/~clickfoz\/ceramica-de-curitiba-e-a-primeira-do-parana-a-receber-selo-nacional-de-qualidade-5848-3\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/ceramica-de-curitiba-e-a-primeira-do-parana-a-receber-selo-nacional-de-qualidade-5848-3\/\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/ceramica-de-curitiba-e-a-primeira-do-parana-a-receber-selo-nacional-de-qualidade-5848-3\/\",\"name\":\"Cer&acirc;mica de Curitiba &eacute; a primeira do Paran&aacute; a receber selo nacional de qualidade - Clickfoz\",\"isPartOf\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#website\"},\"datePublished\":\"2010-06-17T17:56:54+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/ceramica-de-curitiba-e-a-primeira-do-parana-a-receber-selo-nacional-de-qualidade-5848-3\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/box5640.temp.domains\/~clickfoz\/ceramica-de-curitiba-e-a-primeira-do-parana-a-receber-selo-nacional-de-qualidade-5848-3\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/ceramica-de-curitiba-e-a-primeira-do-parana-a-receber-selo-nacional-de-qualidade-5848-3\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/box5640.temp.domains\/~clickfoz\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cer&acirc;mica de Curitiba &eacute; a primeira do Paran&aacute; a receber selo nacional de qualidade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#website\",\"url\":\"https:\/\/box5640.temp.domains\/~clickfoz\/\",\"name\":\"Click Foz do Igua\u00e7u\",\"description\":\"O portal de not\u00edcias de Foz do Igua\u00e7u\",\"publisher\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/box5640.temp.domains\/~clickfoz\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\",\"name\":\"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i\",\"url\":\"https:\/\/box5640.temp.domains\/~clickfoz\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png\",\"contentUrl\":\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png\",\"width\":190,\"height\":65,\"caption\":\"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i\"},\"image\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/clickfoz\",\"https:\/\/x.com\/clickfoz\",\"https:\/\/www.instagram.com\/clickfoz\"]},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cer&acirc;mica de Curitiba &eacute; a primeira do Paran&aacute; a receber selo nacional de qualidade - Clickfoz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/box5640.temp.domains\/~clickfoz\/ceramica-de-curitiba-e-a-primeira-do-parana-a-receber-selo-nacional-de-qualidade-5848-3\/","og_locale":"pt_BR","og_type":"article","og_title":"Cer&acirc;mica de Curitiba &eacute; a primeira do Paran&aacute; a receber selo nacional de qualidade - Clickfoz","og_description":"A Cer&acirc;mica S&atilde;o Pedro, de Curitiba, &eacute; a primeira empresa do ramo no Paran&aacute; a receber o selo do Programa Setorial da Qualidade (PSQ), emitido pela Associa&ccedil;&atilde;o Nacional da Ind&uacute;stria Cer&acirc;mica (ANICER). A empresa obteve a certifica&ccedil;&atilde;o para os blocos cer&acirc;micos estruturais, que produz em sua f&aacute;brica do bairro Caximba, na capital. O PSQ faz [&hellip;]","og_url":"http:\/\/box5640.temp.domains\/~clickfoz\/ceramica-de-curitiba-e-a-primeira-do-parana-a-receber-selo-nacional-de-qualidade-5848-3\/","og_site_name":"Clickfoz","article_publisher":"https:\/\/facebook.com\/clickfoz","article_published_time":"2010-06-17T17:56:54+00:00","og_image":[{"width":1200,"height":675,"url":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2023\/11\/logo-clickfoz.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_creator":"@clickfoz","twitter_site":"@clickfoz","twitter_misc":{"Escrito por":"","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/ceramica-de-curitiba-e-a-primeira-do-parana-a-receber-selo-nacional-de-qualidade-5848-3\/#article","isPartOf":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/ceramica-de-curitiba-e-a-primeira-do-parana-a-receber-selo-nacional-de-qualidade-5848-3\/"},"author":{"name":"","@id":""},"headline":"Cer&acirc;mica de Curitiba &eacute; a primeira do Paran&aacute; a receber selo nacional de qualidade","datePublished":"2010-06-17T17:56:54+00:00","mainEntityOfPage":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/ceramica-de-curitiba-e-a-primeira-do-parana-a-receber-selo-nacional-de-qualidade-5848-3\/"},"wordCount":661,"commentCount":0,"publisher":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization"},"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/box5640.temp.domains\/~clickfoz\/ceramica-de-curitiba-e-a-primeira-do-parana-a-receber-selo-nacional-de-qualidade-5848-3\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/ceramica-de-curitiba-e-a-primeira-do-parana-a-receber-selo-nacional-de-qualidade-5848-3\/","url":"http:\/\/box5640.temp.domains\/~clickfoz\/ceramica-de-curitiba-e-a-primeira-do-parana-a-receber-selo-nacional-de-qualidade-5848-3\/","name":"Cer&acirc;mica de Curitiba &eacute; a primeira do Paran&aacute; a receber selo nacional de qualidade - Clickfoz","isPartOf":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#website"},"datePublished":"2010-06-17T17:56:54+00:00","breadcrumb":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/ceramica-de-curitiba-e-a-primeira-do-parana-a-receber-selo-nacional-de-qualidade-5848-3\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/box5640.temp.domains\/~clickfoz\/ceramica-de-curitiba-e-a-primeira-do-parana-a-receber-selo-nacional-de-qualidade-5848-3\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/ceramica-de-curitiba-e-a-primeira-do-parana-a-receber-selo-nacional-de-qualidade-5848-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/box5640.temp.domains\/~clickfoz\/"},{"@type":"ListItem","position":2,"name":"Cer&acirc;mica de Curitiba &eacute; a primeira do Paran&aacute; a receber selo nacional de qualidade"}]},{"@type":"WebSite","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#website","url":"https:\/\/box5640.temp.domains\/~clickfoz\/","name":"Click Foz do Igua\u00e7u","description":"O portal de not\u00edcias de Foz do Igua\u00e7u","publisher":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/box5640.temp.domains\/~clickfoz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization","name":"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i","url":"https:\/\/box5640.temp.domains\/~clickfoz\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/","url":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png","contentUrl":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png","width":190,"height":65,"caption":"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i"},"image":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/clickfoz","https:\/\/x.com\/clickfoz","https:\/\/www.instagram.com\/clickfoz"]},{"@type":"Person","@id":"","url":"http:\/\/box5640.temp.domains\/~clickfoz\/author\/"}]}},"_links":{"self":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts\/14402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/comments?post=14402"}],"version-history":[{"count":0,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts\/14402\/revisions"}],"wp:attachment":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/media?parent=14402"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/categories?post=14402"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/tags?post=14402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}