{"id":14223,"date":"2010-06-22T18:04:34","date_gmt":"2010-06-22T18:04:34","guid":{"rendered":"http:\/\/localhost:82\/wordpress\/2010\/06\/22\/hotel-bella-italia-completa-20-anos-de-atuacao-em-foz-do-iguacu-5904\/"},"modified":"2010-06-22T18:04:34","modified_gmt":"2010-06-22T18:04:34","slug":"hotel-bella-italia-completa-20-anos-de-atuacao-em-foz-do-iguacu-5904","status":"publish","type":"post","link":"http:\/\/box5640.temp.domains\/~clickfoz\/hotel-bella-italia-completa-20-anos-de-atuacao-em-foz-do-iguacu-5904\/","title":{"rendered":"Hotel Bella Italia completa 20 anos de atua&ccedil;&atilde;o em Foz do Igua&ccedil;u"},"content":{"rendered":"<p style=\"text-align: justify\">\n<table width=\"200\" cellspacing=\"0\" cellpadding=\"0\" border=\"0\" align=\"right\" style=\"margin: 0pt 3px\">\n<tbody>\n<tr>\n<td style=\"text-align: right\"><span style=\"font-size: 11px\">Foto: Hotel Bella Italia<br \/>\n            <\/span><\/td>\n<\/tr>\n<tr>\n<td bgcolor=\"#f4f4f2\"><img fetchpriority=\"high\" decoding=\"async\" height=\"208\" width=\"300\" alt=\"\" src=\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/images\/noticias\/Hotel%20Bella%20Italia%5D\/noiteitaliana8.jpg\" \/><\/td>\n<\/tr>\n<tr>\n<td bgcolor=\"#f4f4f2\" style=\"padding: 3px 1px;text-align: left;font-size: 11px\">Noite Italiana tem mais de 40 tipos de queijo<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: justify\">Mesa farta e alegria s&atilde;o marcas da cultura italiana. A fam&iacute;lia &ldquo;Bortoli&rdquo; &ndash; administradora do <a target=\"_blank\" href=\"http:\/\/www.hotelbellaitalia.com.br\">Hotel Bella Italia<\/a> &ndash; situado no centro de Foz do Igua&ccedil;u, preserva esses valores, tratando cada h&oacute;spede como se fosse membro da fam&iacute;lia, al&eacute;m de caprichar no caf&eacute; da manh&atilde; e no tradicional jantar de massas &ldquo;Noite Italiana&rdquo;. Em 2010, o Bella Italia completa 20 anos de funcionamento, data que ser&aacute; marcada por v&aacute;rios eventos comemorativos &ndash; de jantares especiais at&eacute; uma corrida de rua. O lan&ccedil;amento de um blog &eacute; outra novidade alusiva ao anivers&aacute;rio.<\/p>\n<p style=\"text-align: justify\">Apostando no potencial de Foz do Igua&ccedil;u, terceiro maior destino tur&iacute;stico do Brasil &ndash; abrigando atrativos como Cataratas do Igua&ccedil;u e Itaipu Binacional &#8211; em 1990 Arnaldo e Cleris Bortoli inauguraram o Hotel Bella Italia. E para comemorar os 20 anos de atua&ccedil;&atilde;o ser&atilde;o realizadas v&aacute;rias atividades, com in&iacute;cio em julho. Os clientes que participarem da &ldquo;Noite Italiana&rdquo; nesse m&ecirc;s receber&atilde;o ta&ccedil;as de espumantes como cortesia. Ser&atilde;o nove noites de brindes (dia 3, 7, 10, 14, 17, 21, 24, 28 e 31 de julho). Outra a&ccedil;&atilde;o envolvendo o tradicional jantar de massa do Bella ser&aacute; a &ldquo;Semana Italiana&rdquo;, de 11 a 14 de agosto, reunindo Noite Italiana e a apresenta&ccedil;&atilde;o da cantora ga&uacute;cha Ines Rizzardo, trazendo a Foz do Igua&ccedil;u can&ccedil;&otilde;es folcl&oacute;ricas da cultura italiana. Ainda durante essa semana, os Correios far&atilde;o o lan&ccedil;amento de um selo comemorativo aos 20 Anos do Hotel.<br \/>\n&nbsp;&nbsp; &nbsp;<br \/>\n<strong>Corrida noturna<\/strong> &#8211; Corrida &eacute; uma paix&atilde;o da Fam&iacute;lia Bella Italia &ndash; dos diretores aos funcion&aacute;rios. Contando com o &ldquo;know how&rdquo; da Acorrefoz, ser&aacute; realizada uma competi&ccedil;&atilde;o de oito quil&ocirc;metros pelas ruas do centro de Foz do Igua&ccedil;u. &ldquo;Temos uma equipe que treina regularmente para participar de competi&ccedil;&otilde;es na regi&atilde;o. Como uma das a&ccedil;&otilde;es comemorativas do anivers&aacute;rio decidimos organizar a primeira corrida de rua noturna de Foz do Igua&ccedil;u para integrar os moradores &#8211; a quem somos muito gratos &#8211; a essa grande festa&rdquo;, explica Marcelo Bortoli, gerente de Alimentos e Bebidas do Bella Italia e um dos &ldquo;atletas&rdquo; mais animados da equipe. A &ldquo;Iguassu NightRun 2010 &#8211; Trof&eacute;u 20 anos Bella Italia&rdquo; ser&aacute; no dia 07 de agosto, &agrave;s 19h. As inscri&ccedil;&otilde;es podem ser feitas no site http:\/\/www.iguassunightrun.com.br, de 22 de junho a 29 de julho. A taxa de inscri&ccedil;&atilde;o &eacute; R$ 17,00 e ser&aacute; revertida integralmente para a Associa&ccedil;&atilde;o de Prote&ccedil;&atilde;o a Maternidade e a Inf&acirc;ncia (APMI)<\/p>\n<p><strong>Blog <\/strong>&#8211; A primeira a&ccedil;&atilde;o dos 20 anos do Bella Italia foi o lan&ccedil;amento de um blog, um canal de comunica&ccedil;&atilde;o com linguagem descontra&iacute;da para apresentar a hist&oacute;ria do Hotel, acontecimentos curiosos do cotidiano e at&eacute; artigos sobre gastronomia e vinhos, assinados por profissionais renomados no Brasil, como a en&oacute;loga Paola Tedeschi. O blog tamb&eacute;m ter&aacute; espa&ccedil;o &agrave; divulga&ccedil;&atilde;o dos detalhes de cada atividade programada para o anivers&aacute;rio. A atualiza&ccedil;&atilde;o &eacute; di&aacute;ria. Vale conferir os materiais que j&aacute; est&atilde;o no ar <a target=\"_blank\" href=\"http:\/\/www.hotelbellaitalia.com.br\/blog\">http:\/\/www.hotelbellaitalia.com.br\/blog<\/a>. <\/p>\n<p><strong>Diferenciais <\/strong>&ndash; &ldquo;Se hospedar no Bella Italia e n&atilde;o ganhar alguns quilos no tempo que passa por aqui &eacute; tarefa dif&iacute;cil. Quando entra no apartamento j&aacute; enfrenta a primeira tenta&ccedil;&atilde;o, cart&atilde;o de boas-vindas acompanhado do doce palha italiana, afinal, a primeira impress&atilde;o &eacute; a que fica&rdquo;, brinca Marcelo Valente, diretor comercial do Hotel. Mas, ele ressalta que &eacute; apenas uma &ldquo;amostra&rdquo; das del&iacute;cias que esperam os h&oacute;spedes no caf&eacute; da manh&atilde; caprichado, com 125 itens entre doces, frutas, frios, omeletes, variedade de p&atilde;es e at&eacute; caldos. &ldquo;Muitos h&oacute;spedes falam que &eacute; preciso ficar pelo menos uma semana no Hotel para provar todos os itens&rdquo;, comenta Sidiclei de Moura, executivo de contas do Bella Italia.<\/p>\n<p>O jantar de massas &ldquo;Noite Italiana&rdquo;, realizado na quarta-feira e no s&aacute;bado, &eacute; outro produto que refor&ccedil;a os elogios &agrave; gastronomia do estabelecimento. Ao todo, s&atilde;o mais de 40 tipos de queijos e rod&iacute;zio com 11 tipos de massa, al&eacute;m de carnes nobres, peixe, frios e sobremesas. Carta de vinho com op&ccedil;&otilde;es nacionais e importadas, decora&ccedil;&atilde;o intimista e m&uacute;sica ao vivo completam a &ldquo;Noite Italiana&rdquo; que h&aacute; oito anos encanta turistas e moradores da regi&atilde;o.<\/p>\n<p><strong>Lazer e Entretenimento<\/strong> &ndash; O Hotel Bella Italia conta com op&ccedil;&otilde;es de lazer dentro do pr&oacute;prio hotel, como piscinas para adultos e crian&ccedil;as, academia e biblioteca. Al&eacute;m da localiza&ccedil;&atilde;o privilegiada, no centro de Foz do Igua&ccedil;u, pr&oacute;ximo ao Shopping e outras op&ccedil;&otilde;es de lazer, o Bella Italia tem o &ldquo;Passaporte Iguassu&rdquo;, reunindo os principais passeios da Tr&iacute;plice Fronteira com excelente custo-benef&iacute;cio. Em alguns casos, o desconto chega a 40% comparado com os valores comercializados direto pelos atrativos.<\/p>\n<p>Reconhecendo esse potencial tur&iacute;stico de Foz do Igua&ccedil;u, h&aacute; 20 anos, a fam&iacute;lia Bortoli decidiu apostar na cidade e construir o Hotel Bella Italia que, hoje, &eacute; um dos mais respeitados empreendimentos hoteleiros quatro estrelas do interior do Paran&aacute; e gerador de centenas de empregos diretos e indiretos. &ldquo;Nada mais fizemos que nossa obriga&ccedil;&atilde;o em dar um pouco de n&oacute;s para construir o ambiente em que n&oacute;s vivemos&rdquo;, ressalta Arnaldo Bortoli.<\/p>\n<p><strong>Servi&ccedil;o<\/strong><br \/>\nO que: Comemora&ccedil;&atilde;o 20 anos do Hotel Bella Italia<br \/>\nEventos programados: <br \/>\n<strong>Noite Italiana:<\/strong> <a target=\"_blank\" href=\"http:\/\/www.hotelbellaitalia.com.br\/blog\/noite-italiana\">www.hotelbellaitalia.com.br\/blog\/noite-italiana<\/a><br \/>\n<strong>Semana Italiana:<\/strong> <a target=\"_blank\" href=\"http:\/\/www.hotelbellaitalia.com.br\/blog\/semana-italiana\">www.hotelbellaitalia.com.br\/blog\/semana-italiana<\/a><br \/>\n<strong>Iguassu Night Run 2010 &ndash; Trof&eacute;u 20 Anos Bella Italia:<\/strong>&nbsp; <a target=\"_blank\" href=\"http:\/\/www.iguassunightrun.com.br\">www.iguassunightrun.com.br<\/a><br \/>\n<strong>Informa&ccedil;&otilde;es:&nbsp;<\/strong> <a target=\"_blank\" href=\"http:\/\/www.hotelbellaitalia.com.br\/blog\">www.hotelbellaitalia.com.br\/blog<\/a> ou <a target=\"_blank\" href=\"http:\/\/www.hotelbellaitalia.com.br\">www.hotelbellaitalia.com.br <\/a><br \/>\nFone: (45) 3521-5000<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foto: Hotel Bella Italia Noite Italiana tem mais de 40 tipos de queijo Mesa farta e alegria s&atilde;o marcas da cultura italiana. A fam&iacute;lia &ldquo;Bortoli&rdquo; &ndash; administradora do Hotel Bella Italia &ndash; situado no centro de Foz do Igua&ccedil;u, preserva esses valores, tratando cada h&oacute;spede como se fosse membro da fam&iacute;lia, al&eacute;m de caprichar no [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-14223","post","type-post","status-publish","format-standard","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Hotel Bella Italia completa 20 anos de atua&ccedil;&atilde;o em Foz do Igua&ccedil;u - Clickfoz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/box5640.temp.domains\/~clickfoz\/hotel-bella-italia-completa-20-anos-de-atuacao-em-foz-do-iguacu-5904\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hotel Bella Italia completa 20 anos de atua&ccedil;&atilde;o em Foz do Igua&ccedil;u - Clickfoz\" \/>\n<meta property=\"og:description\" content=\"Foto: Hotel Bella Italia Noite Italiana tem mais de 40 tipos de queijo Mesa farta e alegria s&atilde;o marcas da cultura italiana. A fam&iacute;lia &ldquo;Bortoli&rdquo; &ndash; administradora do Hotel Bella Italia &ndash; situado no centro de Foz do Igua&ccedil;u, preserva esses valores, tratando cada h&oacute;spede como se fosse membro da fam&iacute;lia, al&eacute;m de caprichar no [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/box5640.temp.domains\/~clickfoz\/hotel-bella-italia-completa-20-anos-de-atuacao-em-foz-do-iguacu-5904\/\" \/>\n<meta property=\"og:site_name\" content=\"Clickfoz\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/clickfoz\" \/>\n<meta property=\"article:published_time\" content=\"2010-06-22T18:04:34+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/images\/noticias\/Hotel%20Bella%20Italia%5D\/noiteitaliana8.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@clickfoz\" \/>\n<meta name=\"twitter:site\" content=\"@clickfoz\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/hotel-bella-italia-completa-20-anos-de-atuacao-em-foz-do-iguacu-5904\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/hotel-bella-italia-completa-20-anos-de-atuacao-em-foz-do-iguacu-5904\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Hotel Bella Italia completa 20 anos de atua&ccedil;&atilde;o em Foz do Igua&ccedil;u\",\"datePublished\":\"2010-06-22T18:04:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/hotel-bella-italia-completa-20-anos-de-atuacao-em-foz-do-iguacu-5904\/\"},\"wordCount\":1144,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\"},\"image\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/hotel-bella-italia-completa-20-anos-de-atuacao-em-foz-do-iguacu-5904\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/images\/noticias\/Hotel%20Bella%20Italia%5D\/noiteitaliana8.jpg\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\/\/box5640.temp.domains\/~clickfoz\/hotel-bella-italia-completa-20-anos-de-atuacao-em-foz-do-iguacu-5904\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/hotel-bella-italia-completa-20-anos-de-atuacao-em-foz-do-iguacu-5904\/\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/hotel-bella-italia-completa-20-anos-de-atuacao-em-foz-do-iguacu-5904\/\",\"name\":\"Hotel Bella Italia completa 20 anos de atua&ccedil;&atilde;o em Foz do Igua&ccedil;u - Clickfoz\",\"isPartOf\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/hotel-bella-italia-completa-20-anos-de-atuacao-em-foz-do-iguacu-5904\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/hotel-bella-italia-completa-20-anos-de-atuacao-em-foz-do-iguacu-5904\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/images\/noticias\/Hotel%20Bella%20Italia%5D\/noiteitaliana8.jpg\",\"datePublished\":\"2010-06-22T18:04:34+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/hotel-bella-italia-completa-20-anos-de-atuacao-em-foz-do-iguacu-5904\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/box5640.temp.domains\/~clickfoz\/hotel-bella-italia-completa-20-anos-de-atuacao-em-foz-do-iguacu-5904\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/hotel-bella-italia-completa-20-anos-de-atuacao-em-foz-do-iguacu-5904\/#primaryimage\",\"url\":\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/images\/noticias\/Hotel%20Bella%20Italia%5D\/noiteitaliana8.jpg\",\"contentUrl\":\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/images\/noticias\/Hotel%20Bella%20Italia%5D\/noiteitaliana8.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/hotel-bella-italia-completa-20-anos-de-atuacao-em-foz-do-iguacu-5904\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/box5640.temp.domains\/~clickfoz\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hotel Bella Italia completa 20 anos de atua&ccedil;&atilde;o em Foz do Igua&ccedil;u\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#website\",\"url\":\"https:\/\/box5640.temp.domains\/~clickfoz\/\",\"name\":\"Click Foz do Igua\u00e7u\",\"description\":\"O portal de not\u00edcias de Foz do Igua\u00e7u\",\"publisher\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/box5640.temp.domains\/~clickfoz\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\",\"name\":\"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i\",\"url\":\"https:\/\/box5640.temp.domains\/~clickfoz\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png\",\"contentUrl\":\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png\",\"width\":190,\"height\":65,\"caption\":\"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i\"},\"image\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/clickfoz\",\"https:\/\/x.com\/clickfoz\",\"https:\/\/www.instagram.com\/clickfoz\"]},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hotel Bella Italia completa 20 anos de atua&ccedil;&atilde;o em Foz do Igua&ccedil;u - Clickfoz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/box5640.temp.domains\/~clickfoz\/hotel-bella-italia-completa-20-anos-de-atuacao-em-foz-do-iguacu-5904\/","og_locale":"pt_BR","og_type":"article","og_title":"Hotel Bella Italia completa 20 anos de atua&ccedil;&atilde;o em Foz do Igua&ccedil;u - Clickfoz","og_description":"Foto: Hotel Bella Italia Noite Italiana tem mais de 40 tipos de queijo Mesa farta e alegria s&atilde;o marcas da cultura italiana. A fam&iacute;lia &ldquo;Bortoli&rdquo; &ndash; administradora do Hotel Bella Italia &ndash; situado no centro de Foz do Igua&ccedil;u, preserva esses valores, tratando cada h&oacute;spede como se fosse membro da fam&iacute;lia, al&eacute;m de caprichar no [&hellip;]","og_url":"http:\/\/box5640.temp.domains\/~clickfoz\/hotel-bella-italia-completa-20-anos-de-atuacao-em-foz-do-iguacu-5904\/","og_site_name":"Clickfoz","article_publisher":"https:\/\/facebook.com\/clickfoz","article_published_time":"2010-06-22T18:04:34+00:00","og_image":[{"url":"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/images\/noticias\/Hotel%20Bella%20Italia%5D\/noiteitaliana8.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_creator":"@clickfoz","twitter_site":"@clickfoz","twitter_misc":{"Escrito por":"","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/hotel-bella-italia-completa-20-anos-de-atuacao-em-foz-do-iguacu-5904\/#article","isPartOf":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/hotel-bella-italia-completa-20-anos-de-atuacao-em-foz-do-iguacu-5904\/"},"author":{"name":"","@id":""},"headline":"Hotel Bella Italia completa 20 anos de atua&ccedil;&atilde;o em Foz do Igua&ccedil;u","datePublished":"2010-06-22T18:04:34+00:00","mainEntityOfPage":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/hotel-bella-italia-completa-20-anos-de-atuacao-em-foz-do-iguacu-5904\/"},"wordCount":1144,"commentCount":0,"publisher":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization"},"image":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/hotel-bella-italia-completa-20-anos-de-atuacao-em-foz-do-iguacu-5904\/#primaryimage"},"thumbnailUrl":"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/images\/noticias\/Hotel%20Bella%20Italia%5D\/noiteitaliana8.jpg","inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/box5640.temp.domains\/~clickfoz\/hotel-bella-italia-completa-20-anos-de-atuacao-em-foz-do-iguacu-5904\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/hotel-bella-italia-completa-20-anos-de-atuacao-em-foz-do-iguacu-5904\/","url":"http:\/\/box5640.temp.domains\/~clickfoz\/hotel-bella-italia-completa-20-anos-de-atuacao-em-foz-do-iguacu-5904\/","name":"Hotel Bella Italia completa 20 anos de atua&ccedil;&atilde;o em Foz do Igua&ccedil;u - Clickfoz","isPartOf":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#website"},"primaryImageOfPage":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/hotel-bella-italia-completa-20-anos-de-atuacao-em-foz-do-iguacu-5904\/#primaryimage"},"image":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/hotel-bella-italia-completa-20-anos-de-atuacao-em-foz-do-iguacu-5904\/#primaryimage"},"thumbnailUrl":"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/images\/noticias\/Hotel%20Bella%20Italia%5D\/noiteitaliana8.jpg","datePublished":"2010-06-22T18:04:34+00:00","breadcrumb":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/hotel-bella-italia-completa-20-anos-de-atuacao-em-foz-do-iguacu-5904\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/box5640.temp.domains\/~clickfoz\/hotel-bella-italia-completa-20-anos-de-atuacao-em-foz-do-iguacu-5904\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/hotel-bella-italia-completa-20-anos-de-atuacao-em-foz-do-iguacu-5904\/#primaryimage","url":"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/images\/noticias\/Hotel%20Bella%20Italia%5D\/noiteitaliana8.jpg","contentUrl":"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/images\/noticias\/Hotel%20Bella%20Italia%5D\/noiteitaliana8.jpg"},{"@type":"BreadcrumbList","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/hotel-bella-italia-completa-20-anos-de-atuacao-em-foz-do-iguacu-5904\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/box5640.temp.domains\/~clickfoz\/"},{"@type":"ListItem","position":2,"name":"Hotel Bella Italia completa 20 anos de atua&ccedil;&atilde;o em Foz do Igua&ccedil;u"}]},{"@type":"WebSite","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#website","url":"https:\/\/box5640.temp.domains\/~clickfoz\/","name":"Click Foz do Igua\u00e7u","description":"O portal de not\u00edcias de Foz do Igua\u00e7u","publisher":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/box5640.temp.domains\/~clickfoz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization","name":"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i","url":"https:\/\/box5640.temp.domains\/~clickfoz\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/","url":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png","contentUrl":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png","width":190,"height":65,"caption":"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i"},"image":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/clickfoz","https:\/\/x.com\/clickfoz","https:\/\/www.instagram.com\/clickfoz"]},{"@type":"Person","@id":"","url":"http:\/\/box5640.temp.domains\/~clickfoz\/author\/"}]}},"_links":{"self":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts\/14223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/comments?post=14223"}],"version-history":[{"count":0,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts\/14223\/revisions"}],"wp:attachment":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/media?parent=14223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/categories?post=14223"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/tags?post=14223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}