{"id":14150,"date":"2010-06-25T15:49:56","date_gmt":"2010-06-25T15:49:56","guid":{"rendered":"http:\/\/localhost:82\/wordpress\/2010\/06\/25\/eles-nunca-foram-campeoes-parte-1-ronnie-peterson-o-primeiro-iceman-da-formula-1-5932-3\/"},"modified":"2010-06-25T15:49:56","modified_gmt":"2010-06-25T15:49:56","slug":"eles-nunca-foram-campeoes-parte-1-ronnie-peterson-o-primeiro-iceman-da-formula-1-5932-3","status":"publish","type":"post","link":"http:\/\/box5640.temp.domains\/~clickfoz\/eles-nunca-foram-campeoes-parte-1-ronnie-peterson-o-primeiro-iceman-da-formula-1-5932-3\/","title":{"rendered":"Eles nunca foram campe&otilde;es &#8211; Parte 1: Ronnie Peterson, o primeiro &quot;Iceman&quot; da F&oacute;rmula 1"},"content":{"rendered":"<p style=\"text-align: center\"><img fetchpriority=\"high\" decoding=\"async\" hspace=\"8\" height=\"287\" width=\"610\" vspace=\"8\" align=\"middle\" src=\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/images\/Coluna%20Ta%20n@%20Rede\/tanarede.jpg\" alt=\"\" \/><\/p>\n<p style=\"text-align: justify\">Na minha coluna de junho, como parte das comemora&ccedil;&otilde;es aos 60 anos da F&oacute;rmula 1, vou dar in&iacute;cio a uma s&eacute;rie que contar&aacute; um pouco da hist&oacute;ria de quatro pilotos que, apesar de traduzirem o real sentimento do automobilismo, com v&aacute;rios epis&oacute;dios de coragem e ousadia, por obra do destino, nunca chegaram a ser campe&otilde;es. Carreiras marcadas por vit&oacute;rias sofridas e fins n&atilde;o muito diferentes.<\/p>\n<p style=\"text-align: justify\"><strong>Ronnie Peterson, o primeiro &quot;Iceman&quot; da F&oacute;rmula 1<\/strong><\/p>\n<\/p>\n<p style=\"text-align: justify\">\n<table width=\"200\" cellspacing=\"0\" cellpadding=\"0\" border=\"0\" align=\"right\" style=\"margin: 0pt 3px\">\n<tbody>\n<tr>\n<td style=\"text-align: right\"><span style=\"font-size: 11px\">Fotos: Arquivos FIA<br \/>\n            <\/span><\/td>\n<\/tr>\n<tr>\n<td bgcolor=\"#f4f4f2\"><img decoding=\"async\" height=\"162\" width=\"300\" src=\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/images\/Coluna%20Ta%20n@%20Rede\/Ronnie%20Peterson.jpg\" alt=\"\" \/><\/td>\n<\/tr>\n<tr>\n<td bgcolor=\"#f4f4f2\" style=\"padding: 3px 1px;text-align: left;font-size: 11px\">Em 1971, Ronnie Peterson &quot;voando&quot; na March<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: justify\">O sueco Bengt Ronald Peterson foi um daqueles pilotos bo&ecirc;mios e memor&aacute;veis. Come&ccedil;ou sua carreira no kart, construindo com o pai seus pr&oacute;prios carros nas categorias de base, e levou esse estilo por toda a carreira. Era dono de uma habilidade e arrojo impressionantes, em contraste com sua apar&ecirc;ncia delicada, timidez e f&iacute;sico relaxado, o que lhe rendeu fama de frio &minus; lembra muito um certo finland&ecirc;s que foi campe&atilde;o recentemente, n&atilde;o &eacute;?<\/p>\n<\/p>\n<p style=\"text-align: justify\">Apesar das qualidades, Ronnie sofreu de um mal que acomete a maioria dos pilotos extraordin&aacute;rios: a falta de um carro &agrave; sua altura. Pilotou pela March, entre 1970 e 1973, onde conquistou um vice-campeonato (71). Ainda em 1973, foi para a Lotus, para pilotar ao lado do ent&atilde;o campe&atilde;o Emerson Fittipaldi, que mais tarde se tornaria seu amigo pessoal.<\/p>\n<p style=\"text-align: justify\">\n<table width=\"200\" cellspacing=\"0\" cellpadding=\"0\" border=\"0\" align=\"left\" style=\"margin: 0pt 3px\">\n<tbody>\n<tr>\n<td style=\"text-align: right\"><span style=\"font-size: 11px\"><br \/>\n            <\/span><\/td>\n<\/tr>\n<tr>\n<td bgcolor=\"#f4f4f2\"><img decoding=\"async\" height=\"197\" width=\"300\" alt=\"\" src=\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/images\/Coluna%20Ta%20n@%20Rede\/Ronnie%20e%20equipe.jpg\" \/><\/td>\n<\/tr>\n<tr>\n<td bgcolor=\"#f4f4f2\" style=\"padding: 3px 1px;text-align: left;font-size: 11px\">Patrick Depailler, Ken Tyrrell e Ronnie Peterson (Equipe Tyrrell, Buenos Aires 77)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: justify\">A passagem pelo time de Colin Chapman durou apenas at&eacute; 1975. Ap&oacute;s experimentar o p&iacute;fio Lotus76, o &ldquo;sueco voador&rdquo; voltou &agrave; March. Em 1977, se aventurou na j&aacute; decadente Tyrrell, para, em 1978, regressar &agrave; Lotus.<\/p>\n<p style=\"text-align: justify\">Neste momento, Ronnie finalmente parecia estar no caminho certo para ser campe&atilde;o, com a equipe tendo aperfei&ccedil;oado o revolucion&aacute;rio conceito aerodin&acirc;mico do <a target=\"_blank\" href=\"http:\/\/formulatotal.wordpress.com\/2010\/05\/22\/carro-asa-o-extremo-da-aerodinamica-na-f1\/\">carro-asa<\/a>. E mesmo com o status de 2&ordm; piloto, venceu tr&ecirc;s GPs (Brasil, &Aacute;frica do Sul e &Aacute;ustria), o que j&aacute; lhe assegurava o 2&ordm; vice-campeonato e a vantagem de ser o &uacute;nico a brigar pelo t&iacute;tulo com o americano Mario Andretti.<\/p>\n<p style=\"text-align: justify\"><strong>Monza <\/strong>&#8211; No GP da It&aacute;lia, sua terra natal, Mario Andretti precisava apenas de 1 ponto para sagrar-se campe&atilde;o, mas seu companheiro de equipe, que j&aacute; havia vencido 3 vezes ali, n&atilde;o parecia querer entregar f&aacute;cil o t&iacute;tulo. O que o mundo n&atilde;o sabia era que o campeonato de 1978 seria decidido naquele final de semana, mas sem comemora&ccedil;&otilde;es. Uma sucess&atilde;o de acontecimentos transformaria Monza no palco da &uacute;ltima e mais curta apresenta&ccedil;&atilde;o do &ldquo;sueco voador&rdquo;.<\/p>\n<p>Largando em 5&ordm;, com um fr&aacute;gil carro reserva, ap&oacute;s destruir seu b&oacute;lido no Warm Up, Peterson acabou sendo tra&iacute;do por uma tecnologia que estrearia naquele dia: o sem&aacute;foro de largada. Uma confus&atilde;o do diretor de prova, Gianni Restelli, fez com que a largada fosse dada antes que todos os carros estivessem estacionados no grid, dando uma vantagem os competidores do fundo. 300 metros depois, um toque entre a McLaren de James Hunt e o Arrows de Riccardo Patrese sobra para a Lotus78 de Peterson, que bate em cheio nos guard rails e vira uma bola de fogo.<\/p>\n<p style=\"text-align: justify\">\n<table width=\"200\" cellspacing=\"0\" cellpadding=\"0\" border=\"0\" align=\"left\" style=\"margin: 0pt 3px\">\n<tbody>\n<tr>\n<td style=\"text-align: right\">&nbsp;<\/td>\n<\/tr>\n<tr>\n<td bgcolor=\"#f4f4f2\"><img loading=\"lazy\" decoding=\"async\" height=\"196\" width=\"300\" src=\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/images\/Coluna%20Ta%20n@%20Rede\/Ronnie%20na%20corrida.jpg\" alt=\"\" \/><\/td>\n<\/tr>\n<tr>\n<td bgcolor=\"#f4f4f2\" style=\"padding: 3px 1px;text-align: justify;font-size: 11px\">Peterson e seus tradicionais drifts, herdados da &eacute;poca do kart<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: justify\">Hunt, Clay Regazzoni e Patrick Depailler, em meio &agrave;s trapalhadas dos bombeiros, conseguem retirar o sueco das chamas, vivo, mas com graves ferimentos e m&uacute;ltiplas fraturas nas pernas. No dia seguinte, ap&oacute;s amputa&ccedil;&atilde;o do p&eacute; esquerdo, Ronnie Peterson, aos 34 anos, falece v&iacute;tima de uma embolia.<\/p>\n<p style=\"text-align: justify\">Patrese acabou sendo declarado culpado pelo acidente e recebeu um &ldquo;aviso de suspens&atilde;o&rdquo; por dois anos. E por conta da confus&atilde;o com o uso do sem&aacute;foro, ficou determinou que a largada s&oacute; poderia ser dada depois que um fiscal atravessasse o grid com uma bandeira na m&atilde;o, confirmando que todos os carros estavam parados, o que acontece at&eacute; hoje.<\/p>\n<p style=\"text-align: justify\">&nbsp;<\/p>\n<p style=\"text-align: justify\">&nbsp;<\/p>\n<p style=\"text-align: justify\"><em>*Belenos &eacute; acad&ecirc;mico de Comunica&ccedil;&atilde;o Social, f&atilde; de F&oacute;rmula 1 da era p&oacute;s-Senna e j&aacute; n&atilde;o perde uma corrida desde M&ocirc;naco-1999.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na minha coluna de junho, como parte das comemora&ccedil;&otilde;es aos 60 anos da F&oacute;rmula 1, vou dar in&iacute;cio a uma s&eacute;rie que contar&aacute; um pouco da hist&oacute;ria de quatro pilotos que, apesar de traduzirem o real sentimento do automobilismo, com v&aacute;rios epis&oacute;dios de coragem e ousadia, por obra do destino, nunca chegaram a ser campe&otilde;es. [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-14150","post","type-post","status-publish","format-standard","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Eles nunca foram campe&otilde;es - Parte 1: Ronnie Peterson, o primeiro &quot;Iceman&quot; da F&oacute;rmula 1 - Clickfoz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/box5640.temp.domains\/~clickfoz\/eles-nunca-foram-campeoes-parte-1-ronnie-peterson-o-primeiro-iceman-da-formula-1-5932-3\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eles nunca foram campe&otilde;es - Parte 1: Ronnie Peterson, o primeiro &quot;Iceman&quot; da F&oacute;rmula 1 - Clickfoz\" \/>\n<meta property=\"og:description\" content=\"Na minha coluna de junho, como parte das comemora&ccedil;&otilde;es aos 60 anos da F&oacute;rmula 1, vou dar in&iacute;cio a uma s&eacute;rie que contar&aacute; um pouco da hist&oacute;ria de quatro pilotos que, apesar de traduzirem o real sentimento do automobilismo, com v&aacute;rios epis&oacute;dios de coragem e ousadia, por obra do destino, nunca chegaram a ser campe&otilde;es. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/box5640.temp.domains\/~clickfoz\/eles-nunca-foram-campeoes-parte-1-ronnie-peterson-o-primeiro-iceman-da-formula-1-5932-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Clickfoz\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/clickfoz\" \/>\n<meta property=\"article:published_time\" content=\"2010-06-25T15:49:56+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/images\/Coluna%20Ta%20n@%20Rede\/tanarede.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@clickfoz\" \/>\n<meta name=\"twitter:site\" content=\"@clickfoz\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/eles-nunca-foram-campeoes-parte-1-ronnie-peterson-o-primeiro-iceman-da-formula-1-5932-3\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/eles-nunca-foram-campeoes-parte-1-ronnie-peterson-o-primeiro-iceman-da-formula-1-5932-3\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Eles nunca foram campe&otilde;es &#8211; Parte 1: Ronnie Peterson, o primeiro &quot;Iceman&quot; da F&oacute;rmula 1\",\"datePublished\":\"2010-06-25T15:49:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/eles-nunca-foram-campeoes-parte-1-ronnie-peterson-o-primeiro-iceman-da-formula-1-5932-3\/\"},\"wordCount\":791,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\"},\"image\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/eles-nunca-foram-campeoes-parte-1-ronnie-peterson-o-primeiro-iceman-da-formula-1-5932-3\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/images\/Coluna%20Ta%20n@%20Rede\/tanarede.jpg\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\/\/box5640.temp.domains\/~clickfoz\/eles-nunca-foram-campeoes-parte-1-ronnie-peterson-o-primeiro-iceman-da-formula-1-5932-3\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/eles-nunca-foram-campeoes-parte-1-ronnie-peterson-o-primeiro-iceman-da-formula-1-5932-3\/\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/eles-nunca-foram-campeoes-parte-1-ronnie-peterson-o-primeiro-iceman-da-formula-1-5932-3\/\",\"name\":\"Eles nunca foram campe&otilde;es - Parte 1: Ronnie Peterson, o primeiro &quot;Iceman&quot; da F&oacute;rmula 1 - Clickfoz\",\"isPartOf\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/eles-nunca-foram-campeoes-parte-1-ronnie-peterson-o-primeiro-iceman-da-formula-1-5932-3\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/eles-nunca-foram-campeoes-parte-1-ronnie-peterson-o-primeiro-iceman-da-formula-1-5932-3\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/images\/Coluna%20Ta%20n@%20Rede\/tanarede.jpg\",\"datePublished\":\"2010-06-25T15:49:56+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/eles-nunca-foram-campeoes-parte-1-ronnie-peterson-o-primeiro-iceman-da-formula-1-5932-3\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/box5640.temp.domains\/~clickfoz\/eles-nunca-foram-campeoes-parte-1-ronnie-peterson-o-primeiro-iceman-da-formula-1-5932-3\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/eles-nunca-foram-campeoes-parte-1-ronnie-peterson-o-primeiro-iceman-da-formula-1-5932-3\/#primaryimage\",\"url\":\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/images\/Coluna%20Ta%20n@%20Rede\/tanarede.jpg\",\"contentUrl\":\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/images\/Coluna%20Ta%20n@%20Rede\/tanarede.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/eles-nunca-foram-campeoes-parte-1-ronnie-peterson-o-primeiro-iceman-da-formula-1-5932-3\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/box5640.temp.domains\/~clickfoz\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eles nunca foram campe&otilde;es &#8211; Parte 1: Ronnie Peterson, o primeiro &quot;Iceman&quot; da F&oacute;rmula 1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#website\",\"url\":\"https:\/\/box5640.temp.domains\/~clickfoz\/\",\"name\":\"Click Foz do Igua\u00e7u\",\"description\":\"O portal de not\u00edcias de Foz do Igua\u00e7u\",\"publisher\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/box5640.temp.domains\/~clickfoz\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\",\"name\":\"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i\",\"url\":\"https:\/\/box5640.temp.domains\/~clickfoz\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png\",\"contentUrl\":\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png\",\"width\":190,\"height\":65,\"caption\":\"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i\"},\"image\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/clickfoz\",\"https:\/\/x.com\/clickfoz\",\"https:\/\/www.instagram.com\/clickfoz\"]},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eles nunca foram campe&otilde;es - Parte 1: Ronnie Peterson, o primeiro &quot;Iceman&quot; da F&oacute;rmula 1 - Clickfoz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/box5640.temp.domains\/~clickfoz\/eles-nunca-foram-campeoes-parte-1-ronnie-peterson-o-primeiro-iceman-da-formula-1-5932-3\/","og_locale":"pt_BR","og_type":"article","og_title":"Eles nunca foram campe&otilde;es - Parte 1: Ronnie Peterson, o primeiro &quot;Iceman&quot; da F&oacute;rmula 1 - Clickfoz","og_description":"Na minha coluna de junho, como parte das comemora&ccedil;&otilde;es aos 60 anos da F&oacute;rmula 1, vou dar in&iacute;cio a uma s&eacute;rie que contar&aacute; um pouco da hist&oacute;ria de quatro pilotos que, apesar de traduzirem o real sentimento do automobilismo, com v&aacute;rios epis&oacute;dios de coragem e ousadia, por obra do destino, nunca chegaram a ser campe&otilde;es. [&hellip;]","og_url":"http:\/\/box5640.temp.domains\/~clickfoz\/eles-nunca-foram-campeoes-parte-1-ronnie-peterson-o-primeiro-iceman-da-formula-1-5932-3\/","og_site_name":"Clickfoz","article_publisher":"https:\/\/facebook.com\/clickfoz","article_published_time":"2010-06-25T15:49:56+00:00","og_image":[{"url":"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/images\/Coluna%20Ta%20n@%20Rede\/tanarede.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_creator":"@clickfoz","twitter_site":"@clickfoz","twitter_misc":{"Escrito por":"","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/eles-nunca-foram-campeoes-parte-1-ronnie-peterson-o-primeiro-iceman-da-formula-1-5932-3\/#article","isPartOf":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/eles-nunca-foram-campeoes-parte-1-ronnie-peterson-o-primeiro-iceman-da-formula-1-5932-3\/"},"author":{"name":"","@id":""},"headline":"Eles nunca foram campe&otilde;es &#8211; Parte 1: Ronnie Peterson, o primeiro &quot;Iceman&quot; da F&oacute;rmula 1","datePublished":"2010-06-25T15:49:56+00:00","mainEntityOfPage":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/eles-nunca-foram-campeoes-parte-1-ronnie-peterson-o-primeiro-iceman-da-formula-1-5932-3\/"},"wordCount":791,"commentCount":0,"publisher":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization"},"image":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/eles-nunca-foram-campeoes-parte-1-ronnie-peterson-o-primeiro-iceman-da-formula-1-5932-3\/#primaryimage"},"thumbnailUrl":"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/images\/Coluna%20Ta%20n@%20Rede\/tanarede.jpg","inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/box5640.temp.domains\/~clickfoz\/eles-nunca-foram-campeoes-parte-1-ronnie-peterson-o-primeiro-iceman-da-formula-1-5932-3\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/eles-nunca-foram-campeoes-parte-1-ronnie-peterson-o-primeiro-iceman-da-formula-1-5932-3\/","url":"http:\/\/box5640.temp.domains\/~clickfoz\/eles-nunca-foram-campeoes-parte-1-ronnie-peterson-o-primeiro-iceman-da-formula-1-5932-3\/","name":"Eles nunca foram campe&otilde;es - Parte 1: Ronnie Peterson, o primeiro &quot;Iceman&quot; da F&oacute;rmula 1 - Clickfoz","isPartOf":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#website"},"primaryImageOfPage":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/eles-nunca-foram-campeoes-parte-1-ronnie-peterson-o-primeiro-iceman-da-formula-1-5932-3\/#primaryimage"},"image":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/eles-nunca-foram-campeoes-parte-1-ronnie-peterson-o-primeiro-iceman-da-formula-1-5932-3\/#primaryimage"},"thumbnailUrl":"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/images\/Coluna%20Ta%20n@%20Rede\/tanarede.jpg","datePublished":"2010-06-25T15:49:56+00:00","breadcrumb":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/eles-nunca-foram-campeoes-parte-1-ronnie-peterson-o-primeiro-iceman-da-formula-1-5932-3\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/box5640.temp.domains\/~clickfoz\/eles-nunca-foram-campeoes-parte-1-ronnie-peterson-o-primeiro-iceman-da-formula-1-5932-3\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/eles-nunca-foram-campeoes-parte-1-ronnie-peterson-o-primeiro-iceman-da-formula-1-5932-3\/#primaryimage","url":"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/images\/Coluna%20Ta%20n@%20Rede\/tanarede.jpg","contentUrl":"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/images\/Coluna%20Ta%20n@%20Rede\/tanarede.jpg"},{"@type":"BreadcrumbList","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/eles-nunca-foram-campeoes-parte-1-ronnie-peterson-o-primeiro-iceman-da-formula-1-5932-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/box5640.temp.domains\/~clickfoz\/"},{"@type":"ListItem","position":2,"name":"Eles nunca foram campe&otilde;es &#8211; Parte 1: Ronnie Peterson, o primeiro &quot;Iceman&quot; da F&oacute;rmula 1"}]},{"@type":"WebSite","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#website","url":"https:\/\/box5640.temp.domains\/~clickfoz\/","name":"Click Foz do Igua\u00e7u","description":"O portal de not\u00edcias de Foz do Igua\u00e7u","publisher":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/box5640.temp.domains\/~clickfoz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization","name":"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i","url":"https:\/\/box5640.temp.domains\/~clickfoz\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/","url":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png","contentUrl":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png","width":190,"height":65,"caption":"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i"},"image":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/clickfoz","https:\/\/x.com\/clickfoz","https:\/\/www.instagram.com\/clickfoz"]},{"@type":"Person","@id":"","url":"http:\/\/box5640.temp.domains\/~clickfoz\/author\/"}]}},"_links":{"self":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts\/14150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/comments?post=14150"}],"version-history":[{"count":0,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts\/14150\/revisions"}],"wp:attachment":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/media?parent=14150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/categories?post=14150"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/tags?post=14150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}