{"id":14113,"date":"2010-06-27T00:19:13","date_gmt":"2010-06-27T00:19:13","guid":{"rendered":"http:\/\/localhost:82\/wordpress\/2010\/06\/27\/foz-futsal-e-foz-adeafi-perdem-e-ficam-no-mesmo-grupo-na-segunda-fase-5943-2\/"},"modified":"2010-06-27T00:19:13","modified_gmt":"2010-06-27T00:19:13","slug":"foz-futsal-e-foz-adeafi-perdem-e-ficam-no-mesmo-grupo-na-segunda-fase-5943-2","status":"publish","type":"post","link":"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-e-foz-adeafi-perdem-e-ficam-no-mesmo-grupo-na-segunda-fase-5943-2\/","title":{"rendered":"Foz Futsal e Foz Adeafi perdem e ficam no mesmo grupo na segunda fase"},"content":{"rendered":"<p style=\"text-align: justify\">Oito jogos na noite de s&aacute;bado (26) encerraram a primeira fase do Campeonato Paranaense de Futsal da S&eacute;rie Ouro. Os 12 times classificados para a segunda fase j&aacute; eram conhecidos, os jogos definiram apenas as posi&ccedil;&otilde;es das equipes para a forma&ccedil;&atilde;o dos grupos na sequ&ecirc;ncia do estadual. Agora os times classificados ser&atilde;o divididos em dois grupos de seis cada, jogando entre si em turno e returno. Os quatro primeiros de cada grupo seguem na competi&ccedil;&atilde;o.<\/p>\n<p style=\"text-align: justify\"><strong>Derrotas igua&ccedil;uenses<\/strong> &#8211; Os dois times representantes de Foz do Igua&ccedil;u perderam na rodada. No Gin&aacute;sio Costa Cavalcanti, em Foz, o Foz Futsal perdeu de virada para o Campo Mour&atilde;o, por 3 a 2. Ap&oacute;s Marcelinho ter aberto o placar, Eduardo empatou. Na segunda etapa, o goleiro Boquinha colocou o time visitante na frente do placar. O Foz Futsal voltou a empatar com Mancha, mas quando restavam dois segundos para terminar a partida, o goleiro Boquinha novamente colocou o time mour&atilde;oense na frente do placar. Vit&oacute;ria que fez com que o Campo Mour&atilde;o pulasse da 11&ordf; para 7&ordf; posi&ccedil;&atilde;o, com 21 pontos.<\/p>\n<p style=\"text-align: justify\">Em Itaipul&acirc;ndia, j&aacute; que n&atilde;o teve a libera&ccedil;&atilde;o de outro gin&aacute;sio em Foz por parte da Federa&ccedil;&atilde;o, o Foz Adeafi jogou contra o Marreco Futsal, no Gin&aacute;sio Irineu Luiz Friedrich. E foi o time de Francisco Beltr&atilde;o quem saiu na frente do marcador, logo no come&ccedil;o de partida, com Emerson. O Foz Adeafi empatou com Sidinei e virou com Anderson, em cobran&ccedil;a de falta. S&oacute; que o Marreco voltou a empatar com Alex Maranh&atilde;o. Adeafi desempatou em um belo gol de Anderson, marcando de voleio seu segundo tento da noite. Pretinho empatou novamente e Ronaldo deu vantagem ao time &quot;visitante&quot;. Jonas empatou para Adeafi e Marquinhos deu n&uacute;meros finais ao jogo, fechando o placar em 5 a 4 para o Marreco.<\/p>\n<p style=\"text-align: justify\">Outros resultados da noite foram: Clevel&acirc;ndia 2 x 4 Cascavel; S&atilde;o Miguel 10 x 2 Aqu&aacute;rius; Copagril Maechal 4 x 2 Umuarama; Palotina 1 x 1 Guarapuava; Paran&aacute; 3 x 5 Col&eacute;gio Londrinense; Ciagym Maring&aacute; 4 x 3 S&atilde;o Lucas Paranava&iacute;. Com os resultados o Foz Adeafi termina a primeira fase em 10&ordm; lugar e o Foz Futsal em 12&ordm;.<\/p>\n<p style=\"text-align: justify\">Desta forma o grupo A ficou definido com Copagril (1&ordm;), Marreco (4&ordm;), Ciagym Maring&aacute; (6&ordm;), Umuarama (8&ordm;), Foz Adeafi (10&ordm;) e Foz Futsal (12&ordm;). O grupo B ficou com Guarapuava (2&ordm;), Cascavel (3&ordm;), Col&eacute;gio Londrinense (5&ordm;), Campo Mour&atilde;o (7&ordm;), Paran&aacute; Clube (9&ordm;) e Palotina (11&ordm;). Os jogos da segunda fase ocorrem no s&aacute;bado (3 de julho) exceto para os times que disputam a Liga Nacional, caso de Foz Futsal, Umuarama, Cascavel e Copagril. A Adeafi estreia em casa, no Costa Cavalcanti, &agrave;s 20h30 contra o Marreco.<\/p>\n<p style=\"text-align: justify\"><strong>Jogos 15&ordf; rodada<\/strong><br \/>\nCopagril 4 x 2 Umuarama<br \/>\nS&atilde;o Miguel 10 x 2 Aqu&aacute;rius<br \/>\nPalotina 1 x 1 Guarapuava<br \/>\nCiagym 4 x 3 S&atilde;o Lucas<br \/>\nParan&aacute; 3 x 5 Col&eacute;gio Londrinense<br \/>\nClevel&acirc;ndia 2 x 4 Cascavel<br \/>\nFoz Adeafi 4 x 5 Marreco<br \/>\nFoz Futsal 2 x 3 Campo Mour&atilde;o<\/p>\n<p><strong>Classifica&ccedil;&atilde;o<\/strong> (em negrito os times classificados para segunda fase)<\/p>\n<p style=\"text-align: justify\"><strong>1&ordm; Copagril&#8230;&#8230;&#8230;&#8230;.39<\/strong><\/p>\n<p><strong>2&ordm; Guarapuava&#8230;&#8230;&#8230;..34<\/p>\n<p>3&ordm; Cascavel&#8230;&#8230;&#8230;&#8230;.29<\/p>\n<p>4&ordm; Marreco&#8230;&#8230;&#8230;&#8230;..27<\/p>\n<p>5&ordm; Col. Londrinense&#8230;..26<\/p>\n<p>6&ordm; Ciagym&#8230;&#8230;&#8230;&#8230;&#8230;23<\/p>\n<p>7&ordm; Campo Mour&atilde;o&#8230;&#8230;&#8230;21<\/p>\n<p>8&ordm; Umuarama&#8230;&#8230;&#8230;&#8230;.21<\/p>\n<p>9&ordm; Paran&aacute;&#8230;&#8230;&#8230;&#8230;&#8230;20<\/p>\n<p>10&ordm; Adeafi&#8230;&#8230;&#8230;&#8230;..19<\/p>\n<p>11&ordm; Palotina&#8230;&#8230;&#8230;&#8230;19<\/p>\n<p>12&ordm; Foz Futsal&#8230;&#8230;&#8230;.18<\/strong><\/p>\n<p>&nbsp;13&ordm; S&atilde;o Miguel&#8230;&#8230;&#8230;.15 <\/p>\n<p>14&ordm; S&atilde;o Lucas&#8230;&#8230;&#8230;..12 <\/p>\n<p>15&ordm; Clevel&acirc;ndia&#8230;&#8230;&#8230;09 (rebaixado para a Chave Prata em 2011)<\/p>\n<p>16&ordm; Aqu&aacute;rius&#8230;&#8230;&#8230;&#8230;01 (rebaixado para a Chave Prata em 2011)<\/p>\n<p><strong>Grupo A:<\/strong> Copagril, Marreco, Ciagym, Umuarama, Foz Adeafi e Foz Futsal<br \/>\n<strong>Grupo B:<\/strong> Guarapuava, Cascavel, Col&eacute;gio Londrinense, Campo Mour&atilde;o, Paran&aacute; e Palotina<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oito jogos na noite de s&aacute;bado (26) encerraram a primeira fase do Campeonato Paranaense de Futsal da S&eacute;rie Ouro. Os 12 times classificados para a segunda fase j&aacute; eram conhecidos, os jogos definiram apenas as posi&ccedil;&otilde;es das equipes para a forma&ccedil;&atilde;o dos grupos na sequ&ecirc;ncia do estadual. Agora os times classificados ser&atilde;o divididos em dois [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-14113","post","type-post","status-publish","format-standard","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Foz Futsal e Foz Adeafi perdem e ficam no mesmo grupo na segunda fase - Clickfoz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-e-foz-adeafi-perdem-e-ficam-no-mesmo-grupo-na-segunda-fase-5943-2\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Foz Futsal e Foz Adeafi perdem e ficam no mesmo grupo na segunda fase - Clickfoz\" \/>\n<meta property=\"og:description\" content=\"Oito jogos na noite de s&aacute;bado (26) encerraram a primeira fase do Campeonato Paranaense de Futsal da S&eacute;rie Ouro. Os 12 times classificados para a segunda fase j&aacute; eram conhecidos, os jogos definiram apenas as posi&ccedil;&otilde;es das equipes para a forma&ccedil;&atilde;o dos grupos na sequ&ecirc;ncia do estadual. Agora os times classificados ser&atilde;o divididos em dois [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-e-foz-adeafi-perdem-e-ficam-no-mesmo-grupo-na-segunda-fase-5943-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Clickfoz\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/clickfoz\" \/>\n<meta property=\"article:published_time\" content=\"2010-06-27T00:19:13+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2023\/11\/logo-clickfoz.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@clickfoz\" \/>\n<meta name=\"twitter:site\" content=\"@clickfoz\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-e-foz-adeafi-perdem-e-ficam-no-mesmo-grupo-na-segunda-fase-5943-2\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-e-foz-adeafi-perdem-e-ficam-no-mesmo-grupo-na-segunda-fase-5943-2\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Foz Futsal e Foz Adeafi perdem e ficam no mesmo grupo na segunda fase\",\"datePublished\":\"2010-06-27T00:19:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-e-foz-adeafi-perdem-e-ficam-no-mesmo-grupo-na-segunda-fase-5943-2\/\"},\"wordCount\":672,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-e-foz-adeafi-perdem-e-ficam-no-mesmo-grupo-na-segunda-fase-5943-2\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-e-foz-adeafi-perdem-e-ficam-no-mesmo-grupo-na-segunda-fase-5943-2\/\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-e-foz-adeafi-perdem-e-ficam-no-mesmo-grupo-na-segunda-fase-5943-2\/\",\"name\":\"Foz Futsal e Foz Adeafi perdem e ficam no mesmo grupo na segunda fase - Clickfoz\",\"isPartOf\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#website\"},\"datePublished\":\"2010-06-27T00:19:13+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-e-foz-adeafi-perdem-e-ficam-no-mesmo-grupo-na-segunda-fase-5943-2\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-e-foz-adeafi-perdem-e-ficam-no-mesmo-grupo-na-segunda-fase-5943-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-e-foz-adeafi-perdem-e-ficam-no-mesmo-grupo-na-segunda-fase-5943-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/box5640.temp.domains\/~clickfoz\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Foz Futsal e Foz Adeafi perdem e ficam no mesmo grupo na segunda fase\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#website\",\"url\":\"https:\/\/box5640.temp.domains\/~clickfoz\/\",\"name\":\"Click Foz do Igua\u00e7u\",\"description\":\"O portal de not\u00edcias de Foz do Igua\u00e7u\",\"publisher\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/box5640.temp.domains\/~clickfoz\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\",\"name\":\"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i\",\"url\":\"https:\/\/box5640.temp.domains\/~clickfoz\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png\",\"contentUrl\":\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png\",\"width\":190,\"height\":65,\"caption\":\"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i\"},\"image\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/clickfoz\",\"https:\/\/x.com\/clickfoz\",\"https:\/\/www.instagram.com\/clickfoz\"]},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Foz Futsal e Foz Adeafi perdem e ficam no mesmo grupo na segunda fase - Clickfoz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-e-foz-adeafi-perdem-e-ficam-no-mesmo-grupo-na-segunda-fase-5943-2\/","og_locale":"pt_BR","og_type":"article","og_title":"Foz Futsal e Foz Adeafi perdem e ficam no mesmo grupo na segunda fase - Clickfoz","og_description":"Oito jogos na noite de s&aacute;bado (26) encerraram a primeira fase do Campeonato Paranaense de Futsal da S&eacute;rie Ouro. Os 12 times classificados para a segunda fase j&aacute; eram conhecidos, os jogos definiram apenas as posi&ccedil;&otilde;es das equipes para a forma&ccedil;&atilde;o dos grupos na sequ&ecirc;ncia do estadual. Agora os times classificados ser&atilde;o divididos em dois [&hellip;]","og_url":"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-e-foz-adeafi-perdem-e-ficam-no-mesmo-grupo-na-segunda-fase-5943-2\/","og_site_name":"Clickfoz","article_publisher":"https:\/\/facebook.com\/clickfoz","article_published_time":"2010-06-27T00:19:13+00:00","og_image":[{"width":1200,"height":675,"url":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2023\/11\/logo-clickfoz.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_creator":"@clickfoz","twitter_site":"@clickfoz","twitter_misc":{"Escrito por":"","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-e-foz-adeafi-perdem-e-ficam-no-mesmo-grupo-na-segunda-fase-5943-2\/#article","isPartOf":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-e-foz-adeafi-perdem-e-ficam-no-mesmo-grupo-na-segunda-fase-5943-2\/"},"author":{"name":"","@id":""},"headline":"Foz Futsal e Foz Adeafi perdem e ficam no mesmo grupo na segunda fase","datePublished":"2010-06-27T00:19:13+00:00","mainEntityOfPage":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-e-foz-adeafi-perdem-e-ficam-no-mesmo-grupo-na-segunda-fase-5943-2\/"},"wordCount":672,"commentCount":0,"publisher":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization"},"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-e-foz-adeafi-perdem-e-ficam-no-mesmo-grupo-na-segunda-fase-5943-2\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-e-foz-adeafi-perdem-e-ficam-no-mesmo-grupo-na-segunda-fase-5943-2\/","url":"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-e-foz-adeafi-perdem-e-ficam-no-mesmo-grupo-na-segunda-fase-5943-2\/","name":"Foz Futsal e Foz Adeafi perdem e ficam no mesmo grupo na segunda fase - Clickfoz","isPartOf":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#website"},"datePublished":"2010-06-27T00:19:13+00:00","breadcrumb":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-e-foz-adeafi-perdem-e-ficam-no-mesmo-grupo-na-segunda-fase-5943-2\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-e-foz-adeafi-perdem-e-ficam-no-mesmo-grupo-na-segunda-fase-5943-2\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-e-foz-adeafi-perdem-e-ficam-no-mesmo-grupo-na-segunda-fase-5943-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/box5640.temp.domains\/~clickfoz\/"},{"@type":"ListItem","position":2,"name":"Foz Futsal e Foz Adeafi perdem e ficam no mesmo grupo na segunda fase"}]},{"@type":"WebSite","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#website","url":"https:\/\/box5640.temp.domains\/~clickfoz\/","name":"Click Foz do Igua\u00e7u","description":"O portal de not\u00edcias de Foz do Igua\u00e7u","publisher":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/box5640.temp.domains\/~clickfoz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization","name":"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i","url":"https:\/\/box5640.temp.domains\/~clickfoz\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/","url":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png","contentUrl":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png","width":190,"height":65,"caption":"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i"},"image":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/clickfoz","https:\/\/x.com\/clickfoz","https:\/\/www.instagram.com\/clickfoz"]},{"@type":"Person","@id":"","url":"http:\/\/box5640.temp.domains\/~clickfoz\/author\/"}]}},"_links":{"self":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts\/14113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/comments?post=14113"}],"version-history":[{"count":0,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts\/14113\/revisions"}],"wp:attachment":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/media?parent=14113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/categories?post=14113"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/tags?post=14113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}