{"id":14110,"date":"2010-06-27T13:11:36","date_gmt":"2010-06-27T13:11:36","guid":{"rendered":"http:\/\/localhost:82\/wordpress\/2010\/06\/27\/prefeitura-realizara-treinamento-de-recepcionistas-do-setor-de-saude-5944-2\/"},"modified":"2010-06-27T13:11:36","modified_gmt":"2010-06-27T13:11:36","slug":"prefeitura-realizara-treinamento-de-recepcionistas-do-setor-de-saude-5944-2","status":"publish","type":"post","link":"http:\/\/box5640.temp.domains\/~clickfoz\/prefeitura-realizara-treinamento-de-recepcionistas-do-setor-de-saude-5944-2\/","title":{"rendered":"Prefeitura realizar&aacute; treinamento de recepcionistas do setor de sa&uacute;de"},"content":{"rendered":"<p style=\"text-align: justify\">Durante o programa semanal de r&aacute;dio, no s&aacute;bado (26) o prefeito de Foz do Igua&ccedil;u, Paulo Mac Donald, anunciou que a prefeitura colocar&aacute; em pr&aacute;tica nos pr&oacute;ximos dias um programa de treinamento dos recepcionistas das unidades b&aacute;sicas e demais setores da sa&uacute;de que trabalham diretamente com o p&uacute;blico. A meta &eacute; buscar a excel&ecirc;ncia no atendimento, evitando desorienta&ccedil;&atilde;o e transtornos para os pacientes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante o programa semanal de r&aacute;dio, no s&aacute;bado (26) o prefeito de Foz do Igua&ccedil;u, Paulo Mac Donald, anunciou que a prefeitura colocar&aacute; em pr&aacute;tica nos pr&oacute;ximos dias um programa de treinamento dos recepcionistas das unidades b&aacute;sicas e demais setores da sa&uacute;de que trabalham diretamente com o p&uacute;blico. A meta &eacute; buscar a excel&ecirc;ncia no [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-14110","post","type-post","status-publish","format-standard","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Prefeitura realizar&aacute; treinamento de recepcionistas do setor de sa&uacute;de - Clickfoz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/box5640.temp.domains\/~clickfoz\/prefeitura-realizara-treinamento-de-recepcionistas-do-setor-de-saude-5944-2\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prefeitura realizar&aacute; treinamento de recepcionistas do setor de sa&uacute;de - Clickfoz\" \/>\n<meta property=\"og:description\" content=\"Durante o programa semanal de r&aacute;dio, no s&aacute;bado (26) o prefeito de Foz do Igua&ccedil;u, Paulo Mac Donald, anunciou que a prefeitura colocar&aacute; em pr&aacute;tica nos pr&oacute;ximos dias um programa de treinamento dos recepcionistas das unidades b&aacute;sicas e demais setores da sa&uacute;de que trabalham diretamente com o p&uacute;blico. A meta &eacute; buscar a excel&ecirc;ncia no [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/box5640.temp.domains\/~clickfoz\/prefeitura-realizara-treinamento-de-recepcionistas-do-setor-de-saude-5944-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Clickfoz\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/clickfoz\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/garon.piceli\" \/>\n<meta property=\"article:published_time\" content=\"2010-06-27T13:11:36+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2023\/11\/logo-clickfoz.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Garon Piceli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@garonpiceli\" \/>\n<meta name=\"twitter:site\" content=\"@clickfoz\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Garon Piceli\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/prefeitura-realizara-treinamento-de-recepcionistas-do-setor-de-saude-5944-2\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/prefeitura-realizara-treinamento-de-recepcionistas-do-setor-de-saude-5944-2\/\"},\"author\":{\"name\":\"Garon Piceli\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/person\/1c68351359e4744c29866b9bc7a0bfff\"},\"headline\":\"Prefeitura realizar&aacute; treinamento de recepcionistas do setor de sa&uacute;de\",\"datePublished\":\"2010-06-27T13:11:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/prefeitura-realizara-treinamento-de-recepcionistas-do-setor-de-saude-5944-2\/\"},\"wordCount\":96,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\/\/box5640.temp.domains\/~clickfoz\/prefeitura-realizara-treinamento-de-recepcionistas-do-setor-de-saude-5944-2\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/prefeitura-realizara-treinamento-de-recepcionistas-do-setor-de-saude-5944-2\/\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/prefeitura-realizara-treinamento-de-recepcionistas-do-setor-de-saude-5944-2\/\",\"name\":\"Prefeitura realizar&aacute; treinamento de recepcionistas do setor de sa&uacute;de - Clickfoz\",\"isPartOf\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#website\"},\"datePublished\":\"2010-06-27T13:11:36+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/prefeitura-realizara-treinamento-de-recepcionistas-do-setor-de-saude-5944-2\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/box5640.temp.domains\/~clickfoz\/prefeitura-realizara-treinamento-de-recepcionistas-do-setor-de-saude-5944-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/prefeitura-realizara-treinamento-de-recepcionistas-do-setor-de-saude-5944-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/box5640.temp.domains\/~clickfoz\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prefeitura realizar&aacute; treinamento de recepcionistas do setor de sa&uacute;de\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#website\",\"url\":\"https:\/\/box5640.temp.domains\/~clickfoz\/\",\"name\":\"Click Foz do Igua\u00e7u\",\"description\":\"O portal de not\u00edcias de Foz do Igua\u00e7u\",\"publisher\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/box5640.temp.domains\/~clickfoz\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\",\"name\":\"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i\",\"url\":\"https:\/\/box5640.temp.domains\/~clickfoz\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png\",\"contentUrl\":\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png\",\"width\":190,\"height\":65,\"caption\":\"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i\"},\"image\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/clickfoz\",\"https:\/\/x.com\/clickfoz\",\"https:\/\/www.instagram.com\/clickfoz\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/person\/1c68351359e4744c29866b9bc7a0bfff\",\"name\":\"Garon Piceli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4185832e3322de80868dff0f56e6c20788e54c0fab66a0314b34288fcc3a3fad?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4185832e3322de80868dff0f56e6c20788e54c0fab66a0314b34288fcc3a3fad?s=96&d=mm&r=g\",\"caption\":\"Garon Piceli\"},\"sameAs\":[\"https:\/\/www.facebook.com\/garon.piceli\",\"https:\/\/x.com\/garonpiceli\"],\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/author\/garon\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prefeitura realizar&aacute; treinamento de recepcionistas do setor de sa&uacute;de - Clickfoz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/box5640.temp.domains\/~clickfoz\/prefeitura-realizara-treinamento-de-recepcionistas-do-setor-de-saude-5944-2\/","og_locale":"pt_BR","og_type":"article","og_title":"Prefeitura realizar&aacute; treinamento de recepcionistas do setor de sa&uacute;de - Clickfoz","og_description":"Durante o programa semanal de r&aacute;dio, no s&aacute;bado (26) o prefeito de Foz do Igua&ccedil;u, Paulo Mac Donald, anunciou que a prefeitura colocar&aacute; em pr&aacute;tica nos pr&oacute;ximos dias um programa de treinamento dos recepcionistas das unidades b&aacute;sicas e demais setores da sa&uacute;de que trabalham diretamente com o p&uacute;blico. A meta &eacute; buscar a excel&ecirc;ncia no [&hellip;]","og_url":"http:\/\/box5640.temp.domains\/~clickfoz\/prefeitura-realizara-treinamento-de-recepcionistas-do-setor-de-saude-5944-2\/","og_site_name":"Clickfoz","article_publisher":"https:\/\/facebook.com\/clickfoz","article_author":"https:\/\/www.facebook.com\/garon.piceli","article_published_time":"2010-06-27T13:11:36+00:00","og_image":[{"width":1200,"height":675,"url":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2023\/11\/logo-clickfoz.png","type":"image\/png"}],"author":"Garon Piceli","twitter_card":"summary_large_image","twitter_creator":"@garonpiceli","twitter_site":"@clickfoz","twitter_misc":{"Escrito por":"Garon Piceli"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/prefeitura-realizara-treinamento-de-recepcionistas-do-setor-de-saude-5944-2\/#article","isPartOf":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/prefeitura-realizara-treinamento-de-recepcionistas-do-setor-de-saude-5944-2\/"},"author":{"name":"Garon Piceli","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/person\/1c68351359e4744c29866b9bc7a0bfff"},"headline":"Prefeitura realizar&aacute; treinamento de recepcionistas do setor de sa&uacute;de","datePublished":"2010-06-27T13:11:36+00:00","mainEntityOfPage":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/prefeitura-realizara-treinamento-de-recepcionistas-do-setor-de-saude-5944-2\/"},"wordCount":96,"commentCount":0,"publisher":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization"},"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/box5640.temp.domains\/~clickfoz\/prefeitura-realizara-treinamento-de-recepcionistas-do-setor-de-saude-5944-2\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/prefeitura-realizara-treinamento-de-recepcionistas-do-setor-de-saude-5944-2\/","url":"http:\/\/box5640.temp.domains\/~clickfoz\/prefeitura-realizara-treinamento-de-recepcionistas-do-setor-de-saude-5944-2\/","name":"Prefeitura realizar&aacute; treinamento de recepcionistas do setor de sa&uacute;de - Clickfoz","isPartOf":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#website"},"datePublished":"2010-06-27T13:11:36+00:00","breadcrumb":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/prefeitura-realizara-treinamento-de-recepcionistas-do-setor-de-saude-5944-2\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/box5640.temp.domains\/~clickfoz\/prefeitura-realizara-treinamento-de-recepcionistas-do-setor-de-saude-5944-2\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/prefeitura-realizara-treinamento-de-recepcionistas-do-setor-de-saude-5944-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/box5640.temp.domains\/~clickfoz\/"},{"@type":"ListItem","position":2,"name":"Prefeitura realizar&aacute; treinamento de recepcionistas do setor de sa&uacute;de"}]},{"@type":"WebSite","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#website","url":"https:\/\/box5640.temp.domains\/~clickfoz\/","name":"Click Foz do Igua\u00e7u","description":"O portal de not\u00edcias de Foz do Igua\u00e7u","publisher":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/box5640.temp.domains\/~clickfoz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization","name":"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i","url":"https:\/\/box5640.temp.domains\/~clickfoz\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/","url":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png","contentUrl":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png","width":190,"height":65,"caption":"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i"},"image":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/clickfoz","https:\/\/x.com\/clickfoz","https:\/\/www.instagram.com\/clickfoz"]},{"@type":"Person","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/person\/1c68351359e4744c29866b9bc7a0bfff","name":"Garon Piceli","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/4185832e3322de80868dff0f56e6c20788e54c0fab66a0314b34288fcc3a3fad?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4185832e3322de80868dff0f56e6c20788e54c0fab66a0314b34288fcc3a3fad?s=96&d=mm&r=g","caption":"Garon Piceli"},"sameAs":["https:\/\/www.facebook.com\/garon.piceli","https:\/\/x.com\/garonpiceli"],"url":"http:\/\/box5640.temp.domains\/~clickfoz\/author\/garon\/"}]}},"_links":{"self":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts\/14110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/comments?post=14110"}],"version-history":[{"count":0,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts\/14110\/revisions"}],"wp:attachment":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/media?parent=14110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/categories?post=14110"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/tags?post=14110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}