{"id":14066,"date":"2010-06-28T18:27:58","date_gmt":"2010-06-28T18:27:58","guid":{"rendered":"http:\/\/localhost:82\/wordpress\/2010\/06\/28\/brasil-vence-o-chile-com-folga-no-placar-e-enfrenta-agora-a-holanda-nas-quartas-de-final-5960-2\/"},"modified":"2010-06-28T18:27:58","modified_gmt":"2010-06-28T18:27:58","slug":"brasil-vence-o-chile-com-folga-no-placar-e-enfrenta-agora-a-holanda-nas-quartas-de-final-5960-2","status":"publish","type":"post","link":"http:\/\/box5640.temp.domains\/~clickfoz\/brasil-vence-o-chile-com-folga-no-placar-e-enfrenta-agora-a-holanda-nas-quartas-de-final-5960-2\/","title":{"rendered":"Brasil vence o Chile com folga no placar e enfrenta agora a Holanda nas Quartas-de-Final"},"content":{"rendered":"<p style=\"text-align: justify\">Com uma vit&oacute;ria tranquila por 3 a 0, o Brasil eliminou o Chile e avan&ccedil;ou para as Quartas-de-Final da Copa do Mundo de 2010 na segunda-feira (28), no est&aacute;dio Ellis Park, em Johannesburgo, na &Aacute;frica do Sul.<\/p>\n<p style=\"text-align: justify\">A sele&ccedil;&atilde;o brasileira iniciou a partida das Oitavas-de-Final com mudan&ccedil;as no meio-campo. Sem Elano e Felipe Melo &ndash; ambos machucados &ndash; o t&eacute;cnico Dunga colocou em seus lugares Daniel Alves e Ramires, respectivamente. Ap&oacute;s cumprir suspens&atilde;o contra Portugal no &uacute;ltimo jogo da primeira fase, Kak&aacute; retornou no setor de arma&ccedil;&atilde;o. Nas demais posi&ccedil;&otilde;es, nenhuma mudan&ccedil;a.<\/p>\n<p style=\"text-align: justify\">O primeiro gol do Brasil s&oacute; saiu aos 34 minutos do primeiro tempo. Em cobran&ccedil;a de escanteio, Juan, de cabe&ccedil;a, abriu o placar para o time pentacampe&atilde;o. Tr&ecirc;s minutos depois, aos 37, Luis Fabiano recebeu excelente passe, driblou o goleiro Bravo e&nbsp; ampliou o marcador.<\/p>\n<p style=\"text-align: justify\">Na segunda etapa, aos 14 minutos, Ramires puxou contra-ataque, passou para Robinho, que de primeira mandou no canto esquerdo do goleiro chileno. Um belo gol, fechando o placar em 3 a 0. Dunga promoveu duas estreias na Copa 2010. Kleberson entrou no lugar de Kak&aacute;, que havia tomado um cart&atilde;o amarelo e corria risco de ser expulso novamente e Gilberto no lugar de Robinho. Nilmar foi a terceira substui&ccedil;&atilde;o do jogo, no lugar de Luis Fabiano, por&eacute;m o paranaense j&aacute; atuou nas outras partidas da Copa do Mundo, tendo inclusive come&ccedil;ado como titular contra Portugal.<\/p>\n<p style=\"text-align: justify\">Agora o Brasil enfrentar&aacute; a Holanda, velha conhecida em Copas do Mundo. Em 1994, tamb&eacute;m nas Quartas-de-Final, a sele&ccedil;&atilde;o brasileira enfrentou os holandeses, ficando com o quarto t&iacute;tulo no final. Em 98, o duelo aconteceu nas semifinais, s&oacute; que naquele ano, o Brasil ficou em segundo lugar. O jogo contra a Holanda na Copa 2010 ser&aacute; na sexta-feira (2\/7), &agrave;s 11h, na cidade Port Elizabeth. Quem passar, encara o vencedor de Uruguai e Gana, que jogam no mesmo dia, &agrave;s 15h30.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com uma vit&oacute;ria tranquila por 3 a 0, o Brasil eliminou o Chile e avan&ccedil;ou para as Quartas-de-Final da Copa do Mundo de 2010 na segunda-feira (28), no est&aacute;dio Ellis Park, em Johannesburgo, na &Aacute;frica do Sul. A sele&ccedil;&atilde;o brasileira iniciou a partida das Oitavas-de-Final com mudan&ccedil;as no meio-campo. Sem Elano e Felipe Melo &ndash; [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-14066","post","type-post","status-publish","format-standard","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Brasil vence o Chile com folga no placar e enfrenta agora a Holanda nas Quartas-de-Final - Clickfoz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/box5640.temp.domains\/~clickfoz\/brasil-vence-o-chile-com-folga-no-placar-e-enfrenta-agora-a-holanda-nas-quartas-de-final-5960-2\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Brasil vence o Chile com folga no placar e enfrenta agora a Holanda nas Quartas-de-Final - Clickfoz\" \/>\n<meta property=\"og:description\" content=\"Com uma vit&oacute;ria tranquila por 3 a 0, o Brasil eliminou o Chile e avan&ccedil;ou para as Quartas-de-Final da Copa do Mundo de 2010 na segunda-feira (28), no est&aacute;dio Ellis Park, em Johannesburgo, na &Aacute;frica do Sul. A sele&ccedil;&atilde;o brasileira iniciou a partida das Oitavas-de-Final com mudan&ccedil;as no meio-campo. Sem Elano e Felipe Melo &ndash; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/box5640.temp.domains\/~clickfoz\/brasil-vence-o-chile-com-folga-no-placar-e-enfrenta-agora-a-holanda-nas-quartas-de-final-5960-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Clickfoz\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/clickfoz\" \/>\n<meta property=\"article:published_time\" content=\"2010-06-28T18:27:58+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2023\/11\/logo-clickfoz.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@clickfoz\" \/>\n<meta name=\"twitter:site\" content=\"@clickfoz\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/brasil-vence-o-chile-com-folga-no-placar-e-enfrenta-agora-a-holanda-nas-quartas-de-final-5960-2\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/brasil-vence-o-chile-com-folga-no-placar-e-enfrenta-agora-a-holanda-nas-quartas-de-final-5960-2\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Brasil vence o Chile com folga no placar e enfrenta agora a Holanda nas Quartas-de-Final\",\"datePublished\":\"2010-06-28T18:27:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/brasil-vence-o-chile-com-folga-no-placar-e-enfrenta-agora-a-holanda-nas-quartas-de-final-5960-2\/\"},\"wordCount\":375,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\/\/box5640.temp.domains\/~clickfoz\/brasil-vence-o-chile-com-folga-no-placar-e-enfrenta-agora-a-holanda-nas-quartas-de-final-5960-2\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/brasil-vence-o-chile-com-folga-no-placar-e-enfrenta-agora-a-holanda-nas-quartas-de-final-5960-2\/\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/brasil-vence-o-chile-com-folga-no-placar-e-enfrenta-agora-a-holanda-nas-quartas-de-final-5960-2\/\",\"name\":\"Brasil vence o Chile com folga no placar e enfrenta agora a Holanda nas Quartas-de-Final - Clickfoz\",\"isPartOf\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#website\"},\"datePublished\":\"2010-06-28T18:27:58+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/brasil-vence-o-chile-com-folga-no-placar-e-enfrenta-agora-a-holanda-nas-quartas-de-final-5960-2\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/box5640.temp.domains\/~clickfoz\/brasil-vence-o-chile-com-folga-no-placar-e-enfrenta-agora-a-holanda-nas-quartas-de-final-5960-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/brasil-vence-o-chile-com-folga-no-placar-e-enfrenta-agora-a-holanda-nas-quartas-de-final-5960-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/box5640.temp.domains\/~clickfoz\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Brasil vence o Chile com folga no placar e enfrenta agora a Holanda nas Quartas-de-Final\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#website\",\"url\":\"https:\/\/box5640.temp.domains\/~clickfoz\/\",\"name\":\"Click Foz do Igua\u00e7u\",\"description\":\"O portal de not\u00edcias de Foz do Igua\u00e7u\",\"publisher\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/box5640.temp.domains\/~clickfoz\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\",\"name\":\"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i\",\"url\":\"https:\/\/box5640.temp.domains\/~clickfoz\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png\",\"contentUrl\":\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png\",\"width\":190,\"height\":65,\"caption\":\"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i\"},\"image\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/clickfoz\",\"https:\/\/x.com\/clickfoz\",\"https:\/\/www.instagram.com\/clickfoz\"]},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Brasil vence o Chile com folga no placar e enfrenta agora a Holanda nas Quartas-de-Final - Clickfoz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/box5640.temp.domains\/~clickfoz\/brasil-vence-o-chile-com-folga-no-placar-e-enfrenta-agora-a-holanda-nas-quartas-de-final-5960-2\/","og_locale":"pt_BR","og_type":"article","og_title":"Brasil vence o Chile com folga no placar e enfrenta agora a Holanda nas Quartas-de-Final - Clickfoz","og_description":"Com uma vit&oacute;ria tranquila por 3 a 0, o Brasil eliminou o Chile e avan&ccedil;ou para as Quartas-de-Final da Copa do Mundo de 2010 na segunda-feira (28), no est&aacute;dio Ellis Park, em Johannesburgo, na &Aacute;frica do Sul. A sele&ccedil;&atilde;o brasileira iniciou a partida das Oitavas-de-Final com mudan&ccedil;as no meio-campo. Sem Elano e Felipe Melo &ndash; [&hellip;]","og_url":"http:\/\/box5640.temp.domains\/~clickfoz\/brasil-vence-o-chile-com-folga-no-placar-e-enfrenta-agora-a-holanda-nas-quartas-de-final-5960-2\/","og_site_name":"Clickfoz","article_publisher":"https:\/\/facebook.com\/clickfoz","article_published_time":"2010-06-28T18:27:58+00:00","og_image":[{"width":1200,"height":675,"url":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2023\/11\/logo-clickfoz.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_creator":"@clickfoz","twitter_site":"@clickfoz","twitter_misc":{"Escrito por":"","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/brasil-vence-o-chile-com-folga-no-placar-e-enfrenta-agora-a-holanda-nas-quartas-de-final-5960-2\/#article","isPartOf":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/brasil-vence-o-chile-com-folga-no-placar-e-enfrenta-agora-a-holanda-nas-quartas-de-final-5960-2\/"},"author":{"name":"","@id":""},"headline":"Brasil vence o Chile com folga no placar e enfrenta agora a Holanda nas Quartas-de-Final","datePublished":"2010-06-28T18:27:58+00:00","mainEntityOfPage":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/brasil-vence-o-chile-com-folga-no-placar-e-enfrenta-agora-a-holanda-nas-quartas-de-final-5960-2\/"},"wordCount":375,"commentCount":0,"publisher":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization"},"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/box5640.temp.domains\/~clickfoz\/brasil-vence-o-chile-com-folga-no-placar-e-enfrenta-agora-a-holanda-nas-quartas-de-final-5960-2\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/brasil-vence-o-chile-com-folga-no-placar-e-enfrenta-agora-a-holanda-nas-quartas-de-final-5960-2\/","url":"http:\/\/box5640.temp.domains\/~clickfoz\/brasil-vence-o-chile-com-folga-no-placar-e-enfrenta-agora-a-holanda-nas-quartas-de-final-5960-2\/","name":"Brasil vence o Chile com folga no placar e enfrenta agora a Holanda nas Quartas-de-Final - Clickfoz","isPartOf":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#website"},"datePublished":"2010-06-28T18:27:58+00:00","breadcrumb":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/brasil-vence-o-chile-com-folga-no-placar-e-enfrenta-agora-a-holanda-nas-quartas-de-final-5960-2\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/box5640.temp.domains\/~clickfoz\/brasil-vence-o-chile-com-folga-no-placar-e-enfrenta-agora-a-holanda-nas-quartas-de-final-5960-2\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/brasil-vence-o-chile-com-folga-no-placar-e-enfrenta-agora-a-holanda-nas-quartas-de-final-5960-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/box5640.temp.domains\/~clickfoz\/"},{"@type":"ListItem","position":2,"name":"Brasil vence o Chile com folga no placar e enfrenta agora a Holanda nas Quartas-de-Final"}]},{"@type":"WebSite","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#website","url":"https:\/\/box5640.temp.domains\/~clickfoz\/","name":"Click Foz do Igua\u00e7u","description":"O portal de not\u00edcias de Foz do Igua\u00e7u","publisher":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/box5640.temp.domains\/~clickfoz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization","name":"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i","url":"https:\/\/box5640.temp.domains\/~clickfoz\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/","url":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png","contentUrl":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png","width":190,"height":65,"caption":"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i"},"image":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/clickfoz","https:\/\/x.com\/clickfoz","https:\/\/www.instagram.com\/clickfoz"]},{"@type":"Person","@id":"","url":"http:\/\/box5640.temp.domains\/~clickfoz\/author\/"}]}},"_links":{"self":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts\/14066","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/comments?post=14066"}],"version-history":[{"count":0,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts\/14066\/revisions"}],"wp:attachment":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/media?parent=14066"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/categories?post=14066"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/tags?post=14066"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}