{"id":14021,"date":"2010-07-02T15:36:38","date_gmt":"2010-07-02T15:36:38","guid":{"rendered":"http:\/\/localhost:82\/wordpress\/2010\/07\/02\/assim-como-em-2006-brasil-volta-a-ser-eliminado-nas-quartas-de-final-da-copa-do-mundo-6000\/"},"modified":"2010-07-02T15:36:38","modified_gmt":"2010-07-02T15:36:38","slug":"assim-como-em-2006-brasil-volta-a-ser-eliminado-nas-quartas-de-final-da-copa-do-mundo-6000","status":"publish","type":"post","link":"http:\/\/box5640.temp.domains\/~clickfoz\/assim-como-em-2006-brasil-volta-a-ser-eliminado-nas-quartas-de-final-da-copa-do-mundo-6000\/","title":{"rendered":"Assim como em 2006, Brasil volta a ser eliminado nas quartas de final da Copa do Mundo"},"content":{"rendered":"<p style=\"text-align: justify\">O pa&iacute;s sede foi diferente, o treinador da sele&ccedil;&atilde;o brasileira era diferente, alguns jogadores eram diferentes. O final, acabou sendo o mesmo. Assim como em 2006, o Brasil perde para uma sele&ccedil;&atilde;o europeia nas quartas de final da Copa do Mundo 2010. Se h&aacute; quatro anos o algoz foi a Fran&ccedil;a, em 2010 os respons&aacute;veis pela elimina&ccedil;&atilde;o brasileira foram os holandeses.<\/p>\n<p style=\"text-align: justify\">Com uma vit&oacute;ria de virada por 2 a 1, na sexta-feira (2) &ndash; gol contra de Felipe Melo e outro de Sneijder, com Robinho fazendo o &uacute;nico tento verde-amarelo &ndash; a Holanda avan&ccedil;a para agora enfrentar nas semifinais o vencedor de Uruguai ou Gana, que jogam ainda na sexta, &agrave;s 15h30.<\/p>\n<p style=\"text-align: justify\"><strong>O jogo<\/strong> &ndash; O time comandado pelo t&eacute;cnico Dunga come&ccedil;ou a partida de forma avassaladora. Logo no come&ccedil;o, o Brasil teve um gol corretamente anulado pelo &aacute;rbitro japon&ecirc;s, Yuichi Nishimura. Poucos minutos depois, outro gol, desta vez validado.<\/p>\n<p style=\"text-align: justify\">Felipe Melo fez bom passe pelo meio, encontrando Robinho por tr&aacute;s da zaga. O atacante do Santos bateu de primeira na bola, abrindo o placar para a sele&ccedil;&atilde;o canarinho. E poderia ter sido mais, tamanha era a facilidade com que o Brasil jogava diante da Holanda no primeiro tempo.<\/p>\n<p style=\"text-align: justify\">No entanto, os holandeses responderam r&aacute;pido. Kuyt quase empatou, assim que seu time tomou o primeiro gol. A sele&ccedil;&atilde;o brasileira respondeu com Juan. Ap&oacute;s cobran&ccedil;a de escanteio, o zagueiro mandou por cima do gol. Em um dos raros lances de Kak&aacute;, bastante apagado na partida, o meia do Real Madrid chutou preciso pro gol, o goleiro holand&ecirc;s fez uma bela defesa.<\/p>\n<p style=\"text-align: justify\">Ainda na primeira etapa do jogo, Maicon, pela lateral direita, arriscou (assim como fizera na estreia, contra a Coreia do Norte), mas ficou na defesa do goleiro Stekelenburg. Contra os norte-coreanos, conseguiu fazer o gol.<\/p>\n<p style=\"text-align: justify\"><strong>Rea&ccedil;&atilde;o holandesa <\/strong>&ndash; No segundo tempo, veio a rea&ccedil;&atilde;o da Holanda. Aos oito minutos, em uma falta pela direita, Sneijder levantou para dentro da &aacute;rea. Uma bola que parecia ser f&aacute;cil para o goleiro Julio C&eacute;sar, n&atilde;o fosse atrapalhado pelo jogador Felipe Melo. O jogador da Juventus ainda acabou raspando a cabe&ccedil;a na &ldquo;jabulani&rdquo; e ela foi para o fundo das redes.<\/p>\n<p style=\"text-align: justify\">O jogo estava empatado e o Brasil, aos poucos, foi perdendo a raz&atilde;o. Esteve perto de ter Michel Bastos expulso, j&aacute; que havia levado cart&atilde;o amarelo na primeira etapa. Dunga o substituiu por Gilberto. Aos 22 minutos, em cobran&ccedil;a de escanteio, a bola foi desviada para Sneijder (sempre ele) tamb&eacute;m com a cabe&ccedil;a, virar o placar, fazendo 2 a 1.<\/p>\n<p style=\"text-align: justify\">Se a situa&ccedil;&atilde;o j&aacute; estava ruim, ficou ainda pior com e expuls&atilde;o de Felipe Melo. Com 28 minutos, o meio-campista fez falta, seguido por uma pisada em Robben. O &aacute;rbitro viu, n&atilde;o pensou duas vezes, e mostrou o cart&atilde;o vermelho. O tempo foi passando, e o empate n&atilde;o veio e a Holanda conseguiu, assim como em 1974, eliminar o Brasil e seguir adiante para as semifinais, tentando conquistar o primeiro t&iacute;tulo mundial. Ao Brasil, resta esperar a Copa de 2014, a ser disputada no pr&oacute;prio pa&iacute;s, para tentar o sexto t&iacute;tulo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O pa&iacute;s sede foi diferente, o treinador da sele&ccedil;&atilde;o brasileira era diferente, alguns jogadores eram diferentes. O final, acabou sendo o mesmo. Assim como em 2006, o Brasil perde para uma sele&ccedil;&atilde;o europeia nas quartas de final da Copa do Mundo 2010. Se h&aacute; quatro anos o algoz foi a Fran&ccedil;a, em 2010 os respons&aacute;veis [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-14021","post","type-post","status-publish","format-standard","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Assim como em 2006, Brasil volta a ser eliminado nas quartas de final da Copa do Mundo - Clickfoz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/box5640.temp.domains\/~clickfoz\/assim-como-em-2006-brasil-volta-a-ser-eliminado-nas-quartas-de-final-da-copa-do-mundo-6000\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Assim como em 2006, Brasil volta a ser eliminado nas quartas de final da Copa do Mundo - Clickfoz\" \/>\n<meta property=\"og:description\" content=\"O pa&iacute;s sede foi diferente, o treinador da sele&ccedil;&atilde;o brasileira era diferente, alguns jogadores eram diferentes. O final, acabou sendo o mesmo. Assim como em 2006, o Brasil perde para uma sele&ccedil;&atilde;o europeia nas quartas de final da Copa do Mundo 2010. Se h&aacute; quatro anos o algoz foi a Fran&ccedil;a, em 2010 os respons&aacute;veis [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/box5640.temp.domains\/~clickfoz\/assim-como-em-2006-brasil-volta-a-ser-eliminado-nas-quartas-de-final-da-copa-do-mundo-6000\/\" \/>\n<meta property=\"og:site_name\" content=\"Clickfoz\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/clickfoz\" \/>\n<meta property=\"article:published_time\" content=\"2010-07-02T15:36:38+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2023\/11\/logo-clickfoz.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@clickfoz\" \/>\n<meta name=\"twitter:site\" content=\"@clickfoz\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/assim-como-em-2006-brasil-volta-a-ser-eliminado-nas-quartas-de-final-da-copa-do-mundo-6000\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/assim-como-em-2006-brasil-volta-a-ser-eliminado-nas-quartas-de-final-da-copa-do-mundo-6000\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Assim como em 2006, Brasil volta a ser eliminado nas quartas de final da Copa do Mundo\",\"datePublished\":\"2010-07-02T15:36:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/assim-como-em-2006-brasil-volta-a-ser-eliminado-nas-quartas-de-final-da-copa-do-mundo-6000\/\"},\"wordCount\":609,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\/\/box5640.temp.domains\/~clickfoz\/assim-como-em-2006-brasil-volta-a-ser-eliminado-nas-quartas-de-final-da-copa-do-mundo-6000\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/assim-como-em-2006-brasil-volta-a-ser-eliminado-nas-quartas-de-final-da-copa-do-mundo-6000\/\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/assim-como-em-2006-brasil-volta-a-ser-eliminado-nas-quartas-de-final-da-copa-do-mundo-6000\/\",\"name\":\"Assim como em 2006, Brasil volta a ser eliminado nas quartas de final da Copa do Mundo - Clickfoz\",\"isPartOf\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#website\"},\"datePublished\":\"2010-07-02T15:36:38+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/assim-como-em-2006-brasil-volta-a-ser-eliminado-nas-quartas-de-final-da-copa-do-mundo-6000\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/box5640.temp.domains\/~clickfoz\/assim-como-em-2006-brasil-volta-a-ser-eliminado-nas-quartas-de-final-da-copa-do-mundo-6000\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/assim-como-em-2006-brasil-volta-a-ser-eliminado-nas-quartas-de-final-da-copa-do-mundo-6000\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/box5640.temp.domains\/~clickfoz\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Assim como em 2006, Brasil volta a ser eliminado nas quartas de final da Copa do Mundo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#website\",\"url\":\"https:\/\/box5640.temp.domains\/~clickfoz\/\",\"name\":\"Click Foz do Igua\u00e7u\",\"description\":\"O portal de not\u00edcias de Foz do Igua\u00e7u\",\"publisher\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/box5640.temp.domains\/~clickfoz\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\",\"name\":\"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i\",\"url\":\"https:\/\/box5640.temp.domains\/~clickfoz\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png\",\"contentUrl\":\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png\",\"width\":190,\"height\":65,\"caption\":\"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i\"},\"image\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/clickfoz\",\"https:\/\/x.com\/clickfoz\",\"https:\/\/www.instagram.com\/clickfoz\"]},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Assim como em 2006, Brasil volta a ser eliminado nas quartas de final da Copa do Mundo - Clickfoz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/box5640.temp.domains\/~clickfoz\/assim-como-em-2006-brasil-volta-a-ser-eliminado-nas-quartas-de-final-da-copa-do-mundo-6000\/","og_locale":"pt_BR","og_type":"article","og_title":"Assim como em 2006, Brasil volta a ser eliminado nas quartas de final da Copa do Mundo - Clickfoz","og_description":"O pa&iacute;s sede foi diferente, o treinador da sele&ccedil;&atilde;o brasileira era diferente, alguns jogadores eram diferentes. O final, acabou sendo o mesmo. Assim como em 2006, o Brasil perde para uma sele&ccedil;&atilde;o europeia nas quartas de final da Copa do Mundo 2010. Se h&aacute; quatro anos o algoz foi a Fran&ccedil;a, em 2010 os respons&aacute;veis [&hellip;]","og_url":"http:\/\/box5640.temp.domains\/~clickfoz\/assim-como-em-2006-brasil-volta-a-ser-eliminado-nas-quartas-de-final-da-copa-do-mundo-6000\/","og_site_name":"Clickfoz","article_publisher":"https:\/\/facebook.com\/clickfoz","article_published_time":"2010-07-02T15:36:38+00:00","og_image":[{"width":1200,"height":675,"url":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2023\/11\/logo-clickfoz.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_creator":"@clickfoz","twitter_site":"@clickfoz","twitter_misc":{"Escrito por":"","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/assim-como-em-2006-brasil-volta-a-ser-eliminado-nas-quartas-de-final-da-copa-do-mundo-6000\/#article","isPartOf":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/assim-como-em-2006-brasil-volta-a-ser-eliminado-nas-quartas-de-final-da-copa-do-mundo-6000\/"},"author":{"name":"","@id":""},"headline":"Assim como em 2006, Brasil volta a ser eliminado nas quartas de final da Copa do Mundo","datePublished":"2010-07-02T15:36:38+00:00","mainEntityOfPage":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/assim-como-em-2006-brasil-volta-a-ser-eliminado-nas-quartas-de-final-da-copa-do-mundo-6000\/"},"wordCount":609,"commentCount":0,"publisher":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization"},"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/box5640.temp.domains\/~clickfoz\/assim-como-em-2006-brasil-volta-a-ser-eliminado-nas-quartas-de-final-da-copa-do-mundo-6000\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/assim-como-em-2006-brasil-volta-a-ser-eliminado-nas-quartas-de-final-da-copa-do-mundo-6000\/","url":"http:\/\/box5640.temp.domains\/~clickfoz\/assim-como-em-2006-brasil-volta-a-ser-eliminado-nas-quartas-de-final-da-copa-do-mundo-6000\/","name":"Assim como em 2006, Brasil volta a ser eliminado nas quartas de final da Copa do Mundo - Clickfoz","isPartOf":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#website"},"datePublished":"2010-07-02T15:36:38+00:00","breadcrumb":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/assim-como-em-2006-brasil-volta-a-ser-eliminado-nas-quartas-de-final-da-copa-do-mundo-6000\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/box5640.temp.domains\/~clickfoz\/assim-como-em-2006-brasil-volta-a-ser-eliminado-nas-quartas-de-final-da-copa-do-mundo-6000\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/assim-como-em-2006-brasil-volta-a-ser-eliminado-nas-quartas-de-final-da-copa-do-mundo-6000\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/box5640.temp.domains\/~clickfoz\/"},{"@type":"ListItem","position":2,"name":"Assim como em 2006, Brasil volta a ser eliminado nas quartas de final da Copa do Mundo"}]},{"@type":"WebSite","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#website","url":"https:\/\/box5640.temp.domains\/~clickfoz\/","name":"Click Foz do Igua\u00e7u","description":"O portal de not\u00edcias de Foz do Igua\u00e7u","publisher":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/box5640.temp.domains\/~clickfoz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization","name":"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i","url":"https:\/\/box5640.temp.domains\/~clickfoz\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/","url":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png","contentUrl":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png","width":190,"height":65,"caption":"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i"},"image":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/clickfoz","https:\/\/x.com\/clickfoz","https:\/\/www.instagram.com\/clickfoz"]},{"@type":"Person","@id":"","url":"http:\/\/box5640.temp.domains\/~clickfoz\/author\/"}]}},"_links":{"self":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts\/14021","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/comments?post=14021"}],"version-history":[{"count":0,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts\/14021\/revisions"}],"wp:attachment":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/media?parent=14021"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/categories?post=14021"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/tags?post=14021"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}