{"id":13991,"date":"2010-07-05T17:08:51","date_gmt":"2010-07-05T17:08:51","guid":{"rendered":"http:\/\/localhost:82\/wordpress\/2010\/07\/05\/chefe-do-parque-recebe-homenagem-do-corpo-de-bombeiros-6030\/"},"modified":"2010-07-05T17:08:51","modified_gmt":"2010-07-05T17:08:51","slug":"chefe-do-parque-recebe-homenagem-do-corpo-de-bombeiros-6030","status":"publish","type":"post","link":"http:\/\/box5640.temp.domains\/~clickfoz\/chefe-do-parque-recebe-homenagem-do-corpo-de-bombeiros-6030\/","title":{"rendered":"Chefe do Parque Nacional do Igua&ccedil;u recebe homenagem do Corpo de Bombeiros"},"content":{"rendered":"<div style=\"text-align: justify\">O chefe do Parque Nacional do Igua&ccedil;u, Jorge Pegoraro, foi um dos homenageados pelo 5&ordm; Grupamento de Bombeiros (GB), na sexta-feira (2), com a Medalha de Honra Presidente Carlos Cavalcanti de Albuquerque, um reconhecimento a pessoas que contribuem com a corpora&ccedil;&atilde;o.<\/div>\n<div style=\"text-align: justify\">&nbsp;<\/div>\n<div style=\"text-align: justify\">A homenagem foi realizada durante a troca de comando do 5&ordm; GB em Maring&aacute; (PR). &nbsp;O coronel Jurandi Andr&eacute; deixou o comando e assumiu o tenente coronel Ant&ocirc;nio Luiz Ferreira da Silva.<\/div>\n<div style=\"text-align: justify\">\n<table cellspacing=\"0\" cellpadding=\"0\" border=\"0\" width=\"200\" style=\"margin: 0 3px\">\n<tbody>\n<tr>\n<td style=\"text-align: right\">Foto: Assessoria<\/td>\n<\/tr>\n<tr>\n<td bgcolor=\"#f4f4f2\"><img fetchpriority=\"high\" decoding=\"async\" height=\"458\" width=\"610\" alt=\"\" src=\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/Jorge%20corpo%20de%20bombeiros.jpeg\" \/><\/td>\n<\/tr>\n<tr>\n<td bgcolor=\"#f4f4f2\" style=\"padding-top: 3px;padding-right: 1px;padding-bottom: 3px;padding-left: 1px;font-size: 11px;text-align: center\">\n<p>            O major Marcos Ant&ocirc;nio Jahnke e Jorge Pegoraro                          <\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: justify\">\nTamb&eacute;m foram homenageados os coron&eacute;is Mauro Pirolo e Antonio Aurelio Alves Chaves da Concei&ccedil;&atilde;o, o prefeito de Maring&aacute;, Silvio Barros, o coordenador do SAMU de Apucarana, Rodrigo Cezar Faria e o membro do Conselho Diretor do Funrebom de Umuarama, Abdo Hallu Neto. &ldquo;Agradecemos a todos que de alguma forma colaboraram pelo desempenho do Corpo de Bombeiros do Paran&aacute;&rdquo;, afirmou o coronel Jurandi Andr&eacute;. O evento marcou tamb&eacute;m o Dia Nacional dos Bombeiros.<\/p>\n<p>A homenagem ao chefe do Parque foi proposta pelo major Marcos Ant&ocirc;nio Jahnke, comandante do Grupamento de Bombeiros de Foz do Igua&ccedil;u, ao considerar as muitas a&ccedil;&otilde;es realizadas em conjunto e do apoio do Parque Nacional ao Grupamento de Foz do Igua&ccedil;u. O evento marcou tamb&eacute;m o Dia Nacional dos Bombeiros.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>O chefe do Parque Nacional do Igua&ccedil;u, Jorge Pegoraro, foi um dos homenageados pelo 5&ordm; Grupamento de Bombeiros (GB), na sexta-feira (2), com a Medalha de Honra Presidente Carlos Cavalcanti de Albuquerque, um reconhecimento a pessoas que contribuem com a corpora&ccedil;&atilde;o. &nbsp; A homenagem foi realizada durante a troca de comando do 5&ordm; GB em [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-13991","post","type-post","status-publish","format-standard","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Chefe do Parque Nacional do Igua&ccedil;u recebe homenagem do Corpo de Bombeiros - Clickfoz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/box5640.temp.domains\/~clickfoz\/chefe-do-parque-recebe-homenagem-do-corpo-de-bombeiros-6030\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chefe do Parque Nacional do Igua&ccedil;u recebe homenagem do Corpo de Bombeiros - Clickfoz\" \/>\n<meta property=\"og:description\" content=\"O chefe do Parque Nacional do Igua&ccedil;u, Jorge Pegoraro, foi um dos homenageados pelo 5&ordm; Grupamento de Bombeiros (GB), na sexta-feira (2), com a Medalha de Honra Presidente Carlos Cavalcanti de Albuquerque, um reconhecimento a pessoas que contribuem com a corpora&ccedil;&atilde;o. &nbsp; A homenagem foi realizada durante a troca de comando do 5&ordm; GB em [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/box5640.temp.domains\/~clickfoz\/chefe-do-parque-recebe-homenagem-do-corpo-de-bombeiros-6030\/\" \/>\n<meta property=\"og:site_name\" content=\"Clickfoz\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/clickfoz\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/garon.piceli\" \/>\n<meta property=\"article:published_time\" content=\"2010-07-05T17:08:51+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/Jorge%20corpo%20de%20bombeiros.jpeg\" \/>\n<meta name=\"author\" content=\"Garon Piceli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@garonpiceli\" \/>\n<meta name=\"twitter:site\" content=\"@clickfoz\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Garon Piceli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/chefe-do-parque-recebe-homenagem-do-corpo-de-bombeiros-6030\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/chefe-do-parque-recebe-homenagem-do-corpo-de-bombeiros-6030\/\"},\"author\":{\"name\":\"Garon Piceli\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/person\/1c68351359e4744c29866b9bc7a0bfff\"},\"headline\":\"Chefe do Parque Nacional do Igua&ccedil;u recebe homenagem do Corpo de Bombeiros\",\"datePublished\":\"2010-07-05T17:08:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/chefe-do-parque-recebe-homenagem-do-corpo-de-bombeiros-6030\/\"},\"wordCount\":257,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\"},\"image\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/chefe-do-parque-recebe-homenagem-do-corpo-de-bombeiros-6030\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/Jorge%20corpo%20de%20bombeiros.jpeg\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\/\/box5640.temp.domains\/~clickfoz\/chefe-do-parque-recebe-homenagem-do-corpo-de-bombeiros-6030\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/chefe-do-parque-recebe-homenagem-do-corpo-de-bombeiros-6030\/\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/chefe-do-parque-recebe-homenagem-do-corpo-de-bombeiros-6030\/\",\"name\":\"Chefe do Parque Nacional do Igua&ccedil;u recebe homenagem do Corpo de Bombeiros - Clickfoz\",\"isPartOf\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/chefe-do-parque-recebe-homenagem-do-corpo-de-bombeiros-6030\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/chefe-do-parque-recebe-homenagem-do-corpo-de-bombeiros-6030\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/Jorge%20corpo%20de%20bombeiros.jpeg\",\"datePublished\":\"2010-07-05T17:08:51+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/chefe-do-parque-recebe-homenagem-do-corpo-de-bombeiros-6030\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/box5640.temp.domains\/~clickfoz\/chefe-do-parque-recebe-homenagem-do-corpo-de-bombeiros-6030\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/chefe-do-parque-recebe-homenagem-do-corpo-de-bombeiros-6030\/#primaryimage\",\"url\":\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/Jorge%20corpo%20de%20bombeiros.jpeg\",\"contentUrl\":\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/Jorge%20corpo%20de%20bombeiros.jpeg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/chefe-do-parque-recebe-homenagem-do-corpo-de-bombeiros-6030\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/box5640.temp.domains\/~clickfoz\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chefe do Parque Nacional do Igua&ccedil;u recebe homenagem do Corpo de Bombeiros\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#website\",\"url\":\"https:\/\/box5640.temp.domains\/~clickfoz\/\",\"name\":\"Click Foz do Igua\u00e7u\",\"description\":\"O portal de not\u00edcias de Foz do Igua\u00e7u\",\"publisher\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/box5640.temp.domains\/~clickfoz\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\",\"name\":\"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i\",\"url\":\"https:\/\/box5640.temp.domains\/~clickfoz\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png\",\"contentUrl\":\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png\",\"width\":190,\"height\":65,\"caption\":\"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i\"},\"image\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/clickfoz\",\"https:\/\/x.com\/clickfoz\",\"https:\/\/www.instagram.com\/clickfoz\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/person\/1c68351359e4744c29866b9bc7a0bfff\",\"name\":\"Garon Piceli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4185832e3322de80868dff0f56e6c20788e54c0fab66a0314b34288fcc3a3fad?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4185832e3322de80868dff0f56e6c20788e54c0fab66a0314b34288fcc3a3fad?s=96&d=mm&r=g\",\"caption\":\"Garon Piceli\"},\"sameAs\":[\"https:\/\/www.facebook.com\/garon.piceli\",\"https:\/\/x.com\/garonpiceli\"],\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/author\/garon\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chefe do Parque Nacional do Igua&ccedil;u recebe homenagem do Corpo de Bombeiros - Clickfoz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/box5640.temp.domains\/~clickfoz\/chefe-do-parque-recebe-homenagem-do-corpo-de-bombeiros-6030\/","og_locale":"pt_BR","og_type":"article","og_title":"Chefe do Parque Nacional do Igua&ccedil;u recebe homenagem do Corpo de Bombeiros - Clickfoz","og_description":"O chefe do Parque Nacional do Igua&ccedil;u, Jorge Pegoraro, foi um dos homenageados pelo 5&ordm; Grupamento de Bombeiros (GB), na sexta-feira (2), com a Medalha de Honra Presidente Carlos Cavalcanti de Albuquerque, um reconhecimento a pessoas que contribuem com a corpora&ccedil;&atilde;o. &nbsp; A homenagem foi realizada durante a troca de comando do 5&ordm; GB em [&hellip;]","og_url":"http:\/\/box5640.temp.domains\/~clickfoz\/chefe-do-parque-recebe-homenagem-do-corpo-de-bombeiros-6030\/","og_site_name":"Clickfoz","article_publisher":"https:\/\/facebook.com\/clickfoz","article_author":"https:\/\/www.facebook.com\/garon.piceli","article_published_time":"2010-07-05T17:08:51+00:00","og_image":[{"url":"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/Jorge%20corpo%20de%20bombeiros.jpeg","type":"","width":"","height":""}],"author":"Garon Piceli","twitter_card":"summary_large_image","twitter_creator":"@garonpiceli","twitter_site":"@clickfoz","twitter_misc":{"Escrito por":"Garon Piceli","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/chefe-do-parque-recebe-homenagem-do-corpo-de-bombeiros-6030\/#article","isPartOf":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/chefe-do-parque-recebe-homenagem-do-corpo-de-bombeiros-6030\/"},"author":{"name":"Garon Piceli","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/person\/1c68351359e4744c29866b9bc7a0bfff"},"headline":"Chefe do Parque Nacional do Igua&ccedil;u recebe homenagem do Corpo de Bombeiros","datePublished":"2010-07-05T17:08:51+00:00","mainEntityOfPage":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/chefe-do-parque-recebe-homenagem-do-corpo-de-bombeiros-6030\/"},"wordCount":257,"commentCount":0,"publisher":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization"},"image":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/chefe-do-parque-recebe-homenagem-do-corpo-de-bombeiros-6030\/#primaryimage"},"thumbnailUrl":"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/Jorge%20corpo%20de%20bombeiros.jpeg","inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/box5640.temp.domains\/~clickfoz\/chefe-do-parque-recebe-homenagem-do-corpo-de-bombeiros-6030\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/chefe-do-parque-recebe-homenagem-do-corpo-de-bombeiros-6030\/","url":"http:\/\/box5640.temp.domains\/~clickfoz\/chefe-do-parque-recebe-homenagem-do-corpo-de-bombeiros-6030\/","name":"Chefe do Parque Nacional do Igua&ccedil;u recebe homenagem do Corpo de Bombeiros - Clickfoz","isPartOf":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#website"},"primaryImageOfPage":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/chefe-do-parque-recebe-homenagem-do-corpo-de-bombeiros-6030\/#primaryimage"},"image":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/chefe-do-parque-recebe-homenagem-do-corpo-de-bombeiros-6030\/#primaryimage"},"thumbnailUrl":"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/Jorge%20corpo%20de%20bombeiros.jpeg","datePublished":"2010-07-05T17:08:51+00:00","breadcrumb":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/chefe-do-parque-recebe-homenagem-do-corpo-de-bombeiros-6030\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/box5640.temp.domains\/~clickfoz\/chefe-do-parque-recebe-homenagem-do-corpo-de-bombeiros-6030\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/chefe-do-parque-recebe-homenagem-do-corpo-de-bombeiros-6030\/#primaryimage","url":"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/Jorge%20corpo%20de%20bombeiros.jpeg","contentUrl":"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/Jorge%20corpo%20de%20bombeiros.jpeg"},{"@type":"BreadcrumbList","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/chefe-do-parque-recebe-homenagem-do-corpo-de-bombeiros-6030\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/box5640.temp.domains\/~clickfoz\/"},{"@type":"ListItem","position":2,"name":"Chefe do Parque Nacional do Igua&ccedil;u recebe homenagem do Corpo de Bombeiros"}]},{"@type":"WebSite","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#website","url":"https:\/\/box5640.temp.domains\/~clickfoz\/","name":"Click Foz do Igua\u00e7u","description":"O portal de not\u00edcias de Foz do Igua\u00e7u","publisher":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/box5640.temp.domains\/~clickfoz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization","name":"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i","url":"https:\/\/box5640.temp.domains\/~clickfoz\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/","url":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png","contentUrl":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png","width":190,"height":65,"caption":"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i"},"image":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/clickfoz","https:\/\/x.com\/clickfoz","https:\/\/www.instagram.com\/clickfoz"]},{"@type":"Person","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/person\/1c68351359e4744c29866b9bc7a0bfff","name":"Garon Piceli","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/4185832e3322de80868dff0f56e6c20788e54c0fab66a0314b34288fcc3a3fad?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4185832e3322de80868dff0f56e6c20788e54c0fab66a0314b34288fcc3a3fad?s=96&d=mm&r=g","caption":"Garon Piceli"},"sameAs":["https:\/\/www.facebook.com\/garon.piceli","https:\/\/x.com\/garonpiceli"],"url":"http:\/\/box5640.temp.domains\/~clickfoz\/author\/garon\/"}]}},"_links":{"self":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts\/13991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/comments?post=13991"}],"version-history":[{"count":0,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts\/13991\/revisions"}],"wp:attachment":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/media?parent=13991"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/categories?post=13991"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/tags?post=13991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}