{"id":13977,"date":"2010-07-07T11:45:03","date_gmt":"2010-07-07T11:45:03","guid":{"rendered":"http:\/\/localhost:82\/wordpress\/2010\/07\/07\/congresso-nacional-de-hotelaria-acontece-em-agosto-6045\/"},"modified":"2010-07-07T11:45:03","modified_gmt":"2010-07-07T11:45:03","slug":"congresso-nacional-de-hotelaria-acontece-em-agosto-6045","status":"publish","type":"post","link":"http:\/\/box5640.temp.domains\/~clickfoz\/congresso-nacional-de-hotelaria-acontece-em-agosto-6045\/","title":{"rendered":"Congresso Nacional de Hotelaria acontece em agosto"},"content":{"rendered":"<div>\n<div style=\"text-align: justify\">Entre os dias 17 e 19 de agosto, no Centro de Conven&ccedil;&otilde;es Sul Am&eacute;rica, o Rio de Janeiro sediar&aacute; a 52&ordf; edi&ccedil;&atilde;o do Congresso Nacional de Hotelaria &#8211; Conotel 2010, promovido&nbsp;pela ABIH Nacional.<br \/>\n&nbsp;<\/div>\n<div style=\"text-align: justify\">O tema deste ano &eacute; &ldquo;O Brasil &eacute; a bola da vez&rdquo;, com foco nas transforma&ccedil;&otilde;es que o pais obrigatoriamente ter&aacute; que passar com a conquista da sede de grandes eventos&nbsp;mundiais, como a Copa do Mundo e as Olimp&iacute;adas.<\/p>\n<p>&ldquo;Os eventos que acontecer&atilde;o no pa&iacute;s ter&atilde;o impacto em v&aacute;rios setores da economia, com destaque para o turismo. Por isso, o setor precisa se planejar e agir&nbsp;estrategicamente para realizar com m&aacute;xima compet&ecirc;ncia sua fun&ccedil;&atilde;o de receber bem os turistas que chegar&atilde;o ao pa&iacute;s&rdquo;, explica &Aacute;lvaro Bezerra de Mello, presidente da ABIH&nbsp;Nacional.&nbsp;<\/p><\/div>\n<div style=\"text-align: justify\">&nbsp;<\/div>\n<div style=\"text-align: justify\"><strong>Programa&ccedil;&atilde;o &#8211; <\/strong>A organiza&ccedil;&atilde;o do Conotel 2010 j&aacute; definiu os convidados e os temas a serem apresentados e discutidos no evento em agosto. &ldquo;A grade tem&aacute;tica, com foco na&nbsp;Sustentabilidade Negocial da Hotelaria Brasileira, est&aacute; bem sofisticada e vai ao encontro das expectativas do mercado brasileiro e as demandas do mercado&nbsp;internacional&rdquo;, afirma Bezerra de Mello, presidente da entidade.<\/p>\n<p>Est&aacute; confirmada a presen&ccedil;a do economista e palestrante internacional Carlos Langoni, ex-presidente do Banco Central, que falar&aacute; sobre o mercado econ&ocirc;mico no Brasil. Tamb&eacute;m foram convidados os presidenci&aacute;veis Dilma Rousseff e Jos&eacute; Serra. Os candidatos a presid&ecirc;ncia da rep&uacute;blica falar&atilde;o, nas tardes dos dias 17 e 18 de agosto,&nbsp;sobre os planos que pretendem colocar em pr&aacute;tica para a ind&uacute;stria do turismo caso sejam eleitos.<\/p><\/div>\n<div style=\"text-align: justify\">&nbsp;<\/div>\n<div style=\"text-align: justify\">O evento tamb&eacute;m ter&aacute; a presen&ccedil;a de l&iacute;deres de entidade e consultores internacionais de mercados que j&aacute; viveram a experi&ecirc;ncia de sediar Copas do Mundo, al&eacute;m de&nbsp;especialistas que falar&atilde;o sobre a import&acirc;ncia de aliar estrat&eacute;gia a tecnologia e a pr&aacute;tica. No painel &ldquo;Vale a pena reformar meu hotel&rdquo;, por exemplo, especialistas em&nbsp;retrofit e consultores falar&atilde;o sobre como renovar um hotel atendendo &agrave;s regras de sustentabilidade.<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Entre os dias 17 e 19 de agosto, no Centro de Conven&ccedil;&otilde;es Sul Am&eacute;rica, o Rio de Janeiro sediar&aacute; a 52&ordf; edi&ccedil;&atilde;o do Congresso Nacional de Hotelaria &#8211; Conotel 2010, promovido&nbsp;pela ABIH Nacional. &nbsp; O tema deste ano &eacute; &ldquo;O Brasil &eacute; a bola da vez&rdquo;, com foco nas transforma&ccedil;&otilde;es que o pais obrigatoriamente ter&aacute; [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-13977","post","type-post","status-publish","format-standard","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Congresso Nacional de Hotelaria acontece em agosto - Clickfoz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/box5640.temp.domains\/~clickfoz\/congresso-nacional-de-hotelaria-acontece-em-agosto-6045\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Congresso Nacional de Hotelaria acontece em agosto - Clickfoz\" \/>\n<meta property=\"og:description\" content=\"Entre os dias 17 e 19 de agosto, no Centro de Conven&ccedil;&otilde;es Sul Am&eacute;rica, o Rio de Janeiro sediar&aacute; a 52&ordf; edi&ccedil;&atilde;o do Congresso Nacional de Hotelaria &#8211; Conotel 2010, promovido&nbsp;pela ABIH Nacional. &nbsp; O tema deste ano &eacute; &ldquo;O Brasil &eacute; a bola da vez&rdquo;, com foco nas transforma&ccedil;&otilde;es que o pais obrigatoriamente ter&aacute; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/box5640.temp.domains\/~clickfoz\/congresso-nacional-de-hotelaria-acontece-em-agosto-6045\/\" \/>\n<meta property=\"og:site_name\" content=\"Clickfoz\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/clickfoz\" \/>\n<meta property=\"article:published_time\" content=\"2010-07-07T11:45:03+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2023\/11\/logo-clickfoz.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@clickfoz\" \/>\n<meta name=\"twitter:site\" content=\"@clickfoz\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/congresso-nacional-de-hotelaria-acontece-em-agosto-6045\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/congresso-nacional-de-hotelaria-acontece-em-agosto-6045\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Congresso Nacional de Hotelaria acontece em agosto\",\"datePublished\":\"2010-07-07T11:45:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/congresso-nacional-de-hotelaria-acontece-em-agosto-6045\/\"},\"wordCount\":429,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/box5640.temp.domains\/~clickfoz\/congresso-nacional-de-hotelaria-acontece-em-agosto-6045\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/congresso-nacional-de-hotelaria-acontece-em-agosto-6045\/\",\"url\":\"https:\/\/box5640.temp.domains\/~clickfoz\/congresso-nacional-de-hotelaria-acontece-em-agosto-6045\/\",\"name\":\"Congresso Nacional de Hotelaria acontece em agosto - Clickfoz\",\"isPartOf\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#website\"},\"datePublished\":\"2010-07-07T11:45:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/congresso-nacional-de-hotelaria-acontece-em-agosto-6045\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/box5640.temp.domains\/~clickfoz\/congresso-nacional-de-hotelaria-acontece-em-agosto-6045\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/congresso-nacional-de-hotelaria-acontece-em-agosto-6045\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/box5640.temp.domains\/~clickfoz\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Congresso Nacional de Hotelaria acontece em agosto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#website\",\"url\":\"https:\/\/box5640.temp.domains\/~clickfoz\/\",\"name\":\"Click Foz do Igua\u00e7u\",\"description\":\"O portal de not\u00edcias de Foz do Igua\u00e7u\",\"publisher\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/box5640.temp.domains\/~clickfoz\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\",\"name\":\"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i\",\"url\":\"https:\/\/box5640.temp.domains\/~clickfoz\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png\",\"contentUrl\":\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png\",\"width\":190,\"height\":65,\"caption\":\"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i\"},\"image\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/clickfoz\",\"https:\/\/x.com\/clickfoz\",\"https:\/\/www.instagram.com\/clickfoz\"]},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Congresso Nacional de Hotelaria acontece em agosto - Clickfoz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/box5640.temp.domains\/~clickfoz\/congresso-nacional-de-hotelaria-acontece-em-agosto-6045\/","og_locale":"pt_BR","og_type":"article","og_title":"Congresso Nacional de Hotelaria acontece em agosto - Clickfoz","og_description":"Entre os dias 17 e 19 de agosto, no Centro de Conven&ccedil;&otilde;es Sul Am&eacute;rica, o Rio de Janeiro sediar&aacute; a 52&ordf; edi&ccedil;&atilde;o do Congresso Nacional de Hotelaria &#8211; Conotel 2010, promovido&nbsp;pela ABIH Nacional. &nbsp; O tema deste ano &eacute; &ldquo;O Brasil &eacute; a bola da vez&rdquo;, com foco nas transforma&ccedil;&otilde;es que o pais obrigatoriamente ter&aacute; [&hellip;]","og_url":"https:\/\/box5640.temp.domains\/~clickfoz\/congresso-nacional-de-hotelaria-acontece-em-agosto-6045\/","og_site_name":"Clickfoz","article_publisher":"https:\/\/facebook.com\/clickfoz","article_published_time":"2010-07-07T11:45:03+00:00","og_image":[{"width":1200,"height":675,"url":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2023\/11\/logo-clickfoz.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_creator":"@clickfoz","twitter_site":"@clickfoz","twitter_misc":{"Escrito por":"","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/congresso-nacional-de-hotelaria-acontece-em-agosto-6045\/#article","isPartOf":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/congresso-nacional-de-hotelaria-acontece-em-agosto-6045\/"},"author":{"name":"","@id":""},"headline":"Congresso Nacional de Hotelaria acontece em agosto","datePublished":"2010-07-07T11:45:03+00:00","mainEntityOfPage":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/congresso-nacional-de-hotelaria-acontece-em-agosto-6045\/"},"wordCount":429,"commentCount":0,"publisher":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization"},"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/box5640.temp.domains\/~clickfoz\/congresso-nacional-de-hotelaria-acontece-em-agosto-6045\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/congresso-nacional-de-hotelaria-acontece-em-agosto-6045\/","url":"https:\/\/box5640.temp.domains\/~clickfoz\/congresso-nacional-de-hotelaria-acontece-em-agosto-6045\/","name":"Congresso Nacional de Hotelaria acontece em agosto - Clickfoz","isPartOf":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#website"},"datePublished":"2010-07-07T11:45:03+00:00","breadcrumb":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/congresso-nacional-de-hotelaria-acontece-em-agosto-6045\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/box5640.temp.domains\/~clickfoz\/congresso-nacional-de-hotelaria-acontece-em-agosto-6045\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/congresso-nacional-de-hotelaria-acontece-em-agosto-6045\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/box5640.temp.domains\/~clickfoz\/"},{"@type":"ListItem","position":2,"name":"Congresso Nacional de Hotelaria acontece em agosto"}]},{"@type":"WebSite","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#website","url":"https:\/\/box5640.temp.domains\/~clickfoz\/","name":"Click Foz do Igua\u00e7u","description":"O portal de not\u00edcias de Foz do Igua\u00e7u","publisher":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/box5640.temp.domains\/~clickfoz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization","name":"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i","url":"https:\/\/box5640.temp.domains\/~clickfoz\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/","url":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png","contentUrl":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png","width":190,"height":65,"caption":"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i"},"image":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/clickfoz","https:\/\/x.com\/clickfoz","https:\/\/www.instagram.com\/clickfoz"]},{"@type":"Person","@id":"","url":"http:\/\/box5640.temp.domains\/~clickfoz\/author\/"}]}},"_links":{"self":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts\/13977","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/comments?post=13977"}],"version-history":[{"count":0,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts\/13977\/revisions"}],"wp:attachment":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/media?parent=13977"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/categories?post=13977"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/tags?post=13977"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}