{"id":13875,"date":"2010-07-14T18:26:45","date_gmt":"2010-07-14T18:26:45","guid":{"rendered":"http:\/\/localhost:82\/wordpress\/2010\/07\/14\/federacao-paranaense-confirma-jogo-entre-foz-fc-x-lusa-para-o-estadio-do-abc-6149\/"},"modified":"2010-07-14T18:26:45","modified_gmt":"2010-07-14T18:26:45","slug":"federacao-paranaense-confirma-jogo-entre-foz-fc-x-lusa-para-o-estadio-do-abc-6149","status":"publish","type":"post","link":"http:\/\/box5640.temp.domains\/~clickfoz\/federacao-paranaense-confirma-jogo-entre-foz-fc-x-lusa-para-o-estadio-do-abc-6149\/","title":{"rendered":"Federa&ccedil;&atilde;o Paranaense confirma jogo entre Foz FC x Lusa para o est&aacute;dio do ABC"},"content":{"rendered":"<p style=\"text-align: justify\">Foi confirmado na tarde de quarta-feira (14) pela Federa&ccedil;&atilde;o Paranaense de Futebol (FPF) que o jogo entre Foz do Igua&ccedil;u Futebol Clube e Portuguesa Londrinense ser&aacute; mesmo no est&aacute;dio do ABC, em Foz, no domingo (18), &agrave;s 15h45. A partida &eacute; v&aacute;lida pela terceira rodada da segunda fase do Campeonato Paranaense de Futebol da Segunda Divis&atilde;o.<\/p>\n<p style=\"text-align: justify\">O Foz Futebol Clube est&aacute; na segunda posi&ccedil;&atilde;o, com cinco pontos. Perde a lideran&ccedil;a para o Roma de Apucarana apenas pelos gols marcados (3 a 2). A Portuguesa Londrinense vem logo atr&aacute;s, em terceiro lugar, com quatro pontos. O time de Londrina vem embalado ap&oacute;s a vit&oacute;ria por 2 a 0 sobre o S&atilde;o Jos&eacute;, fora de casa. J&aacute; o time igua&ccedil;uense busca a recupera&ccedil;&atilde;o ap&oacute;s o empate em Arapongas por 1 a 1.<\/p>\n<p style=\"text-align: justify\">A princ&iacute;pio, a partida entre Foz e Portuguesa estava sem local definido. Isto porque um laudo da vigil&acirc;ncia sanit&aacute;ria estava vencido. Mas de acordo o diretor financeiro do Foz Futebol Clube, Arif Osman, o problema j&aacute; foi resolvido. Outra quest&atilde;o que tamb&eacute;m impedia a realiza&ccedil;&atilde;o da partida no est&aacute;dio do ABC, &eacute; que um fiscal da FPF apontou irregularidades na venda de ingressos por parte da diretoria igua&ccedil;uense.<\/p>\n<p style=\"text-align: justify\">De acordo com o fiscal, ingressos que n&atilde;o foram fornecidos pela FPF eram vendidos ilegalmente. Um exemplo est&aacute; na cobran&ccedil;a para as cadeiras. Elas s&atilde;o cobradas &agrave; parte. Por&eacute;m, Arif Osman confirmou que a partir de agora, os ingressos para as cadeiras ser&atilde;o vendidos na bilheteria do est&aacute;dio ao pre&ccedil;o de R$ 20. Ingresso normal segue com o valor de R$ 10 para homens e R$ 5 para mulheres e estudantes mediante apresenta&ccedil;&atilde;o de carteirinha. Crian&ccedil;as de at&eacute; dez anos n&atilde;o pagam.<\/p>\n<p style=\"text-align: justify\"><strong>Jogos da 3&ordf; rodada da 2&ordf; fase<\/strong><br \/>\nDomingo, 18 de julho<br \/>\n15h S&atilde;o Jos&eacute; x Campo Mour&atilde;o<br \/>\n15h15 Arapongas x Roma de Apucarana<br \/>\n15h45 Foz Futebol Clube x Portuguesa Londrinense<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foi confirmado na tarde de quarta-feira (14) pela Federa&ccedil;&atilde;o Paranaense de Futebol (FPF) que o jogo entre Foz do Igua&ccedil;u Futebol Clube e Portuguesa Londrinense ser&aacute; mesmo no est&aacute;dio do ABC, em Foz, no domingo (18), &agrave;s 15h45. A partida &eacute; v&aacute;lida pela terceira rodada da segunda fase do Campeonato Paranaense de Futebol da Segunda [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-13875","post","type-post","status-publish","format-standard","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Federa&ccedil;&atilde;o Paranaense confirma jogo entre Foz FC x Lusa para o est&aacute;dio do ABC - Clickfoz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/box5640.temp.domains\/~clickfoz\/federacao-paranaense-confirma-jogo-entre-foz-fc-x-lusa-para-o-estadio-do-abc-6149\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Federa&ccedil;&atilde;o Paranaense confirma jogo entre Foz FC x Lusa para o est&aacute;dio do ABC - Clickfoz\" \/>\n<meta property=\"og:description\" content=\"Foi confirmado na tarde de quarta-feira (14) pela Federa&ccedil;&atilde;o Paranaense de Futebol (FPF) que o jogo entre Foz do Igua&ccedil;u Futebol Clube e Portuguesa Londrinense ser&aacute; mesmo no est&aacute;dio do ABC, em Foz, no domingo (18), &agrave;s 15h45. A partida &eacute; v&aacute;lida pela terceira rodada da segunda fase do Campeonato Paranaense de Futebol da Segunda [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/box5640.temp.domains\/~clickfoz\/federacao-paranaense-confirma-jogo-entre-foz-fc-x-lusa-para-o-estadio-do-abc-6149\/\" \/>\n<meta property=\"og:site_name\" content=\"Clickfoz\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/clickfoz\" \/>\n<meta property=\"article:published_time\" content=\"2010-07-14T18:26:45+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2023\/11\/logo-clickfoz.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@clickfoz\" \/>\n<meta name=\"twitter:site\" content=\"@clickfoz\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/federacao-paranaense-confirma-jogo-entre-foz-fc-x-lusa-para-o-estadio-do-abc-6149\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/federacao-paranaense-confirma-jogo-entre-foz-fc-x-lusa-para-o-estadio-do-abc-6149\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Federa&ccedil;&atilde;o Paranaense confirma jogo entre Foz FC x Lusa para o est&aacute;dio do ABC\",\"datePublished\":\"2010-07-14T18:26:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/federacao-paranaense-confirma-jogo-entre-foz-fc-x-lusa-para-o-estadio-do-abc-6149\/\"},\"wordCount\":399,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\/\/box5640.temp.domains\/~clickfoz\/federacao-paranaense-confirma-jogo-entre-foz-fc-x-lusa-para-o-estadio-do-abc-6149\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/federacao-paranaense-confirma-jogo-entre-foz-fc-x-lusa-para-o-estadio-do-abc-6149\/\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/federacao-paranaense-confirma-jogo-entre-foz-fc-x-lusa-para-o-estadio-do-abc-6149\/\",\"name\":\"Federa&ccedil;&atilde;o Paranaense confirma jogo entre Foz FC x Lusa para o est&aacute;dio do ABC - Clickfoz\",\"isPartOf\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#website\"},\"datePublished\":\"2010-07-14T18:26:45+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/federacao-paranaense-confirma-jogo-entre-foz-fc-x-lusa-para-o-estadio-do-abc-6149\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/box5640.temp.domains\/~clickfoz\/federacao-paranaense-confirma-jogo-entre-foz-fc-x-lusa-para-o-estadio-do-abc-6149\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/federacao-paranaense-confirma-jogo-entre-foz-fc-x-lusa-para-o-estadio-do-abc-6149\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/box5640.temp.domains\/~clickfoz\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Federa&ccedil;&atilde;o Paranaense confirma jogo entre Foz FC x Lusa para o est&aacute;dio do ABC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#website\",\"url\":\"https:\/\/box5640.temp.domains\/~clickfoz\/\",\"name\":\"Click Foz do Igua\u00e7u\",\"description\":\"O portal de not\u00edcias de Foz do Igua\u00e7u\",\"publisher\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/box5640.temp.domains\/~clickfoz\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\",\"name\":\"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i\",\"url\":\"https:\/\/box5640.temp.domains\/~clickfoz\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png\",\"contentUrl\":\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png\",\"width\":190,\"height\":65,\"caption\":\"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i\"},\"image\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/clickfoz\",\"https:\/\/x.com\/clickfoz\",\"https:\/\/www.instagram.com\/clickfoz\"]},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Federa&ccedil;&atilde;o Paranaense confirma jogo entre Foz FC x Lusa para o est&aacute;dio do ABC - Clickfoz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/box5640.temp.domains\/~clickfoz\/federacao-paranaense-confirma-jogo-entre-foz-fc-x-lusa-para-o-estadio-do-abc-6149\/","og_locale":"pt_BR","og_type":"article","og_title":"Federa&ccedil;&atilde;o Paranaense confirma jogo entre Foz FC x Lusa para o est&aacute;dio do ABC - Clickfoz","og_description":"Foi confirmado na tarde de quarta-feira (14) pela Federa&ccedil;&atilde;o Paranaense de Futebol (FPF) que o jogo entre Foz do Igua&ccedil;u Futebol Clube e Portuguesa Londrinense ser&aacute; mesmo no est&aacute;dio do ABC, em Foz, no domingo (18), &agrave;s 15h45. A partida &eacute; v&aacute;lida pela terceira rodada da segunda fase do Campeonato Paranaense de Futebol da Segunda [&hellip;]","og_url":"http:\/\/box5640.temp.domains\/~clickfoz\/federacao-paranaense-confirma-jogo-entre-foz-fc-x-lusa-para-o-estadio-do-abc-6149\/","og_site_name":"Clickfoz","article_publisher":"https:\/\/facebook.com\/clickfoz","article_published_time":"2010-07-14T18:26:45+00:00","og_image":[{"width":1200,"height":675,"url":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2023\/11\/logo-clickfoz.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_creator":"@clickfoz","twitter_site":"@clickfoz","twitter_misc":{"Escrito por":"","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/federacao-paranaense-confirma-jogo-entre-foz-fc-x-lusa-para-o-estadio-do-abc-6149\/#article","isPartOf":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/federacao-paranaense-confirma-jogo-entre-foz-fc-x-lusa-para-o-estadio-do-abc-6149\/"},"author":{"name":"","@id":""},"headline":"Federa&ccedil;&atilde;o Paranaense confirma jogo entre Foz FC x Lusa para o est&aacute;dio do ABC","datePublished":"2010-07-14T18:26:45+00:00","mainEntityOfPage":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/federacao-paranaense-confirma-jogo-entre-foz-fc-x-lusa-para-o-estadio-do-abc-6149\/"},"wordCount":399,"commentCount":0,"publisher":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization"},"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/box5640.temp.domains\/~clickfoz\/federacao-paranaense-confirma-jogo-entre-foz-fc-x-lusa-para-o-estadio-do-abc-6149\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/federacao-paranaense-confirma-jogo-entre-foz-fc-x-lusa-para-o-estadio-do-abc-6149\/","url":"http:\/\/box5640.temp.domains\/~clickfoz\/federacao-paranaense-confirma-jogo-entre-foz-fc-x-lusa-para-o-estadio-do-abc-6149\/","name":"Federa&ccedil;&atilde;o Paranaense confirma jogo entre Foz FC x Lusa para o est&aacute;dio do ABC - Clickfoz","isPartOf":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#website"},"datePublished":"2010-07-14T18:26:45+00:00","breadcrumb":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/federacao-paranaense-confirma-jogo-entre-foz-fc-x-lusa-para-o-estadio-do-abc-6149\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/box5640.temp.domains\/~clickfoz\/federacao-paranaense-confirma-jogo-entre-foz-fc-x-lusa-para-o-estadio-do-abc-6149\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/federacao-paranaense-confirma-jogo-entre-foz-fc-x-lusa-para-o-estadio-do-abc-6149\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/box5640.temp.domains\/~clickfoz\/"},{"@type":"ListItem","position":2,"name":"Federa&ccedil;&atilde;o Paranaense confirma jogo entre Foz FC x Lusa para o est&aacute;dio do ABC"}]},{"@type":"WebSite","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#website","url":"https:\/\/box5640.temp.domains\/~clickfoz\/","name":"Click Foz do Igua\u00e7u","description":"O portal de not\u00edcias de Foz do Igua\u00e7u","publisher":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/box5640.temp.domains\/~clickfoz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization","name":"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i","url":"https:\/\/box5640.temp.domains\/~clickfoz\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/","url":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png","contentUrl":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png","width":190,"height":65,"caption":"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i"},"image":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/clickfoz","https:\/\/x.com\/clickfoz","https:\/\/www.instagram.com\/clickfoz"]},{"@type":"Person","@id":"","url":"http:\/\/box5640.temp.domains\/~clickfoz\/author\/"}]}},"_links":{"self":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts\/13875","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/comments?post=13875"}],"version-history":[{"count":0,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts\/13875\/revisions"}],"wp:attachment":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/media?parent=13875"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/categories?post=13875"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/tags?post=13875"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}