{"id":13846,"date":"2010-07-16T16:27:23","date_gmt":"2010-07-16T16:27:23","guid":{"rendered":"http:\/\/localhost:82\/wordpress\/2010\/07\/16\/foz-adeafi-tem-encontro-decisivo-contra-o-ciagym-maringa-no-sabado-17-6197\/"},"modified":"2010-07-16T16:27:23","modified_gmt":"2010-07-16T16:27:23","slug":"foz-adeafi-tem-encontro-decisivo-contra-o-ciagym-maringa-no-sabado-17-6197","status":"publish","type":"post","link":"http:\/\/box5640.temp.domains\/~clickfoz\/foz-adeafi-tem-encontro-decisivo-contra-o-ciagym-maringa-no-sabado-17-6197\/","title":{"rendered":"Foz Adeafi tem encontro decisivo contra o Ciagym Maring&aacute; no s&aacute;bado (17)"},"content":{"rendered":"<p style=\"text-align: justify\">O Foz do Igua&ccedil;u Adeafi recebe o Ciagym Maring&aacute; no s&aacute;bado (17) lutando para sair da lanterna do Grupo A da segunda fase da Chave Ouro do Campeonato Paranaese. Com duas derrotas em dois jogos, o confronto contra o Ciagym Maring&aacute; &eacute; considerado fundamental para a equipe igua&ccedil;uense manter as chances de classifica&ccedil;&atilde;o para a terceira fase. A partida ser&aacute; realizada &agrave;s 20h30, no gin&aacute;sio Costa Cavalcanti e os ingressos ser&atilde;o vendidos apenas no hor&aacute;rio da partida a R$ 5.<\/p>\n<p>Enfrentando uma situa&ccedil;&atilde;o delicada na competi&ccedil;&atilde;o, o t&eacute;cnico S&eacute;rgio Narvaez ter&aacute; uma novidade na escala&ccedil;&atilde;o para o jogo de s&aacute;bado. O ala, e capit&atilde;o da equipe, Edjan retorna &agrave; equipe ap&oacute;s cumprir suspens&atilde;o autom&aacute;tica na derrota da Adeafi para o Copagril\/Marechal por 3 a 2 na &uacute;ltima rodada, disputada s&aacute;bado (10).<\/p>\n<p>&ldquo;O retorno de Edjan &eacute; um grande refor&ccedil;o para n&oacute;s. Ele &eacute; o jogador que dita o ritmo da nossa equipe, al&eacute;m de ser muito importante no nosso sistema defensivo&rdquo;, comentou o t&eacute;cnico. Apesar da derrota para o Copagril\/Marechal, Narvaez elogiou a postura da equipe e acredita que uma atua&ccedil;&atilde;o semelhante dar&aacute; a vit&oacute;ria a equipe igua&ccedil;uense. &ldquo;Mesmo com a derrota, fizemos um grande jogo e tivemos boas chances de vencer. Por isso, temos que entrar focados em nos defender bem e jogar com vontade diante de nossa torcida&rdquo;, afirmou. <\/p>\n<p>Para o t&eacute;cnico, a presen&ccedil;a do torcedor tamb&eacute;m poder&aacute; fazer a diferen&ccedil;a no jogo contra o Ciagym. &ldquo;Temos que saber fazer o torcedor jogar junto com a gente. Entrar em quadra com determina&ccedil;&atilde;o e garra para que possamos incendiar quem vier at&eacute; o Costa Cavalcanti&rdquo;, comentou. <\/p>\n<p>Destaques da equipes nas &uacute;ltimas partidas, Anderson e Henrique s&atilde;o as grandes apostas na tentativa da Adeafi em deixar a lanterna do Grupo A. Com seis gols em seis jogos, Anderson &eacute; um dos vice-artilheiros da equipe na Chave Ouro. J&aacute; Henrique, tamb&eacute;m autor de seis gols, vem sendo umas das principais armas ofensivas do time igua&ccedil;uense.&nbsp; &ldquo;Espero que possamos fazer um grande jogo para retribuir o carinho que o torcedor vem nos dando mesmo nesse momento ruim&rdquo;, afimou Anderson.<\/p>\n<p>Na primeira fase, as duas equipes se enfrentaram em um jogo bastante tumultuado no gin&aacute;sio da ACEMA, em Maring&aacute;. A partida, que acabou em um empate por 3 a 3, contou com tr&ecirc;s expuls&otilde;es e agress&otilde;es f&iacute;sicas de jogadores da equipe de Maring&aacute; a membros da diretoria do Foz Adeafi. <\/p>\n<p>Para o jogo de s&aacute;bado, as &uacute;nicas baixas da Adeafi s&atilde;o as do goleiro Ilb&eacute;rio, que se recupera de um estiramento posterior na coxa direita, e Banana, que est&aacute; em fase final de recupera&ccedil;&atilde;o ap&oacute;s uma les&atilde;o no p&eacute; direito. A Adeafi vai &agrave; quadra com: Cris, Henrique Rafagnin, Oito Meia, Henrique, Jonas, Neto, Anderson, Edjan, Luan, Silmar, Roger e Sidnei Ribeiro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Foz do Igua&ccedil;u Adeafi recebe o Ciagym Maring&aacute; no s&aacute;bado (17) lutando para sair da lanterna do Grupo A da segunda fase da Chave Ouro do Campeonato Paranaese. Com duas derrotas em dois jogos, o confronto contra o Ciagym Maring&aacute; &eacute; considerado fundamental para a equipe igua&ccedil;uense manter as chances de classifica&ccedil;&atilde;o para a [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-13846","post","type-post","status-publish","format-standard","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Foz Adeafi tem encontro decisivo contra o Ciagym Maring&aacute; no s&aacute;bado (17) - Clickfoz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-adeafi-tem-encontro-decisivo-contra-o-ciagym-maringa-no-sabado-17-6197\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Foz Adeafi tem encontro decisivo contra o Ciagym Maring&aacute; no s&aacute;bado (17) - Clickfoz\" \/>\n<meta property=\"og:description\" content=\"O Foz do Igua&ccedil;u Adeafi recebe o Ciagym Maring&aacute; no s&aacute;bado (17) lutando para sair da lanterna do Grupo A da segunda fase da Chave Ouro do Campeonato Paranaese. Com duas derrotas em dois jogos, o confronto contra o Ciagym Maring&aacute; &eacute; considerado fundamental para a equipe igua&ccedil;uense manter as chances de classifica&ccedil;&atilde;o para a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-adeafi-tem-encontro-decisivo-contra-o-ciagym-maringa-no-sabado-17-6197\/\" \/>\n<meta property=\"og:site_name\" content=\"Clickfoz\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/clickfoz\" \/>\n<meta property=\"article:published_time\" content=\"2010-07-16T16:27:23+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2023\/11\/logo-clickfoz.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@clickfoz\" \/>\n<meta name=\"twitter:site\" content=\"@clickfoz\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-adeafi-tem-encontro-decisivo-contra-o-ciagym-maringa-no-sabado-17-6197\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-adeafi-tem-encontro-decisivo-contra-o-ciagym-maringa-no-sabado-17-6197\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Foz Adeafi tem encontro decisivo contra o Ciagym Maring&aacute; no s&aacute;bado (17)\",\"datePublished\":\"2010-07-16T16:27:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-adeafi-tem-encontro-decisivo-contra-o-ciagym-maringa-no-sabado-17-6197\/\"},\"wordCount\":588,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-adeafi-tem-encontro-decisivo-contra-o-ciagym-maringa-no-sabado-17-6197\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-adeafi-tem-encontro-decisivo-contra-o-ciagym-maringa-no-sabado-17-6197\/\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-adeafi-tem-encontro-decisivo-contra-o-ciagym-maringa-no-sabado-17-6197\/\",\"name\":\"Foz Adeafi tem encontro decisivo contra o Ciagym Maring&aacute; no s&aacute;bado (17) - Clickfoz\",\"isPartOf\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#website\"},\"datePublished\":\"2010-07-16T16:27:23+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-adeafi-tem-encontro-decisivo-contra-o-ciagym-maringa-no-sabado-17-6197\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-adeafi-tem-encontro-decisivo-contra-o-ciagym-maringa-no-sabado-17-6197\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-adeafi-tem-encontro-decisivo-contra-o-ciagym-maringa-no-sabado-17-6197\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/box5640.temp.domains\/~clickfoz\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Foz Adeafi tem encontro decisivo contra o Ciagym Maring&aacute; no s&aacute;bado (17)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#website\",\"url\":\"https:\/\/box5640.temp.domains\/~clickfoz\/\",\"name\":\"Click Foz do Igua\u00e7u\",\"description\":\"O portal de not\u00edcias de Foz do Igua\u00e7u\",\"publisher\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/box5640.temp.domains\/~clickfoz\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\",\"name\":\"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i\",\"url\":\"https:\/\/box5640.temp.domains\/~clickfoz\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png\",\"contentUrl\":\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png\",\"width\":190,\"height\":65,\"caption\":\"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i\"},\"image\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/clickfoz\",\"https:\/\/x.com\/clickfoz\",\"https:\/\/www.instagram.com\/clickfoz\"]},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Foz Adeafi tem encontro decisivo contra o Ciagym Maring&aacute; no s&aacute;bado (17) - Clickfoz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/box5640.temp.domains\/~clickfoz\/foz-adeafi-tem-encontro-decisivo-contra-o-ciagym-maringa-no-sabado-17-6197\/","og_locale":"pt_BR","og_type":"article","og_title":"Foz Adeafi tem encontro decisivo contra o Ciagym Maring&aacute; no s&aacute;bado (17) - Clickfoz","og_description":"O Foz do Igua&ccedil;u Adeafi recebe o Ciagym Maring&aacute; no s&aacute;bado (17) lutando para sair da lanterna do Grupo A da segunda fase da Chave Ouro do Campeonato Paranaese. Com duas derrotas em dois jogos, o confronto contra o Ciagym Maring&aacute; &eacute; considerado fundamental para a equipe igua&ccedil;uense manter as chances de classifica&ccedil;&atilde;o para a [&hellip;]","og_url":"http:\/\/box5640.temp.domains\/~clickfoz\/foz-adeafi-tem-encontro-decisivo-contra-o-ciagym-maringa-no-sabado-17-6197\/","og_site_name":"Clickfoz","article_publisher":"https:\/\/facebook.com\/clickfoz","article_published_time":"2010-07-16T16:27:23+00:00","og_image":[{"width":1200,"height":675,"url":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2023\/11\/logo-clickfoz.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_creator":"@clickfoz","twitter_site":"@clickfoz","twitter_misc":{"Escrito por":"","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/foz-adeafi-tem-encontro-decisivo-contra-o-ciagym-maringa-no-sabado-17-6197\/#article","isPartOf":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/foz-adeafi-tem-encontro-decisivo-contra-o-ciagym-maringa-no-sabado-17-6197\/"},"author":{"name":"","@id":""},"headline":"Foz Adeafi tem encontro decisivo contra o Ciagym Maring&aacute; no s&aacute;bado (17)","datePublished":"2010-07-16T16:27:23+00:00","mainEntityOfPage":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/foz-adeafi-tem-encontro-decisivo-contra-o-ciagym-maringa-no-sabado-17-6197\/"},"wordCount":588,"commentCount":0,"publisher":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization"},"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/box5640.temp.domains\/~clickfoz\/foz-adeafi-tem-encontro-decisivo-contra-o-ciagym-maringa-no-sabado-17-6197\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/foz-adeafi-tem-encontro-decisivo-contra-o-ciagym-maringa-no-sabado-17-6197\/","url":"http:\/\/box5640.temp.domains\/~clickfoz\/foz-adeafi-tem-encontro-decisivo-contra-o-ciagym-maringa-no-sabado-17-6197\/","name":"Foz Adeafi tem encontro decisivo contra o Ciagym Maring&aacute; no s&aacute;bado (17) - Clickfoz","isPartOf":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#website"},"datePublished":"2010-07-16T16:27:23+00:00","breadcrumb":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/foz-adeafi-tem-encontro-decisivo-contra-o-ciagym-maringa-no-sabado-17-6197\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/box5640.temp.domains\/~clickfoz\/foz-adeafi-tem-encontro-decisivo-contra-o-ciagym-maringa-no-sabado-17-6197\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/foz-adeafi-tem-encontro-decisivo-contra-o-ciagym-maringa-no-sabado-17-6197\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/box5640.temp.domains\/~clickfoz\/"},{"@type":"ListItem","position":2,"name":"Foz Adeafi tem encontro decisivo contra o Ciagym Maring&aacute; no s&aacute;bado (17)"}]},{"@type":"WebSite","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#website","url":"https:\/\/box5640.temp.domains\/~clickfoz\/","name":"Click Foz do Igua\u00e7u","description":"O portal de not\u00edcias de Foz do Igua\u00e7u","publisher":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/box5640.temp.domains\/~clickfoz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization","name":"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i","url":"https:\/\/box5640.temp.domains\/~clickfoz\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/","url":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png","contentUrl":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png","width":190,"height":65,"caption":"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i"},"image":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/clickfoz","https:\/\/x.com\/clickfoz","https:\/\/www.instagram.com\/clickfoz"]},{"@type":"Person","@id":"","url":"http:\/\/box5640.temp.domains\/~clickfoz\/author\/"}]}},"_links":{"self":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts\/13846","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/comments?post=13846"}],"version-history":[{"count":0,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts\/13846\/revisions"}],"wp:attachment":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/media?parent=13846"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/categories?post=13846"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/tags?post=13846"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}