{"id":13796,"date":"2010-07-21T10:47:59","date_gmt":"2010-07-21T10:47:59","guid":{"rendered":"http:\/\/localhost:82\/wordpress\/2010\/07\/21\/foz-futsal-derrota-o-assoeva-fica-perto-da-classificacao-na-liga-nacional-6249\/"},"modified":"2010-07-21T10:47:59","modified_gmt":"2010-07-21T10:47:59","slug":"foz-futsal-derrota-o-assoeva-fica-perto-da-classificacao-na-liga-nacional-6249","status":"publish","type":"post","link":"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-derrota-o-assoeva-fica-perto-da-classificacao-na-liga-nacional-6249\/","title":{"rendered":"Foz Futsal derrota o Assoeva fica perto da classifica&ccedil;&atilde;o na Liga Nacional"},"content":{"rendered":"<p style=\"text-align: justify\">Em boa fase na temporada, a equipe do Foz Futsal superou a Assoeva\/Ven&acirc;ncio Aires (RS) na noite de ter&ccedil;a-feira (20), por 4 a 2. Com a vit&oacute;ria no gin&aacute;sio Costa Cavalcanti, em Foz do Igua&ccedil;u, o time comandado pelo t&eacute;cnico Ed Carlos chegou aos 27 pontos na tabela e se aproximou da classifica&ccedil;&atilde;o a pr&oacute;xima fase da Liga Futsal 2010.<\/p>\n<p style=\"text-align: justify\">Jogando em casa, o Foz contou com o apoio de sua torcida, que compareceu em bom n&uacute;mero para empurrar o time paranaense a mais uma vit&oacute;ria no campeonato nacional. Superior no primeiro tempo, a equipe local abriu 3 a 1 no placar com gols de Yuri, Mancha e Ma&ccedil;arico. Markinhos descontou para os ga&uacute;chos.<\/p>\n<p style=\"text-align: justify\">Depois do intervalo, a agremia&ccedil;&atilde;o ga&uacute;cha tentou pressionar o time da casa. Apesar das investidas do advers&aacute;rio, o Foz Futsal manteve a calma no confronto e tentou liquidar o resultado com jogadas r&aacute;pidas de contra-ataques.<\/p>\n<p style=\"text-align: justify\">Restando menos de dois minutos para o encerramento do duelo, paranaenses e ga&uacute;chos continuaram no ataque e marcaram mais duas vezes. Enquanto o experiente fixo Ma&ccedil;arico, que iniciou o jogo no banco de reservas, assinalou seu segundo tento na noite, o quarto do Foz, Markinhos, da Assoeva, marcou aos 39min34 e definiu o placar em 4 a 2 para a agremia&ccedil;&atilde;o da casa.<\/p>\n<p style=\"text-align: justify\">No s&aacute;bado (24) o Foz Futsal ir&aacute; S&atilde;o Paulo enfrentar o l&iacute;der da Liga Futsal 2010, o S&atilde;o Caetano\/Corinthians. J&aacute; a Assoeva ter&aacute; pela frente o cl&aacute;ssico ga&uacute;cho contra o Atl&acirc;ntico\/Erechim.<\/p>\n<p style=\"text-align: justify\"><strong>Cl&aacute;ssico igua&ccedil;uense<\/strong> &#8211; Antes do confronto de s&aacute;bado pela Liga, o Foz Futsal enfrenta&nbsp; a Adeafi pela Chave Ouro do Paranaense. A partida est&aacute; programada para quinta-feira (22), 20h30, no Costa Cavalcanti.<\/p>\n<p style=\"text-align: justify\">Os ingressos antecipados para o jogo custam R$ 5 e podem ser adquiridos nas Lojas Manica, Estacionamento Bismillah, Master Farma &#8211; Evolu&ccedil;&atilde;o, Mundo do Futebol, Iguassu Boulevard e Cataratas Materiais de Constru&ccedil;&atilde;o. A bilheteria do Gin&aacute;sio Costa Cavalcanti estar&aacute; aberta a partir das 19h00. Lembrando que na hora os ingressos custam R$ 10 para homens. Mulheres e estudantes pagam R$ 5.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em boa fase na temporada, a equipe do Foz Futsal superou a Assoeva\/Ven&acirc;ncio Aires (RS) na noite de ter&ccedil;a-feira (20), por 4 a 2. Com a vit&oacute;ria no gin&aacute;sio Costa Cavalcanti, em Foz do Igua&ccedil;u, o time comandado pelo t&eacute;cnico Ed Carlos chegou aos 27 pontos na tabela e se aproximou da classifica&ccedil;&atilde;o a pr&oacute;xima [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-13796","post","type-post","status-publish","format-standard","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Foz Futsal derrota o Assoeva fica perto da classifica&ccedil;&atilde;o na Liga Nacional - Clickfoz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-derrota-o-assoeva-fica-perto-da-classificacao-na-liga-nacional-6249\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Foz Futsal derrota o Assoeva fica perto da classifica&ccedil;&atilde;o na Liga Nacional - Clickfoz\" \/>\n<meta property=\"og:description\" content=\"Em boa fase na temporada, a equipe do Foz Futsal superou a Assoeva\/Ven&acirc;ncio Aires (RS) na noite de ter&ccedil;a-feira (20), por 4 a 2. Com a vit&oacute;ria no gin&aacute;sio Costa Cavalcanti, em Foz do Igua&ccedil;u, o time comandado pelo t&eacute;cnico Ed Carlos chegou aos 27 pontos na tabela e se aproximou da classifica&ccedil;&atilde;o a pr&oacute;xima [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-derrota-o-assoeva-fica-perto-da-classificacao-na-liga-nacional-6249\/\" \/>\n<meta property=\"og:site_name\" content=\"Clickfoz\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/clickfoz\" \/>\n<meta property=\"article:published_time\" content=\"2010-07-21T10:47:59+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2023\/11\/logo-clickfoz.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@clickfoz\" \/>\n<meta name=\"twitter:site\" content=\"@clickfoz\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-derrota-o-assoeva-fica-perto-da-classificacao-na-liga-nacional-6249\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-derrota-o-assoeva-fica-perto-da-classificacao-na-liga-nacional-6249\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Foz Futsal derrota o Assoeva fica perto da classifica&ccedil;&atilde;o na Liga Nacional\",\"datePublished\":\"2010-07-21T10:47:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-derrota-o-assoeva-fica-perto-da-classificacao-na-liga-nacional-6249\/\"},\"wordCount\":414,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-derrota-o-assoeva-fica-perto-da-classificacao-na-liga-nacional-6249\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-derrota-o-assoeva-fica-perto-da-classificacao-na-liga-nacional-6249\/\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-derrota-o-assoeva-fica-perto-da-classificacao-na-liga-nacional-6249\/\",\"name\":\"Foz Futsal derrota o Assoeva fica perto da classifica&ccedil;&atilde;o na Liga Nacional - Clickfoz\",\"isPartOf\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#website\"},\"datePublished\":\"2010-07-21T10:47:59+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-derrota-o-assoeva-fica-perto-da-classificacao-na-liga-nacional-6249\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-derrota-o-assoeva-fica-perto-da-classificacao-na-liga-nacional-6249\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-derrota-o-assoeva-fica-perto-da-classificacao-na-liga-nacional-6249\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/box5640.temp.domains\/~clickfoz\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Foz Futsal derrota o Assoeva fica perto da classifica&ccedil;&atilde;o na Liga Nacional\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#website\",\"url\":\"https:\/\/box5640.temp.domains\/~clickfoz\/\",\"name\":\"Click Foz do Igua\u00e7u\",\"description\":\"O portal de not\u00edcias de Foz do Igua\u00e7u\",\"publisher\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/box5640.temp.domains\/~clickfoz\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\",\"name\":\"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i\",\"url\":\"https:\/\/box5640.temp.domains\/~clickfoz\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png\",\"contentUrl\":\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png\",\"width\":190,\"height\":65,\"caption\":\"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i\"},\"image\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/clickfoz\",\"https:\/\/x.com\/clickfoz\",\"https:\/\/www.instagram.com\/clickfoz\"]},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Foz Futsal derrota o Assoeva fica perto da classifica&ccedil;&atilde;o na Liga Nacional - Clickfoz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-derrota-o-assoeva-fica-perto-da-classificacao-na-liga-nacional-6249\/","og_locale":"pt_BR","og_type":"article","og_title":"Foz Futsal derrota o Assoeva fica perto da classifica&ccedil;&atilde;o na Liga Nacional - Clickfoz","og_description":"Em boa fase na temporada, a equipe do Foz Futsal superou a Assoeva\/Ven&acirc;ncio Aires (RS) na noite de ter&ccedil;a-feira (20), por 4 a 2. Com a vit&oacute;ria no gin&aacute;sio Costa Cavalcanti, em Foz do Igua&ccedil;u, o time comandado pelo t&eacute;cnico Ed Carlos chegou aos 27 pontos na tabela e se aproximou da classifica&ccedil;&atilde;o a pr&oacute;xima [&hellip;]","og_url":"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-derrota-o-assoeva-fica-perto-da-classificacao-na-liga-nacional-6249\/","og_site_name":"Clickfoz","article_publisher":"https:\/\/facebook.com\/clickfoz","article_published_time":"2010-07-21T10:47:59+00:00","og_image":[{"width":1200,"height":675,"url":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2023\/11\/logo-clickfoz.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_creator":"@clickfoz","twitter_site":"@clickfoz","twitter_misc":{"Escrito por":"","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-derrota-o-assoeva-fica-perto-da-classificacao-na-liga-nacional-6249\/#article","isPartOf":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-derrota-o-assoeva-fica-perto-da-classificacao-na-liga-nacional-6249\/"},"author":{"name":"","@id":""},"headline":"Foz Futsal derrota o Assoeva fica perto da classifica&ccedil;&atilde;o na Liga Nacional","datePublished":"2010-07-21T10:47:59+00:00","mainEntityOfPage":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-derrota-o-assoeva-fica-perto-da-classificacao-na-liga-nacional-6249\/"},"wordCount":414,"commentCount":0,"publisher":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization"},"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-derrota-o-assoeva-fica-perto-da-classificacao-na-liga-nacional-6249\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-derrota-o-assoeva-fica-perto-da-classificacao-na-liga-nacional-6249\/","url":"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-derrota-o-assoeva-fica-perto-da-classificacao-na-liga-nacional-6249\/","name":"Foz Futsal derrota o Assoeva fica perto da classifica&ccedil;&atilde;o na Liga Nacional - Clickfoz","isPartOf":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#website"},"datePublished":"2010-07-21T10:47:59+00:00","breadcrumb":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-derrota-o-assoeva-fica-perto-da-classificacao-na-liga-nacional-6249\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-derrota-o-assoeva-fica-perto-da-classificacao-na-liga-nacional-6249\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/foz-futsal-derrota-o-assoeva-fica-perto-da-classificacao-na-liga-nacional-6249\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/box5640.temp.domains\/~clickfoz\/"},{"@type":"ListItem","position":2,"name":"Foz Futsal derrota o Assoeva fica perto da classifica&ccedil;&atilde;o na Liga Nacional"}]},{"@type":"WebSite","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#website","url":"https:\/\/box5640.temp.domains\/~clickfoz\/","name":"Click Foz do Igua\u00e7u","description":"O portal de not\u00edcias de Foz do Igua\u00e7u","publisher":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/box5640.temp.domains\/~clickfoz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization","name":"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i","url":"https:\/\/box5640.temp.domains\/~clickfoz\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/","url":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png","contentUrl":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png","width":190,"height":65,"caption":"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i"},"image":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/clickfoz","https:\/\/x.com\/clickfoz","https:\/\/www.instagram.com\/clickfoz"]},{"@type":"Person","@id":"","url":"http:\/\/box5640.temp.domains\/~clickfoz\/author\/"}]}},"_links":{"self":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts\/13796","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/comments?post=13796"}],"version-history":[{"count":0,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts\/13796\/revisions"}],"wp:attachment":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/media?parent=13796"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/categories?post=13796"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/tags?post=13796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}