{"id":13673,"date":"2010-07-30T17:58:54","date_gmt":"2010-07-30T17:58:54","guid":{"rendered":"http:\/\/localhost:82\/wordpress\/2010\/07\/30\/atletas-do-parana-participam-das-paraolimpiadas-escolares-6375\/"},"modified":"2010-07-30T17:58:54","modified_gmt":"2010-07-30T17:58:54","slug":"atletas-do-parana-participam-das-paraolimpiadas-escolares-6375","status":"publish","type":"post","link":"http:\/\/box5640.temp.domains\/~clickfoz\/atletas-do-parana-participam-das-paraolimpiadas-escolares-6375\/","title":{"rendered":"Atletas do Paran&aacute; participam das Paraolimp&iacute;adas Escolares"},"content":{"rendered":"<p style=\"text-align: justify\">O Paran&aacute; vai competir nas modalidades atletismo, nata&ccedil;&atilde;o e t&ecirc;nis de mesa nas Paraolimp&iacute;adas Escolares de 2010, que ser&aacute; realizada de 6 a 11 de setembro em S&atilde;o Paulo. &ldquo;S&atilde;o as modalidades que tivemos campe&otilde;es na fase final dos Jogos Colegiais do Paran&aacute; de 2010, nas faixas et&aacute;rias estabelecidas para a competi&ccedil;&atilde;o nacional&rdquo;, explica o diretor-presidente da Paran&aacute; Esporte, Marco Aur&eacute;lio Saldanha Rocha. <\/p>\n<p style=\"text-align: justify\">Devem participar das Paraolimp&iacute;adas Escolares de 2010 cerca de 1.200 pessoas entre alunos, t&eacute;cnicos e dirigentes, representando 22 estados e o Distrito Federal. S&atilde;o disputadas 10 modalidades, entre elas duas novidades: t&ecirc;nis em cadeiras de roda e v&ocirc;lei sentado. As outras s&atilde;o: atletismo, bocha, futebol 5, futebol 7, goalball, jud&ocirc;, nata&ccedil;&atilde;o e t&ecirc;nis de mesa. O sistema de disputa &eacute; o estabelecido pelo Comit&ecirc; Paraol&iacute;mpico Internacional. <\/p>\n<p style=\"text-align: justify\">A Paraolimp&iacute;ada Escolar &eacute; promovida pelo Comit&ecirc; Paraol&iacute;mpico Brasileiro e Minist&eacute;rio do Esporte, em parceria com o Governo de S&atilde;o Paulo e demais estados participantes, cabendo a esses &uacute;ltimos o transporte das delega&ccedil;&otilde;es. O objetivo &eacute; fomentar, estimular e oportunizar a participa&ccedil;&atilde;o de estudantes com defici&ecirc;ncia f&iacute;sica, intelectual e visual em atividades esportivas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Paran&aacute; vai competir nas modalidades atletismo, nata&ccedil;&atilde;o e t&ecirc;nis de mesa nas Paraolimp&iacute;adas Escolares de 2010, que ser&aacute; realizada de 6 a 11 de setembro em S&atilde;o Paulo. &ldquo;S&atilde;o as modalidades que tivemos campe&otilde;es na fase final dos Jogos Colegiais do Paran&aacute; de 2010, nas faixas et&aacute;rias estabelecidas para a competi&ccedil;&atilde;o nacional&rdquo;, explica o [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-13673","post","type-post","status-publish","format-standard","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Atletas do Paran&aacute; participam das Paraolimp&iacute;adas Escolares - Clickfoz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/box5640.temp.domains\/~clickfoz\/atletas-do-parana-participam-das-paraolimpiadas-escolares-6375\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Atletas do Paran&aacute; participam das Paraolimp&iacute;adas Escolares - Clickfoz\" \/>\n<meta property=\"og:description\" content=\"O Paran&aacute; vai competir nas modalidades atletismo, nata&ccedil;&atilde;o e t&ecirc;nis de mesa nas Paraolimp&iacute;adas Escolares de 2010, que ser&aacute; realizada de 6 a 11 de setembro em S&atilde;o Paulo. &ldquo;S&atilde;o as modalidades que tivemos campe&otilde;es na fase final dos Jogos Colegiais do Paran&aacute; de 2010, nas faixas et&aacute;rias estabelecidas para a competi&ccedil;&atilde;o nacional&rdquo;, explica o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/box5640.temp.domains\/~clickfoz\/atletas-do-parana-participam-das-paraolimpiadas-escolares-6375\/\" \/>\n<meta property=\"og:site_name\" content=\"Clickfoz\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/clickfoz\" \/>\n<meta property=\"article:published_time\" content=\"2010-07-30T17:58:54+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2023\/11\/logo-clickfoz.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@clickfoz\" \/>\n<meta name=\"twitter:site\" content=\"@clickfoz\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/atletas-do-parana-participam-das-paraolimpiadas-escolares-6375\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/atletas-do-parana-participam-das-paraolimpiadas-escolares-6375\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Atletas do Paran&aacute; participam das Paraolimp&iacute;adas Escolares\",\"datePublished\":\"2010-07-30T17:58:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/atletas-do-parana-participam-das-paraolimpiadas-escolares-6375\/\"},\"wordCount\":249,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\/\/box5640.temp.domains\/~clickfoz\/atletas-do-parana-participam-das-paraolimpiadas-escolares-6375\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/atletas-do-parana-participam-das-paraolimpiadas-escolares-6375\/\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/atletas-do-parana-participam-das-paraolimpiadas-escolares-6375\/\",\"name\":\"Atletas do Paran&aacute; participam das Paraolimp&iacute;adas Escolares - Clickfoz\",\"isPartOf\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#website\"},\"datePublished\":\"2010-07-30T17:58:54+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/atletas-do-parana-participam-das-paraolimpiadas-escolares-6375\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/box5640.temp.domains\/~clickfoz\/atletas-do-parana-participam-das-paraolimpiadas-escolares-6375\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/atletas-do-parana-participam-das-paraolimpiadas-escolares-6375\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/box5640.temp.domains\/~clickfoz\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Atletas do Paran&aacute; participam das Paraolimp&iacute;adas Escolares\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#website\",\"url\":\"https:\/\/box5640.temp.domains\/~clickfoz\/\",\"name\":\"Click Foz do Igua\u00e7u\",\"description\":\"O portal de not\u00edcias de Foz do Igua\u00e7u\",\"publisher\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/box5640.temp.domains\/~clickfoz\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\",\"name\":\"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i\",\"url\":\"https:\/\/box5640.temp.domains\/~clickfoz\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png\",\"contentUrl\":\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png\",\"width\":190,\"height\":65,\"caption\":\"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i\"},\"image\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/clickfoz\",\"https:\/\/x.com\/clickfoz\",\"https:\/\/www.instagram.com\/clickfoz\"]},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Atletas do Paran&aacute; participam das Paraolimp&iacute;adas Escolares - Clickfoz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/box5640.temp.domains\/~clickfoz\/atletas-do-parana-participam-das-paraolimpiadas-escolares-6375\/","og_locale":"pt_BR","og_type":"article","og_title":"Atletas do Paran&aacute; participam das Paraolimp&iacute;adas Escolares - Clickfoz","og_description":"O Paran&aacute; vai competir nas modalidades atletismo, nata&ccedil;&atilde;o e t&ecirc;nis de mesa nas Paraolimp&iacute;adas Escolares de 2010, que ser&aacute; realizada de 6 a 11 de setembro em S&atilde;o Paulo. &ldquo;S&atilde;o as modalidades que tivemos campe&otilde;es na fase final dos Jogos Colegiais do Paran&aacute; de 2010, nas faixas et&aacute;rias estabelecidas para a competi&ccedil;&atilde;o nacional&rdquo;, explica o [&hellip;]","og_url":"http:\/\/box5640.temp.domains\/~clickfoz\/atletas-do-parana-participam-das-paraolimpiadas-escolares-6375\/","og_site_name":"Clickfoz","article_publisher":"https:\/\/facebook.com\/clickfoz","article_published_time":"2010-07-30T17:58:54+00:00","og_image":[{"width":1200,"height":675,"url":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2023\/11\/logo-clickfoz.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_creator":"@clickfoz","twitter_site":"@clickfoz","twitter_misc":{"Escrito por":"","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/atletas-do-parana-participam-das-paraolimpiadas-escolares-6375\/#article","isPartOf":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/atletas-do-parana-participam-das-paraolimpiadas-escolares-6375\/"},"author":{"name":"","@id":""},"headline":"Atletas do Paran&aacute; participam das Paraolimp&iacute;adas Escolares","datePublished":"2010-07-30T17:58:54+00:00","mainEntityOfPage":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/atletas-do-parana-participam-das-paraolimpiadas-escolares-6375\/"},"wordCount":249,"commentCount":0,"publisher":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization"},"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/box5640.temp.domains\/~clickfoz\/atletas-do-parana-participam-das-paraolimpiadas-escolares-6375\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/atletas-do-parana-participam-das-paraolimpiadas-escolares-6375\/","url":"http:\/\/box5640.temp.domains\/~clickfoz\/atletas-do-parana-participam-das-paraolimpiadas-escolares-6375\/","name":"Atletas do Paran&aacute; participam das Paraolimp&iacute;adas Escolares - Clickfoz","isPartOf":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#website"},"datePublished":"2010-07-30T17:58:54+00:00","breadcrumb":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/atletas-do-parana-participam-das-paraolimpiadas-escolares-6375\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/box5640.temp.domains\/~clickfoz\/atletas-do-parana-participam-das-paraolimpiadas-escolares-6375\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/atletas-do-parana-participam-das-paraolimpiadas-escolares-6375\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/box5640.temp.domains\/~clickfoz\/"},{"@type":"ListItem","position":2,"name":"Atletas do Paran&aacute; participam das Paraolimp&iacute;adas Escolares"}]},{"@type":"WebSite","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#website","url":"https:\/\/box5640.temp.domains\/~clickfoz\/","name":"Click Foz do Igua\u00e7u","description":"O portal de not\u00edcias de Foz do Igua\u00e7u","publisher":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/box5640.temp.domains\/~clickfoz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization","name":"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i","url":"https:\/\/box5640.temp.domains\/~clickfoz\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/","url":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png","contentUrl":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png","width":190,"height":65,"caption":"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i"},"image":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/clickfoz","https:\/\/x.com\/clickfoz","https:\/\/www.instagram.com\/clickfoz"]},{"@type":"Person","@id":"","url":"http:\/\/box5640.temp.domains\/~clickfoz\/author\/"}]}},"_links":{"self":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts\/13673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/comments?post=13673"}],"version-history":[{"count":0,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts\/13673\/revisions"}],"wp:attachment":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/media?parent=13673"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/categories?post=13673"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/tags?post=13673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}