{"id":13656,"date":"2010-08-02T10:25:34","date_gmt":"2010-08-02T10:25:34","guid":{"rendered":"http:\/\/localhost:82\/wordpress\/2010\/08\/02\/foz-fc-sofre-mas-consegue-a-virada-sobre-o-roma-de-apucara-e-lidera-o-acesso-6393\/"},"modified":"2010-08-02T10:25:34","modified_gmt":"2010-08-02T10:25:34","slug":"foz-fc-sofre-mas-consegue-a-virada-sobre-o-roma-de-apucara-e-lidera-o-acesso-6393","status":"publish","type":"post","link":"http:\/\/box5640.temp.domains\/~clickfoz\/foz-fc-sofre-mas-consegue-a-virada-sobre-o-roma-de-apucara-e-lidera-o-acesso-6393\/","title":{"rendered":"Foz FC sofre, mas consegue a virada sobre o Roma de Apucara e lidera o Acesso"},"content":{"rendered":"<p style=\"text-align: justify\"><img fetchpriority=\"high\" decoding=\"async\" hspace=\"8\" height=\"400\" width=\"255\" vspace=\"8\" align=\"left\" alt=\"\" src=\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/images\/noticias\/Logos\/brasao%20FFC.jpg\" \/>O jogo valia a lideran&ccedil;a do Hexagonal Final do Campeonato Paranaense da Segunda Divis&atilde;o. Em campo, as duas equipes que tiveram as melhores campanhas na primeira fase. Foz Futebol Clube e Roma de Apucarana se enfrentaram na tarde de domingo (1&ordm;) no est&aacute;dio do ABC, pela 5&ordf; e &uacute;ltima rodada do primeiro turno do Hexagonal.<\/p>\n<p style=\"text-align: justify\">Os dois times precisavam e muito da vit&oacute;ria para assumirem a lideran&ccedil;a e se manterem no grupo dos dois primeiros colocados que se classificam &agrave; Primeira Divis&atilde;o do Paranaense de 2011. E, para surpresa dos mais de mil torcedores presentes ao est&aacute;dio, quem saiu na frente do placar foi o time visitante.<\/p>\n<p style=\"text-align: justify\">Logo aos nove minutos de jogo, em jogada pela direita, cruzamento para dentro da &aacute;rea e o artilheiro do campeonato, F&aacute;bio, com 15 gols, abriu o marcador para o Roma de Apucarana: 1 a 0. A partir da&iacute; o desespero come&ccedil;ou a tomar conta dos jogadores igua&ccedil;uenses.<\/p>\n<p style=\"text-align: justify\">As tentativas de empatar foram v&aacute;rias e o goleiro do Roma, Spada, foi o grande destaque do primeiro tempo. No time do Foz, os principais destaques eram o lateral esquerdo Nelsinho e o atacante Pequi, que retornava de suspens&atilde;o. Mas os v&aacute;rios passes errados dados pelos jogadores do &ldquo;Azul&atilde;o da Fronteira&rdquo; fizeram com que os torcedores vaiassem a equipe no final da primeira etapa.<\/p>\n<p style=\"text-align: justify\">Durante o intervalo o presidente do Foz FC, Loiri Jos&eacute; Dalla Corte (Loli), foi at&eacute; o vesti&aacute;rio do time e, ao que parece, conversou com os jogadores sobre o andamento da partida. Coincid&ecirc;ncia ou n&atilde;o, aliado com a entrada do meia Brito no lugar de Thiago Martins, a postura da equipe ficou mais ofensiva. Mas foi o Roma quem quase marcou pela segunda vez, logo no come&ccedil;o do segundo tempo.<\/p>\n<p style=\"text-align: justify\">Era o susto necess&aacute;rio para o Foz definitivamente acordar no jogo. Assim como o gol do Roma, o empate do Foz tamb&eacute;m nasceu em uma jogada pela direita. S&oacute; que desta vez o cruzamento foi rasteiro e Gilmar empurrou para o fundo das redes, aos dez minutos.<\/p>\n<p style=\"text-align: justify\">A press&atilde;o do time da casa continuou e, 17 minutos depois, veio a virada. E foi preciso um jogador da defesa, que n&atilde;o &eacute; titular com frequ&ecirc;ncia. Em cobran&ccedil;a de escanteio, houve bate-rebate dentro da &aacute;rea e Rodrigo, de cabe&ccedil;a, virou para o Foz.<\/p>\n<p style=\"text-align: justify\">Nos minutos finais, o &aacute;rbitro Leandro J&uacute;nior Hermes deu cinco minutos de acr&eacute;scimo, para desespero do torcedor e ira do presidente Loli. Isso porque, o Roma passou a pressionar e por pouco n&atilde;o empatou.<\/p>\n<p style=\"text-align: justify\">A vit&oacute;ria devolveu o Foz &agrave; lideran&ccedil;a, com 12 pontos, quatro a mais do que o Roma, que permaneceu em terceiro. O segundo colocado e que hoje estaria classificado &eacute; o Arapongas, com 11 pontos. Na pr&oacute;xima rodada, o Foz FC vai at&eacute; S&atilde;o Jos&eacute; dos Pinhais enfrentar o S&atilde;o Jos&eacute;. A partida deve ocorrer no est&aacute;dio do Pinh&atilde;o, &agrave;s 15h de quarta-feira (4), pois o est&aacute;dio n&atilde;o possui ilumina&ccedil;&atilde;o.<\/p>\n<p style=\"text-align: justify\"><strong>Jogos da 5&ordf; rodada do Hexagonal Final<\/strong><br \/>\nS&atilde;o Jos&eacute; 0 x 1 Arapongas<br \/>\nSport Campo Mour&atilde;o 3 x 2 Portuguesa Londrinense<br \/>\nFoz FC 2 x 1 Roma de Apucarana<\/p>\n<p style=\"text-align: justify\"><strong>Classifica&ccedil;&atilde;o<\/strong><\/p>\n<p style=\"text-align: center\"><img decoding=\"async\" hspace=\"8\" height=\"137\" width=\"610\" vspace=\"8\" align=\"middle\" alt=\"\" src=\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/images\/noticias\/Esportes\/classificacao-ao-final-do-primeiro-turno.jpg\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O jogo valia a lideran&ccedil;a do Hexagonal Final do Campeonato Paranaense da Segunda Divis&atilde;o. Em campo, as duas equipes que tiveram as melhores campanhas na primeira fase. Foz Futebol Clube e Roma de Apucarana se enfrentaram na tarde de domingo (1&ordm;) no est&aacute;dio do ABC, pela 5&ordf; e &uacute;ltima rodada do primeiro turno do Hexagonal. [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-13656","post","type-post","status-publish","format-standard","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Foz FC sofre, mas consegue a virada sobre o Roma de Apucara e lidera o Acesso - Clickfoz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-fc-sofre-mas-consegue-a-virada-sobre-o-roma-de-apucara-e-lidera-o-acesso-6393\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Foz FC sofre, mas consegue a virada sobre o Roma de Apucara e lidera o Acesso - Clickfoz\" \/>\n<meta property=\"og:description\" content=\"O jogo valia a lideran&ccedil;a do Hexagonal Final do Campeonato Paranaense da Segunda Divis&atilde;o. Em campo, as duas equipes que tiveram as melhores campanhas na primeira fase. Foz Futebol Clube e Roma de Apucarana se enfrentaram na tarde de domingo (1&ordm;) no est&aacute;dio do ABC, pela 5&ordf; e &uacute;ltima rodada do primeiro turno do Hexagonal. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-fc-sofre-mas-consegue-a-virada-sobre-o-roma-de-apucara-e-lidera-o-acesso-6393\/\" \/>\n<meta property=\"og:site_name\" content=\"Clickfoz\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/clickfoz\" \/>\n<meta property=\"article:published_time\" content=\"2010-08-02T10:25:34+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/images\/noticias\/Logos\/brasao%20FFC.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@clickfoz\" \/>\n<meta name=\"twitter:site\" content=\"@clickfoz\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-fc-sofre-mas-consegue-a-virada-sobre-o-roma-de-apucara-e-lidera-o-acesso-6393\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-fc-sofre-mas-consegue-a-virada-sobre-o-roma-de-apucara-e-lidera-o-acesso-6393\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Foz FC sofre, mas consegue a virada sobre o Roma de Apucara e lidera o Acesso\",\"datePublished\":\"2010-08-02T10:25:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-fc-sofre-mas-consegue-a-virada-sobre-o-roma-de-apucara-e-lidera-o-acesso-6393\/\"},\"wordCount\":614,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\"},\"image\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-fc-sofre-mas-consegue-a-virada-sobre-o-roma-de-apucara-e-lidera-o-acesso-6393\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/images\/noticias\/Logos\/brasao%20FFC.jpg\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-fc-sofre-mas-consegue-a-virada-sobre-o-roma-de-apucara-e-lidera-o-acesso-6393\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-fc-sofre-mas-consegue-a-virada-sobre-o-roma-de-apucara-e-lidera-o-acesso-6393\/\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-fc-sofre-mas-consegue-a-virada-sobre-o-roma-de-apucara-e-lidera-o-acesso-6393\/\",\"name\":\"Foz FC sofre, mas consegue a virada sobre o Roma de Apucara e lidera o Acesso - Clickfoz\",\"isPartOf\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-fc-sofre-mas-consegue-a-virada-sobre-o-roma-de-apucara-e-lidera-o-acesso-6393\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-fc-sofre-mas-consegue-a-virada-sobre-o-roma-de-apucara-e-lidera-o-acesso-6393\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/images\/noticias\/Logos\/brasao%20FFC.jpg\",\"datePublished\":\"2010-08-02T10:25:34+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-fc-sofre-mas-consegue-a-virada-sobre-o-roma-de-apucara-e-lidera-o-acesso-6393\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-fc-sofre-mas-consegue-a-virada-sobre-o-roma-de-apucara-e-lidera-o-acesso-6393\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-fc-sofre-mas-consegue-a-virada-sobre-o-roma-de-apucara-e-lidera-o-acesso-6393\/#primaryimage\",\"url\":\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/images\/noticias\/Logos\/brasao%20FFC.jpg\",\"contentUrl\":\"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/images\/noticias\/Logos\/brasao%20FFC.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/foz-fc-sofre-mas-consegue-a-virada-sobre-o-roma-de-apucara-e-lidera-o-acesso-6393\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/box5640.temp.domains\/~clickfoz\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Foz FC sofre, mas consegue a virada sobre o Roma de Apucara e lidera o Acesso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#website\",\"url\":\"https:\/\/box5640.temp.domains\/~clickfoz\/\",\"name\":\"Click Foz do Igua\u00e7u\",\"description\":\"O portal de not\u00edcias de Foz do Igua\u00e7u\",\"publisher\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/box5640.temp.domains\/~clickfoz\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\",\"name\":\"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i\",\"url\":\"https:\/\/box5640.temp.domains\/~clickfoz\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png\",\"contentUrl\":\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png\",\"width\":190,\"height\":65,\"caption\":\"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i\"},\"image\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/clickfoz\",\"https:\/\/x.com\/clickfoz\",\"https:\/\/www.instagram.com\/clickfoz\"]},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Foz FC sofre, mas consegue a virada sobre o Roma de Apucara e lidera o Acesso - Clickfoz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/box5640.temp.domains\/~clickfoz\/foz-fc-sofre-mas-consegue-a-virada-sobre-o-roma-de-apucara-e-lidera-o-acesso-6393\/","og_locale":"pt_BR","og_type":"article","og_title":"Foz FC sofre, mas consegue a virada sobre o Roma de Apucara e lidera o Acesso - Clickfoz","og_description":"O jogo valia a lideran&ccedil;a do Hexagonal Final do Campeonato Paranaense da Segunda Divis&atilde;o. Em campo, as duas equipes que tiveram as melhores campanhas na primeira fase. Foz Futebol Clube e Roma de Apucarana se enfrentaram na tarde de domingo (1&ordm;) no est&aacute;dio do ABC, pela 5&ordf; e &uacute;ltima rodada do primeiro turno do Hexagonal. [&hellip;]","og_url":"http:\/\/box5640.temp.domains\/~clickfoz\/foz-fc-sofre-mas-consegue-a-virada-sobre-o-roma-de-apucara-e-lidera-o-acesso-6393\/","og_site_name":"Clickfoz","article_publisher":"https:\/\/facebook.com\/clickfoz","article_published_time":"2010-08-02T10:25:34+00:00","og_image":[{"url":"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/images\/noticias\/Logos\/brasao%20FFC.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_creator":"@clickfoz","twitter_site":"@clickfoz","twitter_misc":{"Escrito por":"","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/foz-fc-sofre-mas-consegue-a-virada-sobre-o-roma-de-apucara-e-lidera-o-acesso-6393\/#article","isPartOf":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/foz-fc-sofre-mas-consegue-a-virada-sobre-o-roma-de-apucara-e-lidera-o-acesso-6393\/"},"author":{"name":"","@id":""},"headline":"Foz FC sofre, mas consegue a virada sobre o Roma de Apucara e lidera o Acesso","datePublished":"2010-08-02T10:25:34+00:00","mainEntityOfPage":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/foz-fc-sofre-mas-consegue-a-virada-sobre-o-roma-de-apucara-e-lidera-o-acesso-6393\/"},"wordCount":614,"commentCount":0,"publisher":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization"},"image":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/foz-fc-sofre-mas-consegue-a-virada-sobre-o-roma-de-apucara-e-lidera-o-acesso-6393\/#primaryimage"},"thumbnailUrl":"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/images\/noticias\/Logos\/brasao%20FFC.jpg","inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/box5640.temp.domains\/~clickfoz\/foz-fc-sofre-mas-consegue-a-virada-sobre-o-roma-de-apucara-e-lidera-o-acesso-6393\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/foz-fc-sofre-mas-consegue-a-virada-sobre-o-roma-de-apucara-e-lidera-o-acesso-6393\/","url":"http:\/\/box5640.temp.domains\/~clickfoz\/foz-fc-sofre-mas-consegue-a-virada-sobre-o-roma-de-apucara-e-lidera-o-acesso-6393\/","name":"Foz FC sofre, mas consegue a virada sobre o Roma de Apucara e lidera o Acesso - Clickfoz","isPartOf":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#website"},"primaryImageOfPage":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/foz-fc-sofre-mas-consegue-a-virada-sobre-o-roma-de-apucara-e-lidera-o-acesso-6393\/#primaryimage"},"image":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/foz-fc-sofre-mas-consegue-a-virada-sobre-o-roma-de-apucara-e-lidera-o-acesso-6393\/#primaryimage"},"thumbnailUrl":"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/images\/noticias\/Logos\/brasao%20FFC.jpg","datePublished":"2010-08-02T10:25:34+00:00","breadcrumb":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/foz-fc-sofre-mas-consegue-a-virada-sobre-o-roma-de-apucara-e-lidera-o-acesso-6393\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/box5640.temp.domains\/~clickfoz\/foz-fc-sofre-mas-consegue-a-virada-sobre-o-roma-de-apucara-e-lidera-o-acesso-6393\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/foz-fc-sofre-mas-consegue-a-virada-sobre-o-roma-de-apucara-e-lidera-o-acesso-6393\/#primaryimage","url":"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/images\/noticias\/Logos\/brasao%20FFC.jpg","contentUrl":"http:\/\/www.clickfozdoiguacu.com.br\/static\/image\/midia\/images\/noticias\/Logos\/brasao%20FFC.jpg"},{"@type":"BreadcrumbList","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/foz-fc-sofre-mas-consegue-a-virada-sobre-o-roma-de-apucara-e-lidera-o-acesso-6393\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/box5640.temp.domains\/~clickfoz\/"},{"@type":"ListItem","position":2,"name":"Foz FC sofre, mas consegue a virada sobre o Roma de Apucara e lidera o Acesso"}]},{"@type":"WebSite","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#website","url":"https:\/\/box5640.temp.domains\/~clickfoz\/","name":"Click Foz do Igua\u00e7u","description":"O portal de not\u00edcias de Foz do Igua\u00e7u","publisher":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/box5640.temp.domains\/~clickfoz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization","name":"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i","url":"https:\/\/box5640.temp.domains\/~clickfoz\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/","url":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png","contentUrl":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png","width":190,"height":65,"caption":"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i"},"image":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/clickfoz","https:\/\/x.com\/clickfoz","https:\/\/www.instagram.com\/clickfoz"]},{"@type":"Person","@id":"","url":"http:\/\/box5640.temp.domains\/~clickfoz\/author\/"}]}},"_links":{"self":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts\/13656","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/comments?post=13656"}],"version-history":[{"count":0,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts\/13656\/revisions"}],"wp:attachment":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/media?parent=13656"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/categories?post=13656"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/tags?post=13656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}