{"id":13651,"date":"2010-08-02T15:21:37","date_gmt":"2010-08-02T15:21:37","guid":{"rendered":"http:\/\/localhost:82\/wordpress\/2010\/08\/02\/piso-de-policiais-e-acordo-de-itaipu-podem-entrar-na-pauta-da-camara-6398\/"},"modified":"2010-08-02T15:21:37","modified_gmt":"2010-08-02T15:21:37","slug":"piso-de-policiais-e-acordo-de-itaipu-podem-entrar-na-pauta-da-camara-6398","status":"publish","type":"post","link":"http:\/\/box5640.temp.domains\/~clickfoz\/piso-de-policiais-e-acordo-de-itaipu-podem-entrar-na-pauta-da-camara-6398\/","title":{"rendered":"Piso de policiais e acordo de Itaipu podem entrar na pauta da C&acirc;mara"},"content":{"rendered":"<p style=\"text-align: justify\">Al&eacute;m das tr&ecirc;s medidas provis&oacute;rias que trancam a pauta do Plen&aacute;rio, a base aliada ao Executivo vai tentar votar o Projeto de Decreto Legislativo (PDC) 2600\/10, que aumenta o valor pago ao Paraguai pela energia de Itaipu, e o segundo turno da proposta de piso salarial (PECs 300\/08 e 446\/09) para os policiais e bombeiros dos estados. A informa&ccedil;&atilde;o &eacute; do l&iacute;der do governo, deputado C&acirc;ndido Vaccarezza (PT-SP).<\/p>\n<p>Outras prioridades do governo, segundo o parlamentar, s&atilde;o as MPs 487\/10, sobre a capitaliza&ccedil;&atilde;o do BNDES; e 488\/10 e 489\/10, que preparam o Brasil para receber as Olimp&iacute;adas de 2016. Essas mat&eacute;rias j&aacute; est&atilde;o na pauta.<\/p>\n<p>Por&eacute;m, o l&iacute;der do PSDB, deputado Jo&atilde;o Almeida (BA), alerta que n&atilde;o haver&aacute; acordo sobre a revis&atilde;o do Tratado de Itaipu. &ldquo;Essa proposta ainda tem de ser discutida em uma comiss&atilde;o especial. &Eacute; um absurdo levar isso ao Plen&aacute;rio e vamos obstruir&nbsp; a vota&ccedil;&atilde;o do pedido de urg&ecirc;ncia para inclus&atilde;o da mat&eacute;ria na pauta&rdquo;, disse Almeida. Segundo o projeto em an&aacute;lise na C&acirc;mara, o valor pago pelo Brasil ao Paraguai pela energia excedente de Itaipu saltaria de cerca de R$ 222 milh&otilde;es para cerca de R$ 666 milh&otilde;es por ano.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al&eacute;m das tr&ecirc;s medidas provis&oacute;rias que trancam a pauta do Plen&aacute;rio, a base aliada ao Executivo vai tentar votar o Projeto de Decreto Legislativo (PDC) 2600\/10, que aumenta o valor pago ao Paraguai pela energia de Itaipu, e o segundo turno da proposta de piso salarial (PECs 300\/08 e 446\/09) para os policiais e bombeiros [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-13651","post","type-post","status-publish","format-standard","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Piso de policiais e acordo de Itaipu podem entrar na pauta da C&acirc;mara - Clickfoz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/box5640.temp.domains\/~clickfoz\/piso-de-policiais-e-acordo-de-itaipu-podem-entrar-na-pauta-da-camara-6398\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Piso de policiais e acordo de Itaipu podem entrar na pauta da C&acirc;mara - Clickfoz\" \/>\n<meta property=\"og:description\" content=\"Al&eacute;m das tr&ecirc;s medidas provis&oacute;rias que trancam a pauta do Plen&aacute;rio, a base aliada ao Executivo vai tentar votar o Projeto de Decreto Legislativo (PDC) 2600\/10, que aumenta o valor pago ao Paraguai pela energia de Itaipu, e o segundo turno da proposta de piso salarial (PECs 300\/08 e 446\/09) para os policiais e bombeiros [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/box5640.temp.domains\/~clickfoz\/piso-de-policiais-e-acordo-de-itaipu-podem-entrar-na-pauta-da-camara-6398\/\" \/>\n<meta property=\"og:site_name\" content=\"Clickfoz\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/clickfoz\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/garon.piceli\" \/>\n<meta property=\"article:published_time\" content=\"2010-08-02T15:21:37+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2023\/11\/logo-clickfoz.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Garon Piceli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@garonpiceli\" \/>\n<meta name=\"twitter:site\" content=\"@clickfoz\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Garon Piceli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/piso-de-policiais-e-acordo-de-itaipu-podem-entrar-na-pauta-da-camara-6398\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/piso-de-policiais-e-acordo-de-itaipu-podem-entrar-na-pauta-da-camara-6398\/\"},\"author\":{\"name\":\"Garon Piceli\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/person\/1c68351359e4744c29866b9bc7a0bfff\"},\"headline\":\"Piso de policiais e acordo de Itaipu podem entrar na pauta da C&acirc;mara\",\"datePublished\":\"2010-08-02T15:21:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/piso-de-policiais-e-acordo-de-itaipu-podem-entrar-na-pauta-da-camara-6398\/\"},\"wordCount\":262,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\/\/box5640.temp.domains\/~clickfoz\/piso-de-policiais-e-acordo-de-itaipu-podem-entrar-na-pauta-da-camara-6398\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/piso-de-policiais-e-acordo-de-itaipu-podem-entrar-na-pauta-da-camara-6398\/\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/piso-de-policiais-e-acordo-de-itaipu-podem-entrar-na-pauta-da-camara-6398\/\",\"name\":\"Piso de policiais e acordo de Itaipu podem entrar na pauta da C&acirc;mara - Clickfoz\",\"isPartOf\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#website\"},\"datePublished\":\"2010-08-02T15:21:37+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/piso-de-policiais-e-acordo-de-itaipu-podem-entrar-na-pauta-da-camara-6398\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/box5640.temp.domains\/~clickfoz\/piso-de-policiais-e-acordo-de-itaipu-podem-entrar-na-pauta-da-camara-6398\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/box5640.temp.domains\/~clickfoz\/piso-de-policiais-e-acordo-de-itaipu-podem-entrar-na-pauta-da-camara-6398\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/box5640.temp.domains\/~clickfoz\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Piso de policiais e acordo de Itaipu podem entrar na pauta da C&acirc;mara\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#website\",\"url\":\"https:\/\/box5640.temp.domains\/~clickfoz\/\",\"name\":\"Click Foz do Igua\u00e7u\",\"description\":\"O portal de not\u00edcias de Foz do Igua\u00e7u\",\"publisher\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/box5640.temp.domains\/~clickfoz\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#organization\",\"name\":\"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i\",\"url\":\"https:\/\/box5640.temp.domains\/~clickfoz\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png\",\"contentUrl\":\"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png\",\"width\":190,\"height\":65,\"caption\":\"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i\"},\"image\":{\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/clickfoz\",\"https:\/\/x.com\/clickfoz\",\"https:\/\/www.instagram.com\/clickfoz\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/person\/1c68351359e4744c29866b9bc7a0bfff\",\"name\":\"Garon Piceli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4185832e3322de80868dff0f56e6c20788e54c0fab66a0314b34288fcc3a3fad?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4185832e3322de80868dff0f56e6c20788e54c0fab66a0314b34288fcc3a3fad?s=96&d=mm&r=g\",\"caption\":\"Garon Piceli\"},\"sameAs\":[\"https:\/\/www.facebook.com\/garon.piceli\",\"https:\/\/x.com\/garonpiceli\"],\"url\":\"http:\/\/box5640.temp.domains\/~clickfoz\/author\/garon\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Piso de policiais e acordo de Itaipu podem entrar na pauta da C&acirc;mara - Clickfoz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/box5640.temp.domains\/~clickfoz\/piso-de-policiais-e-acordo-de-itaipu-podem-entrar-na-pauta-da-camara-6398\/","og_locale":"pt_BR","og_type":"article","og_title":"Piso de policiais e acordo de Itaipu podem entrar na pauta da C&acirc;mara - Clickfoz","og_description":"Al&eacute;m das tr&ecirc;s medidas provis&oacute;rias que trancam a pauta do Plen&aacute;rio, a base aliada ao Executivo vai tentar votar o Projeto de Decreto Legislativo (PDC) 2600\/10, que aumenta o valor pago ao Paraguai pela energia de Itaipu, e o segundo turno da proposta de piso salarial (PECs 300\/08 e 446\/09) para os policiais e bombeiros [&hellip;]","og_url":"http:\/\/box5640.temp.domains\/~clickfoz\/piso-de-policiais-e-acordo-de-itaipu-podem-entrar-na-pauta-da-camara-6398\/","og_site_name":"Clickfoz","article_publisher":"https:\/\/facebook.com\/clickfoz","article_author":"https:\/\/www.facebook.com\/garon.piceli","article_published_time":"2010-08-02T15:21:37+00:00","og_image":[{"width":1200,"height":675,"url":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2023\/11\/logo-clickfoz.png","type":"image\/png"}],"author":"Garon Piceli","twitter_card":"summary_large_image","twitter_creator":"@garonpiceli","twitter_site":"@clickfoz","twitter_misc":{"Escrito por":"Garon Piceli","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/piso-de-policiais-e-acordo-de-itaipu-podem-entrar-na-pauta-da-camara-6398\/#article","isPartOf":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/piso-de-policiais-e-acordo-de-itaipu-podem-entrar-na-pauta-da-camara-6398\/"},"author":{"name":"Garon Piceli","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/person\/1c68351359e4744c29866b9bc7a0bfff"},"headline":"Piso de policiais e acordo de Itaipu podem entrar na pauta da C&acirc;mara","datePublished":"2010-08-02T15:21:37+00:00","mainEntityOfPage":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/piso-de-policiais-e-acordo-de-itaipu-podem-entrar-na-pauta-da-camara-6398\/"},"wordCount":262,"commentCount":0,"publisher":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization"},"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/box5640.temp.domains\/~clickfoz\/piso-de-policiais-e-acordo-de-itaipu-podem-entrar-na-pauta-da-camara-6398\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/piso-de-policiais-e-acordo-de-itaipu-podem-entrar-na-pauta-da-camara-6398\/","url":"http:\/\/box5640.temp.domains\/~clickfoz\/piso-de-policiais-e-acordo-de-itaipu-podem-entrar-na-pauta-da-camara-6398\/","name":"Piso de policiais e acordo de Itaipu podem entrar na pauta da C&acirc;mara - Clickfoz","isPartOf":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#website"},"datePublished":"2010-08-02T15:21:37+00:00","breadcrumb":{"@id":"http:\/\/box5640.temp.domains\/~clickfoz\/piso-de-policiais-e-acordo-de-itaipu-podem-entrar-na-pauta-da-camara-6398\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/box5640.temp.domains\/~clickfoz\/piso-de-policiais-e-acordo-de-itaipu-podem-entrar-na-pauta-da-camara-6398\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/box5640.temp.domains\/~clickfoz\/piso-de-policiais-e-acordo-de-itaipu-podem-entrar-na-pauta-da-camara-6398\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/box5640.temp.domains\/~clickfoz\/"},{"@type":"ListItem","position":2,"name":"Piso de policiais e acordo de Itaipu podem entrar na pauta da C&acirc;mara"}]},{"@type":"WebSite","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#website","url":"https:\/\/box5640.temp.domains\/~clickfoz\/","name":"Click Foz do Igua\u00e7u","description":"O portal de not\u00edcias de Foz do Igua\u00e7u","publisher":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/box5640.temp.domains\/~clickfoz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#organization","name":"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i","url":"https:\/\/box5640.temp.domains\/~clickfoz\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/","url":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png","contentUrl":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-content\/uploads\/2019\/04\/clickfoz-mini-logo-green-mouse-190x65.png","width":190,"height":65,"caption":"Clickfoz - Portal de Not\u00edcias de Foz do Igua\u00e7i"},"image":{"@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/clickfoz","https:\/\/x.com\/clickfoz","https:\/\/www.instagram.com\/clickfoz"]},{"@type":"Person","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/person\/1c68351359e4744c29866b9bc7a0bfff","name":"Garon Piceli","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/box5640.temp.domains\/~clickfoz\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/4185832e3322de80868dff0f56e6c20788e54c0fab66a0314b34288fcc3a3fad?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4185832e3322de80868dff0f56e6c20788e54c0fab66a0314b34288fcc3a3fad?s=96&d=mm&r=g","caption":"Garon Piceli"},"sameAs":["https:\/\/www.facebook.com\/garon.piceli","https:\/\/x.com\/garonpiceli"],"url":"http:\/\/box5640.temp.domains\/~clickfoz\/author\/garon\/"}]}},"_links":{"self":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts\/13651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/comments?post=13651"}],"version-history":[{"count":0,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/posts\/13651\/revisions"}],"wp:attachment":[{"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/media?parent=13651"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/categories?post=13651"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/box5640.temp.domains\/~clickfoz\/wp-json\/wp\/v2\/tags?post=13651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}